{"id":18290,"date":"2025-10-20T21:00:20","date_gmt":"2025-10-20T18:00:20","guid":{"rendered":"https:\/\/almaschool.org\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/"},"modified":"2026-06-24T10:41:28","modified_gmt":"2026-06-24T07:41:28","slug":"desastres-naturais-alteracoes-climaticas-ou-o-juizo-final","status":"publish","type":"page","link":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/","title":{"rendered":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18290\" class=\"elementor elementor-18290 elementor-17808\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9c341 e-con-full e-flex e-con e-parent\" data-id=\"4b9c341\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d7bac2 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"3d7bac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desastres Naturais: <br \/>Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-066298f e-flex e-con-boxed e-con e-parent\" data-id=\"066298f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5293f5c e-con-full e-flex e-con e-child\" data-id=\"5293f5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae18e09 elementor-widget elementor-widget-heading\" data-id=\"ae18e09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assista a Palestra<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95642df elementor-widget elementor-widget-text-editor\" data-id=\"95642df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens.<br\/>&nbsp;Clique em configura\u00e7\u00f5es para ativar as legendas no seu&nbsp;idioma preferido.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-637825c elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"637825c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div style=\"position:relative;padding-top:56.25%;\"><iframe src=\"https:\/\/iframe.mediadelivery.net\/embed\/141115\/b0a66287-86d2-4c02-b466-a0202fc6520a?autoplay=false&loop=false&muted=false&preload=false&responsive=true\" loading=\"lazy\" style=\"border:0;position:absolute;top:0;height:100%;width:100%;\" allow=\"accelerometer;gyroscope;autoplay;encrypted-media;picture-in-picture;\" allowfullscreen=\"true\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e55aa25 elementor-widget elementor-widget-heading\" data-id=\"e55aa25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ou\u00e7a o artigo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-671e81d elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"671e81d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/open.spotify.com\/embed\/episode\/3kKgaqddPLQzNzkjhIPjr4?utm_source=generator\" style=\"      width: min(100%, 600px);     height: 152px;     border: none;     border-radius: 8px;     display: block;     margin: 0 auto;    \" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\">\r\n<\/iframe>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6248384 e-flex e-con-boxed e-con e-parent\" data-id=\"6248384\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2066115 elementor-widget elementor-widget-heading\" data-id=\"2066115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leia o artigo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9d24ff elementor-widget elementor-widget-n-accordion\" data-id=\"b9d24ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1940\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1940\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Introdu\u00e7\u00e3o <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1940\" class=\"elementor-element elementor-element-a29fbe7 e-con-full e-flex e-con e-child\" data-id=\"a29fbe7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eca5e3e elementor-widget elementor-widget-text-editor\" data-id=\"eca5e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da Cria\u00e7\u00e3o at\u00e9 os dias atuais, conectando os segredos dos tempos antigos com a nova era.<\/p><p>O que existe de comum entre a Grande Pir\u00e2mide de Giz\u00e9. Stonehenge, as Linhas de Nazca e os agroglifos que apareceram recentemente?<\/p><p>Qual \u00e9 a conex\u00e3o entre os &#8220;deuses&#8221; das v\u00e1rias mitologias antigas, a f\u00edsica qu\u00e2ntica e especialmente com a energia livre sobre a qual Nikola Tesla falou?<\/p><p>Qual \u00e9 a natureza daquele Grande Cometa de que todas as profecias falam, referindo-se ao Ju\u00edzo Final do Fim dos Tempos?<\/p><p>E como tudo isso est\u00e1 conectado aos desastres naturais que agora est\u00e3o ocorrendo em todo o mundo?<\/p><p>A conex\u00e3o superior entre todos esses assuntos e muito mais ser\u00e1 revelada e explicada ao longo dos sete cap\u00edtulos seguintes.<\/p><p>O conhecimento que est\u00e1 prestes a ser revelado aqui \u00e9 extenso e abrangente, e muito provavelmente o racioc\u00ednio intelectual r\u00edgido n\u00e3o ser\u00e1 capaz de compreender completamente tudo numa primeira leitura ou audi\u00e7\u00e3o. Mas se o seu esp\u00edrito estiver alerta, ele perceber\u00e1 a <strong>vibra\u00e7\u00e3o<\/strong> e receber\u00e1 for\u00e7a, e isso \u00e9 mais importante!  <\/p><p>Por essa raz\u00e3o, ap\u00f3s cada cap\u00edtulo, recomendamos que voc\u00ea fa\u00e7a uma breve pausa, feche os olhos, descanse e talvez ou\u00e7a alguma m\u00fasica harmoniosa.<\/p><p>Cada vez que voc\u00ea ler ou ouvir esta palestra novamente, voc\u00ea obter\u00e1 gradualmente reconhecimentos adicionais.<\/p><p>Reconhecimentos que trar\u00e3o aos buscadores s\u00e9rios entre voc\u00eas um passo mais pr\u00f3ximo de compreender a signific\u00e2ncia destes tempos criticamente decisivos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1941\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1941\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cap\u00edtulo Um: A Par\u00e1bola dos H\u00f3spedes Rudes <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1941\" class=\"elementor-element elementor-element-3f07dae e-con-full e-flex e-con e-child\" data-id=\"3f07dae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a29fa0e elementor-widget elementor-widget-text-editor\" data-id=\"a29fa0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>A Par\u00e1bola dos H\u00f3spedes Rudes<\/strong><\/p><p>Era uma vez um rei amoroso e generoso que ordenou a seus servos fi\u00e9is que preparassem diligentemente jardins magn\u00edficos, maravilhosos em sua beleza e abundantes em sua fartura.<\/p><p>Tudo isso para que os jardins pudessem servir como um local de habita\u00e7\u00e3o<strong> tempor\u00e1ria<\/strong> para h\u00f3spedes que precisavam permanecer nos jardins para seu pr\u00f3prio desenvolvimento, e que, em troca, contribuiriam com seus talentos \u00fanicos para a prosperidade dos jardins, enquanto se adaptariam harmoniosamente \u00e0 ordem natural que existia nos jardins.<\/p><p>Os servos que sempre se alegraram em trabalhar a servi\u00e7o do rei realizaram mais esse trabalho fielmente e aguardavam ansiosamente a oportunidade de colaborar com os h\u00f3spedes que trariam seus pr\u00f3prios talentos especiais.<\/p><p>Contudo, qu\u00e3o grande foi seu espanto quando esses h\u00f3spedes chegaram e n\u00e3o apenas esqueceram de que eram h\u00f3spedes, mas at\u00e9 mesmo come\u00e7aram a se comportar rudemente e fazer exig\u00eancias!<\/p><p>Os novos h\u00f3spedes alegaram que os jardins pertenciam a eles! Que os jardins se destinavam a satisfazer apenas aos seus desejos e, portanto, os h\u00f3spedes n\u00e3o tinham interesse em nutri-los para o benef\u00edcio das gera\u00e7\u00f5es futuras. Eles come\u00e7aram a alterar os jardins de acordo com suas pr\u00f3prias ideias e, assim, a explor\u00e1-los!  <\/p><p>Mas a pior parte foi que esses h\u00f3spedes, no seu desejo de mudar tudo, tornaram-se t\u00e3o arrogantes e cegos que alegaram que os servos fi\u00e9is, e at\u00e9 mesmo o pr\u00f3prio rei, nem existiam de fato!<\/p><p>Os servos ficaram muito tristes com tudo isso. Eles n\u00e3o entendiam por que os h\u00f3spedes se comportavam de forma t\u00e3o rude, nem o que exatamente eram os talentos especiais que esses h\u00f3spedes deveriam expressar. Pois al\u00e9m do ego\u00edsmo e de trazer destrui\u00e7\u00e3o sobre aquilo que os servos haviam, com seu trabalho, desenvolvido e nutrido para eles, os h\u00f3spedes que, enquanto isso, se declararam propriet\u00e1rios, n\u00e3o demonstraram nenhuma qualidade positiva.  <\/p><p>Assim, os servos fi\u00e9is que inicialmente haviam revelado seus rostos sorridentes, esperando fazer amizade com os h\u00f3spedes, come\u00e7aram a se esconder e a fugir deles! Contudo, por ordem do rei que n\u00e3o era apenas amoroso e generoso, mas tamb\u00e9m paciente e cheio de gra\u00e7a, os servos, mesmo assim, continuaram secretamente seu trabalho. Isso ocorreu por serem leais ao rei, que desejava dar repetidamente aos h\u00f3spedes a oportunidade de se arrependerem e de mudarem seu mau comportamento, e de cumprirem o prop\u00f3sito para o qual foram enviados aos jardins maravilhosos e luminosos.  <\/p><p>Portanto, para despertar os h\u00f3spedes rudes, o rei come\u00e7ou a enviar-lhes mensageiros, mas os h\u00f3spedes os espancaram e os expulsaram!<\/p><p>O rei chegou a enviar-lhes seus dois filhos amados, mas os h\u00f3spedes ingratos os atormentaram e, por fim, causaram suas mortes!<\/p><p>De tempos em tempos, os servos fi\u00e9is tamb\u00e9m eram obrigados a punir os h\u00f3spedes, pois talvez o sofrimento os ajudasse a retornar ao caminho correto, mas tudo isso foi em v\u00e3o. N\u00e3o os fez abandonar seu comportamento ignorante e arrogante, e nem a devasta\u00e7\u00e3o e destrui\u00e7\u00e3o que causavam. <\/p><p>Mas o rei prometeu a seus fi\u00e9is auxiliares que chegaria um dia em que esse longo per\u00edodo de gra\u00e7a finalmente terminaria. Ent\u00e3o viria o tempo do acerto final de contas, quando os servos teriam permiss\u00e3o para executar a Lei de Causa e Efeito: destruir todas as obras feias dos h\u00f3spedes rudes e remov\u00ea-los dos jardins luminosos e maravilhosos! <\/p><p>Os h\u00f3spedes, que n\u00e3o entendiam que n\u00e3o eram os propriet\u00e1rios, seriam ent\u00e3o for\u00e7ados a retornar ao seu lar. Partiriam lamentando, envergonhados e de m\u00e3os vazias, tendo desperdi\u00e7ado o tempo da gra\u00e7a que lhes foi concedido para desenvolvimento nos jardins luminosos por meio de esfor\u00e7os errados e pensando que sabiam melhor. <\/p><p>Em contraste, os poucos que foram h\u00f3spedes humildes e gratos e que trabalharam em coopera\u00e7\u00e3o com os servos, em honra do rei, retornariam aben\u00e7oados e alegres ao seu lar eterno.<\/p><p>***<\/p><p><strong>A moral desta par\u00e1bola ser\u00e1 revelada ao longo desta palestra sob v\u00e1rias perspectivas, permitindo uma compreens\u00e3o mais profunda e sua internaliza\u00e7\u00e3o.<\/strong><\/p><p>Mas primeiro, precisamos entender <strong>seu aspecto mais simples:<\/strong><\/p><p>Pela Vontade do Rei dos Reis, surgiu toda a Cria\u00e7\u00e3o.<\/p><p>A origem de todos os seres humanos \u00e9 <strong>a esfera espiritual,<\/strong> que tamb\u00e9m \u00e9 denominada <strong>Para\u00edso<\/strong>, da qual todos emergimos como <strong>g\u00e9rmen espiritual<\/strong>, portando com um impulso inato para o desenvolvimento. Desenvolvimento significa a transforma\u00e7\u00e3o de um estado inconsciente para um estado consciente, e para alcan\u00e7ar esse prop\u00f3sito o g\u00e9rmen espiritual deve experimentar o mundo da mat\u00e9ria grosseira, tamb\u00e9m conhecido como &#8220;natureza&#8221;. (O processo \u00e9 semelhante ao da semente que s\u00f3 pode se desenvolver depois de ter sido plantada na terra, ter passado pelo processo de desenvolvimento que exige \u00e1gua, luz solar e condi\u00e7\u00f5es naturais desafiadoras como ventos fortes ou seca que aceleram o crescimento e fortalecimento.) <\/p><p><strong>A natureza perfeita em seu plano, de acordo com as Leis da Cria\u00e7\u00e3o, \u00e9 o mais belo presente de Deus, que nos possibilita o desenvolvimento!<\/strong><\/p><p>Contudo, assim como ningu\u00e9m espera que o p\u00e3o, as roupas ou as casas apare\u00e7am do nada sem a colabora\u00e7\u00e3o de m\u00e3os humanas para faz\u00ea-los, a pr\u00f3pria <strong>natureza<\/strong> n\u00e3o foi criada por Deus atrav\u00e9s de um ato de magia, como podemos ter aprendido no jardim de inf\u00e2ncia. Ao contr\u00e1rio, ela foi formada por seres que se desenvolveram a partir <strong>da irradia\u00e7\u00e3o de Deus: os seres elementais.<\/strong> <\/p><p><strong>Esses seres elementais d\u00e3o vitalidade \u00e0 mat\u00e9ria, e sem eles ela permaneceria sem vida. Morta! <\/strong> (A conex\u00e3o entre essa vitalidade, a f\u00edsica qu\u00e2ntica e a energia livre, citada por Nikola Tesla, ser\u00e1 discutida no quinto cap\u00edtulo.)<\/p><p>Nas <strong>v\u00e1rias linhas mitol\u00f3gicas<\/strong> \u2014e abordaremos esse assunto tamb\u00e9m no terceiro cap\u00edtulo\u2014 os seres elementais foram <strong>erroneamente <\/strong>denominados <strong>deuses<\/strong>, como <strong>Poseidon, o deus do mar<\/strong> na mitologia grega, ou <strong>Netuno<\/strong> na mitologia romana. No Livro dos Salmos, onde est\u00e1 escrito: &#8220;<strong>Atribu\u00ed ao Senhor, \u00f3h filhos de deuses, atribu\u00ed ao Senhor gl\u00f3ria e for\u00e7a<\/strong>&#8221; (Salmo 29:1), <strong>estes seres, referidos como filhos de deuses, foram erroneamente identificados como anjos. <\/strong>(Trata-se de um erro, pois anjos n\u00e3o descem diretamente da Esfera Divina para a Terra.) <\/p><p>Os seres elementais s\u00e3o, de fato, aqueles que trabalharam para criar os poderosos e maravilhosos reinos da natureza, n\u00e3o apenas os mares, montanhas e vegeta\u00e7\u00e3o, mas tamb\u00e9m todos os <strong>planetas, sistemas solares, gal\u00e1xias e os sete universos,<\/strong> ao longo de bilh\u00f5es de anos, e continuam a cuidar diligentemente de sua preserva\u00e7\u00e3o e exist\u00eancia at\u00e9 os dias atuais.<\/p><p>Esses seres aguardaram por bilh\u00f5es de anos pela chegada dos primeiros esp\u00edritos humanos no mundo de mat\u00e9ria grosseira, h\u00e1 aproximadamente tr\u00eas milh\u00f5es de anos, e para trabalharem com ele em coopera\u00e7\u00e3o. Os esp\u00edritos humanos que deveriam ter sido <strong>a coroa da Cria\u00e7\u00e3o!<\/strong><\/p><p>Isso porque os seres humanos haviam sido dotados de uma for\u00e7a especial: <strong>a for\u00e7a espiritual! O poder criativo! <\/strong> <strong>A for\u00e7a do livre-arb\u00edtrio <\/strong>que poderia ter auxiliado os seres elementais, que n\u00e3o possuem livre-arb\u00edtrio, mil vezes mais, na constru\u00e7\u00e3o e no refinamento de todos os reinos da natureza!<\/p><p>De fato, <strong>o esp\u00edrito humano, com essa capacidade inata, deveria ter sido um administrador benevolente e ter transformado o planeta Terra num reflexo material do Para\u00edso!<\/strong><\/p><p>Contudo, desde que os seres humanos se renderam a L\u00facifer, como foi explicado detalhadamente na palestra <strong>&#8220;A Agenda de L\u00facifer&#8221;<\/strong>, eles se desconectaram de seu esp\u00edrito e se tornaram escravos do intelecto, que os limitou ao tempo e ao espa\u00e7o.<\/p><p>Assim, em vez de considerar suas vidas na Terra meramente <strong>como uma estada tempor\u00e1ria<\/strong> para o desenvolvimento do esp\u00edrito, para que pudessem retornar \u00e0 sua verdadeira p\u00e1tria, que \u00e9 o Para\u00edso, eles come\u00e7aram a se ver como os propriet\u00e1rios do planeta Terra!<\/p><p>Pior ainda, sua motiva\u00e7\u00e3o n\u00e3o era proteger o planeta, mas sim explor\u00e1-lo em prol de seus desejos ego\u00edstas, o que inevitavelmente levou a guerras intermin\u00e1veis, destrui\u00e7\u00e3o e devasta\u00e7\u00e3o.<\/p><p>Em outras palavras: em vez de manter o anseio pela Luz e pelo desenvolvimento e ascens\u00e3o do esp\u00edrito, para voltar ao Para\u00edso como um esp\u00edrito plenamente consciente, esse conceito &#8220;anseio&#8221; foi distorcido em in\u00fameros desejos terrenos (propriedade de casa, carros, f\u00e9rias, refei\u00e7\u00f5es luxuosas, preocupa\u00e7\u00f5es obsessivas com a sa\u00fade, manuten\u00e7\u00e3o r\u00edgida de um determinado estilo de vida etc.).<\/p><p>Podemos ser comparados a algu\u00e9m que recebeu as chaves de um vasto reino, mas que escolhe brincar com brinquedos de crian\u00e7a.<\/p><p>Portanto, quanto mais n\u00f3s \u2014Sim! N\u00f3s somos aqueles h\u00f3spedes rudes!\u2014 nos distanciamos da influ\u00eancia da Luz, tamb\u00e9m mais nos afastamos da influ\u00eancia dos nossos bons amigos e protetores: os seres elementais!<\/p><p>Violamos vergonhosamente a confian\u00e7a que esses seres depositaram em n\u00f3s, a ponto de hoje nem mesmo sabermos sobre sua exist\u00eancia nem sua extensa atividade!<\/p><p>Mas n\u00f3s n\u00e3o apenas tra\u00edmos e rejeitamos esses servos fi\u00e9is, mas tamb\u00e9m a Deus!<\/p><p>Em nossa grande aud\u00e1cia, ousamos dizer que o mundo se criou por si mesmo e nos pertence inteiramente, e sendo assim, podemos fazer com ele o que quisermos!<\/p><p>Mas agora chegou o tempo em que <strong>todos n\u00f3s devemos <\/strong>internalizar\/absorver completamente esse conhecimento: N\u00f3s n\u00e3o estamos nesta Terra por direito pr\u00f3prio, mas por Amor e a Gra\u00e7a de Deus, que repetidamente nos concedeu oportunidades para reconhecer nossos erros e nos afastar de nossos maus caminhos.<\/p><p>Mensageiros, que s\u00e3o de fato os profetas, foram enviados a n\u00f3s, mas n\u00f3s os expulsamos ap\u00f3s atorment\u00e1-los e nos recusarmos a ouvir suas repreens\u00f5es, rejeitadas pelo nosso ego. Da pr\u00f3pria Divindade, os dois Filhos de Deus tamb\u00e9m foram enviados a n\u00f3s: <strong>o Filho de Deus e o Filho do Homem <\/strong>\u2014 sobre os quais voc\u00ea pode ouvir mais detalhes na palestra &#8220;<strong>Jesus Cristo: A Verdadeira Hist\u00f3ria Segundo as Leis da Cria\u00e7\u00e3o&#8221;<\/strong>\u2014 <strong>cujas mortes fomos n\u00f3s os causadores!<\/strong> <\/p><p>Contudo, o Amor Divino e a Justi\u00e7a Divina n\u00e3o podem ser separados, pois ambos s\u00e3o direcionados exclusivamente para o bem supremo do ser humano, que \u00e9 o desenvolvimento do esp\u00edrito.<\/p><p><strong>Portanto, como nos desviamos gravemente do caminho correto, a Lei de Causa e Efeito trouxe o Julgamento sobre n\u00f3s, ou seja, sofrimento, para que despert\u00e1ssemos por meio desse sofrimento e corrig\u00edssemos voluntariamente nossos caminhos!<\/strong><\/p><p>Muitas vezes, como explicado detalhadamente na palestra <strong>&#8220;Profetas versus Imp\u00e9rios&#8221;<\/strong>, esse julgamento recaiu sobre n\u00f3s por meio de governantes cru\u00e9is que, de fato, foram meramente instrumentos de execu\u00e7\u00e3o da Lei de Causa e Efeito, de acordo com o princ\u00edpio de que <strong>at\u00e9 mesmo os planos das Trevas executar\u00e3o, em \u00faltima inst\u00e2ncia, o Plano da Luz.<\/strong><\/p><p>Em outras ocasi\u00f5es, isto ocorreu por meio de outros mensageiros do mecanismo das Leis da Cria\u00e7\u00e3o de Deus: os seres elementais, que sempre foram aqueles que implementaram o <strong>Julgamento atrav\u00e9s das for\u00e7as da natureza,<\/strong> sobre os quais \u00e9 dito no Livro dos Salmos (104:4): <strong>&#8220;Ele faz dos ventos Seus anjos, e do fogo flamejante Seus ministros&#8221;.<\/strong><\/p><p>Por exemplo, <strong>os seres elementais<\/strong> <strong>do fogo<\/strong> trouxeram o Julgamento sobre <strong>Sodoma e Gomorra, e<\/strong> <strong>os respons\u00e1veis pelas \u00e1guas afundaram Atl\u00e2ntida.<\/strong><\/p><p>Contudo, desde o in\u00edcio da exist\u00eancia do mundo material, foi previsto que este estava destinado \u00e0 desintegra\u00e7\u00e3o, uma vez que, de acordo com as Leis da Cria\u00e7\u00e3o, <strong>toda mat\u00e9ria <\/strong>passa pelo processo natural de in\u00edcio, desenvolvimento e desintegra\u00e7\u00e3o.<\/p><p>(Por exemplo: Quantos anos uma pessoa pode viver? Setenta, oitenta ou noventa anos, mas finalmente deve morrer e seu corpo se desintegrar\u00e1. O mesmo princ\u00edpio se aplica ao nosso planeta. Embora aqui estejamos falando de um processo que dura bilh\u00f5es de anos, ele tamb\u00e9m eventualmente chegar\u00e1 ao seu fim. De fato, como est\u00e1, nosso planeta tem apenas cerca de mil anos restantes.)<\/p><p>Estamos no momento que os profetas chamaram de <strong>Dias do Julgamento Final<\/strong>, imediatamente antes <strong>do Fim dos Tempos<\/strong>. Este per\u00edodo \u00e9 cr\u00edtico para o esp\u00edrito humano, pois se ele n\u00e3o utilizou suas milhares de encarna\u00e7\u00f5es para se desenvolver, isto \u00e9, para se transformar do estado de inconsci\u00eancia para consci\u00eancia espiritual, n\u00e3o ser\u00e1 capaz de cumprir seu prop\u00f3sito e retornar ao lar, o Para\u00edso, como esp\u00edrito consciente. <\/p><p>Este \u00e9 o destino mais terr\u00edvel para o esp\u00edrito, e \u00e9 equivalente <strong>a ser apagado do Livro da Vida<\/strong>: &#8220;o Livro&#8221; em que est\u00e1 \u201cregistrado\u201d tudo o que cada esp\u00edrito humano vivenciou ao longo de todas as suas encarna\u00e7\u00f5es na Terra.<\/p><p>Este per\u00edodo, que todos n\u00f3s percebemos agora, \u00e9 caracterizado pela <strong>press\u00e3o do Poder da Luz<\/strong>, que leva ao fechamento acelerado de todos os ciclos c\u00e1rmicos para todos os habitantes da Terra!<\/p><p>Agora ser\u00e3o <strong>os seres elementais<\/strong>, que sozinhos podem verdadeiramente portar o t\u00edtulo <strong>&#8220;Guerreiros da Luz&#8221;<\/strong>, que trar\u00e3o o Julgamento sobre a humanidade por meio das for\u00e7as da natureza. Um Julgamento que destruir\u00e1 as inven\u00e7\u00f5es err\u00f4neas da humanidade arrogante, expulsar\u00e1 todos os h\u00f3spedes rudes e purificar\u00e1 a Terra de tudo que \u00e9 hostil \u00e0 Luz. <\/p><p>Assim, apenas uma porcentagem muito pequena da humanidade permanecer\u00e1, que estar\u00e1 pronta e disposta a aprender a se tornar um novo ser humano: <strong>um ser humano com consci\u00eancia espiritual, de acordo com a Vontade de Deus.<\/strong><\/p><p><strong>O Reino de Mil Anos, um per\u00edodo que j\u00e1 come\u00e7ou, ser\u00e1 uma escola para a humanidade em que apenas os poucos que compreendem tudo isso sobreviver\u00e3o espiritualmente!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1942\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1942\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cap\u00edtulo Dois: Os Espiritualmente Cegos e Surdos <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1942\" class=\"elementor-element elementor-element-402ee9b e-con-full e-flex e-con e-child\" data-id=\"402ee9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f68ecc2 elementor-widget elementor-widget-text-editor\" data-id=\"f68ecc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hoje, a <strong>vasta maioria<\/strong> da humanidade pode ser dividida em dois grupos:<\/p><p>Um grupo consiste em pessoas que se comportam <strong>como avestruzes<\/strong> e continuam a enterrar suas cabe\u00e7as na areia, apesar de tudo o que, de fato, est\u00e1 desmoronando ao seu redor (&#8220;pandemias&#8221;, guerras, crises econ\u00f4micas, aumento da criminalidade e, \u00e9 claro, desastres naturais).<\/p><p>E outro grupo que olha para tudo o que est\u00e1 acontecendo e <strong>procura algu\u00e9m para culpar<\/strong>: primeiro e principalmente, as elites globalistas, para quem todos os governos do mundo trabalham a fim de implementar uma &#8220;nova ordem mundial.&#8221;<\/p><p>Ambos os grupos, ou <strong>zombam <\/strong>daqueles que falam sobre o Ju\u00edzo Final (porque n\u00e3o acreditam em Deus), ou se <strong>ressentem<\/strong> daqueles que, em sua opini\u00e3o, &#8220;<strong>se envolvem em alarmismo<\/strong>&#8221; (e, portanto, tendem a buscar falsos mestres que os &#8220;acalmar\u00e3o&#8221; com promessas v\u00e3s&#8230;)<\/p><p><strong>Mas ambos os grupos s\u00e3o espiritualmente cegos e surdos<\/strong>. Al\u00e9m disso, eles t\u00eam um denominador comum: <\/p><p><strong>A teimosia de seu ego que busca remover de si toda culpa e responsabilidade pessoal, e seu desejo de continuar suas vidas terrenas de forma agrad\u00e1vel e sem qualquer perturba\u00e7\u00e3o, mesmo que seus comportamentos sejam hostis \u00e0 Vontade da Luz.<\/strong><\/p><p><strong>Foi sobre tais pessoas que o profeta Jeremias disse:<\/strong><\/p><p><strong>&#8220;Ouvi agora isto, \u00f3 povo insensato e sem entendimento, que tendes olhos e n\u00e3o vedes, que tendes ouvidos e n\u00e3o ouvis&#8221; (Jeremias 5:21).<\/strong><\/p><p><strong>Ouvi agora isto! Prestai aten\u00e7\u00e3o a isto! <\/strong><\/p><p>Nossas opini\u00f5es e nossas cren\u00e7as simplesmente <strong>n\u00e3o s\u00e3o relevantes<\/strong> diante do Poder e da For\u00e7a de Deus! Nem diante do Julgamento atrav\u00e9s das for\u00e7as da natureza, que agora nos atinge, essa humanidade pecaminosa, como um bumerangue! <\/p><p>E o que ser\u00e1 de fato aterrorizante n\u00e3o ser\u00e3o as palavras dos profetas que nos advertiram contra continuarmos a contraria as Leis da Cria\u00e7\u00e3o, mas sim <strong>o cumprimento efetivo de suas profecias!<\/strong> <\/p><p>Portanto, quando Jesus disse: <strong>&#8220;Deixai que os mortos sepultem os seus mortos!&#8221;<\/strong> (Mateus 8:22), ele estava se referindo a todos aqueles que se recusam veementemente a desenvolver a vis\u00e3o e a audi\u00e7\u00e3o espirituais, porque quem \u00e9 espiritualmente cego e surdo \u00e9 considerado espiritualmente morto!<\/p><p>Assim, aqueles que s\u00e3o pobres em esp\u00edrito e consequentemente arrogantes, pois a pobreza espiritual gera arrog\u00e2ncia, n\u00e3o podem ser ajudados.<\/p><p>Esta \u00e9 a raz\u00e3o pela qual esta palestra se destina apenas \u00e0queles que est\u00e3o prontos para abrir seus olhos e ouvidos, e assim salvar o seu pr\u00f3prio esp\u00edrito<\/p><p>***<\/p><p><strong>O Ju\u00edzo Final,<\/strong> previsto por tantas profecias, j\u00e1 est\u00e1 aqui e n\u00e3o precisa mais ser profetizado nem lido, mas simplesmente requer que abramos nossos olhos para v\u00ea-lo se desdobrando sobre n\u00f3s:<\/p><p><strong>Se olharmos apenas para 2025, ele j\u00e1 est\u00e1 caracterizado como um ano de eventos naturais sem precedentes:<\/strong><\/p><p>Erup\u00e7\u00f5es vulc\u00e2nicas, inunda\u00e7\u00f5es mortais, terremotos, maremotos, tempestades severas, inc\u00eandios massivos, poderosas tempestades solares, enfraquecimento imenso do campo magn\u00e9tico que circunda a Terra, e muito mais.<\/p><p>E n\u00e3o s\u00e3o os governantes da Matrix, em suas tentativas pat\u00e9ticas de engenharia clim\u00e1tica, que est\u00e3o criando o maior evento na hist\u00f3ria!<\/p><p>Portanto, quem acredita que todos os nossos problemas hoje derivam da engenharia clim\u00e1tica est\u00e1 na verdade <strong>coroando as elites globalistas como Senhores do mundo!<\/strong><\/p><p>Voc\u00eas realmente acreditam que eles s\u00e3o mais poderosos que Deus?<\/p><p>Voc\u00eas pensam que porque eles t\u00eam tanto dinheiro e poder terreno, eles podem realmente controlar a Cria\u00e7\u00e3o de Deus?<\/p><p>Voc\u00eas conseguem perceber como isso \u00e9 rid\u00edculo?<\/p><p>***<\/p><p>O que \u00e9 interessante \u00e9 que, diferentemente de todas as pessoas ignorantes que zombam do Ju\u00edzo Final, as elites sabem exatamente o que est\u00e1 prestes a se desenrolar e, portanto, <strong>est\u00e3o se preparando adequadamente!<\/strong><\/p><p>Enquanto isso, elas trabalham para distrair a aten\u00e7\u00e3o p\u00fablica deste mesmo <strong>acontecimento<\/strong> de in\u00fameras maneiras, para prevenir histeria p\u00fablica em massa!<\/p><p>Um exemplo perfeito disso \u00e9 apresentado no filme cujo t\u00edtulo revela exatamente a estrat\u00e9gia que eles est\u00e3o usando:<\/p><p><strong>&#8220;N\u00e3o Olhem Para Cima!&#8221;<\/strong><\/p><p>***<\/p><p>No <strong><em>Livro do Apocalipse<\/em><\/strong>, que descreve em imagens os eventos dos Dias do Ju\u00edzo Final, essa prepara\u00e7\u00e3o das elites \u00e9 descrita como parte da representa\u00e7\u00e3o da abertura <strong>do sexto selo.<\/strong><\/p><p>Mas antes de compartilharmos a cita\u00e7\u00e3o relacionada \u00e0 prepara\u00e7\u00e3o das elites, permitam-nos primeiro explicar qual \u00e9 <strong>o significado da abertura dos selos:<\/strong><\/p><p>Nos tempos antigos, o pergaminho de papiro era escrito e enrolado, e selos de cera eram colocados para selar o pergaminho. Cada um desses portava o selo \u00fanico do escritor, que garantia autenticidade e prevenia a falsifica\u00e7\u00e3o. <\/p><p>O documento seria aberto na presen\u00e7a de testemunhas, e <strong>apenas uma pessoa autorizada a faz\u00ea-lo <\/strong>poderia abri-lo.<\/p><p>O significado simb\u00f3lico apresentado no <em>Livro do Apocalipse<\/em> \u00e9 que o propriet\u00e1rio do pergaminho, que \u00e9 Deus, declara a revoga\u00e7\u00e3o do dom\u00ednio humano sobre a Terra, uma vez que a humanidade entregou seu livre-arb\u00edtrio a Satan\u00e1s desde o tempo do pecado de Ad\u00e3o e Eva.<\/p><p>O selo \u00e9, na verdade, como um ferrolho que impede o acesso ao conhecimento e ao poder contidos dentro dele.<\/p><p>Mas o que acontece quando o selo \u00e9 aberto?<\/p><p>Cada selo que \u00e9 aberto libera ou provoca um evento ou um poder, em outras palavras, causa o <strong>desencadeamento<\/strong> de algo que estava &#8220;guardado&#8221; ou &#8220;selado&#8221; dentro dele.<\/p><p><strong>O resultado \u00e9 que, com cada abertura de selo, um novo Julgamento Divino \u00e9 liberado sobre a Terra, como parte do processo de recolocar a Terra sob o Poder de Deus.<\/strong><\/p><p><strong>Entretanto, aquele que est\u00e1 autorizado e \u00e9 capaz de abrir os selos do pergaminho e causar esse desencadeamento n\u00e3o \u00e9 Jesus, o Filho de Deus, que supostamente deve retornar numa Segunda Vinda, como a tradi\u00e7\u00e3o crist\u00e3 erroneamente afirma, mas uma figura inteiramente diferente: o Filho do Homem!<\/strong><\/p><p><strong>Tudo isso acontece diante das testemunhas: os 144.000 Convocados.<\/strong><\/p><p>(Apresentamos detalhes sobre o Filho do Homem, os Convocados e os desencadeamentos simb\u00f3licos que est\u00e3o ocorrendo atualmente, em nosso curso avan\u00e7ado.)<\/p><p>***<\/p><p>Agora, retornemos \u00e0s elites e \u00e0 cita\u00e7\u00e3o do<em> Livro do Apocalipse<\/em> sobre elas:<\/p><p><strong>&#8220;E os reis da Terra, e os grandes, e os ricos, e os tribunos, e os poderosos&#8230; se esconderam nas cavernas e nas rochas das montanhas; e disseram aos montes e aos rochedos: Ca\u00ed sobre n\u00f3s e escondei-nos do rosto daquele que est\u00e1 assentado sobre o trono&#8230;&#8221; (Cap\u00edtulo 6:15-16)<\/strong><\/p><p><strong>E, de fato, h\u00e1 muitos relat\u00f3rios detalhados de que pessoas ricas e influentes est\u00e3o realmente construindo bunkers e abrigos subterr\u00e2neos luxuosos<\/strong> (incluindo piscinas, cinemas, academias e at\u00e9 mesmo pistas de carros!)<\/p><p><strong>Por exemplo, Mark Zuckerberg <\/strong>construiu um complexo subterr\u00e2neo no Hava\u00ed, custando 270 milh\u00f5es de d\u00f3lares!<\/p><p><strong>Bill Gates, Jeff Bezos e Elon Musk<\/strong> supostamente teriam bunkers privados em v\u00e1rias localiza\u00e7\u00f5es ao redor do mundo!<\/p><p>A <strong>Nova Zel\u00e2ndia <\/strong>\u00e9 considerada um &#8220;destino de fuga desejado para as elites americanas&#8221;, al\u00e9m de lugares isolados nos Estados Unidos, como <strong>Dakota do Sul e Montana<\/strong>.<\/p><p>Se voc\u00ea pesquisar minuciosamente, descobrir\u00e1 que muitos pa\u00edses desenvolvidos, como <strong>Finl\u00e2ndia, Jap\u00e3o, Canad\u00e1 e Noruega,<\/strong> j\u00e1 est\u00e3o coordenando edifica\u00e7\u00f5es subterr\u00e2neas e conduzindo escava\u00e7\u00f5es abaixo da superf\u00edcie, embora muitos de seus residentes n\u00e3o estejam cientes disso&#8230;<\/p><p><strong>Entretanto, nenhum esp\u00edrito humano ser\u00e1 capaz de escapar de seu carma! Nem mesmo se escondendo no subsolo! <\/strong><\/p><p><strong>Al\u00e9m disso, devido \u00e0 mentalidade extremamente materialista dessas elites, elas esquecem que, em \u00faltima inst\u00e2ncia, seus corpos tamb\u00e9m ter\u00e3o que se desintegrar <\/strong><strong>de acordo com as Leis da Cria\u00e7\u00e3o,<\/strong><strong>apesar de terem dinheiro suficiente para construir para si mesmas um bunker luxuoso! Ent\u00e3o, quando a alma for liberada do corpo f\u00edsico, elas ser\u00e3o for\u00e7adas a descobrir, <\/strong><strong>inevitavelmente,<\/strong> <strong>qu\u00e3o pobres eles s\u00e3o no Reino de Deus.<\/strong><\/p><p>Quanto tempo durar\u00e1 o Julgamento e sua grande purifica\u00e7\u00e3o que o acompanha? Isso, ningu\u00e9m pode dizer. Pode acontecer em alguns meses ou ao longo de uma gera\u00e7\u00e3o inteira, mas, em \u00faltima inst\u00e2ncia, isso \u00e9 o que foi escrito e isso \u00e9 o que ser\u00e1!  <\/p><p>***<\/p><p>Portanto, j\u00e1 nesta fase da palestra, e antes de nos aprofundarmos, voc\u00ea tem as respostas para perguntas que certamente est\u00e3o surgindo dentro de voc\u00ea:<\/p><ol><li><strong> Qual \u00e9 a principal raz\u00e3o da prolifera\u00e7\u00e3o de desastres naturais em todo o mundo?<\/strong><\/li><\/ol><p>O Julgamento atrav\u00e9s das for\u00e7as da natureza nos Dias do Julgamento Final, que traz o fechamento de todos os ciclos c\u00e1rmicos.<\/p><ol start=\"2\"><li><strong> Por que a grande m\u00eddia quase n\u00e3o reporta sobre eles?<\/strong><\/li><\/ol><p>Porque se as pessoas entendessem tudo o que est\u00e1 prestes a se desenrolar, uma histeria em massa incontrol\u00e1vel irromperia.<\/p><ol start=\"3\"><li><strong> Esses desastres s\u00e3o causados pelo homem: engenharia clim\u00e1tica ou aquecimento global?<\/strong><\/li><\/ol><p>Como mencionado, a causa <strong>prim\u00e1ria<\/strong> da intensifica\u00e7\u00e3o dos grandes eventos naturais \u00e9 o julgamento dos Dias do Julgamento Final.<\/p><p>Contudo, a humanidade certamente &#8220;contribuiu&#8221; para isso, ao garantir que esses eventos n\u00e3o apenas promovam a renova\u00e7\u00e3o da natureza, conforme pretendido no Plano original da Cria\u00e7\u00e3o, mas se tornar\u00e3o cataclismos.<\/p><p><strong>Quebramos nosso pacto com a natureza e os seres elementais muito antes de as elites arrogantemente inventarem tecnologias para controlar a natureza atrav\u00e9s da engenharia clim\u00e1tica.<\/strong><\/p><p>Portanto, agora, os seres elementais n\u00e3o apenas destruir\u00e3o nossas obras feias, que ignoraram as Leis da Natureza, mas tamb\u00e9m nos retornar\u00e3o as consequ\u00eancias destrutivas de tudo que \u00e9 sombrio e impuro que tecemos<strong> em nossos pensamentos, nossas emo\u00e7\u00f5es e em nossas palavras.<\/strong><\/p><p>Portanto, no Ju\u00edzo Final, <strong>todas<\/strong> as obras err\u00f4neas da humanidade ser\u00e3o destru\u00eddas!<\/p><p>Ao mesmo tempo, a natureza ser\u00e1 renovada, como pode ser visto, por exemplo, na forma\u00e7\u00e3o de novas ilhas em Tonga, no Oceano Pac\u00edfico.<\/p><p>Um inc\u00eandio florestal devastador concede um exemplo convincente deste princ\u00edpio. A pr\u00f3pria natureza se recupera rapidamente das chamas, com solos f\u00e9rteis e novas florestas emergindo das cinzas. Mas quando o inferno se espalha por assentamentos humanos, ele elimina meios de subsist\u00eancia e infraestrutura permanentemente. As antigas obras humanas s\u00e3o apagadas, tornando-se coisa do passado, enquanto a natureza se renova.   <\/p><ol start=\"4\"><li><strong> O que \u00e9 o Julgamento atrav\u00e9s das for\u00e7as da natureza de que todas as profecias falam, e quem \u00e9 realmente respons\u00e1vel pela execu\u00e7\u00e3o dele?<\/strong><\/li><\/ol><p>Como mencionado, agora \u00e9 o tempo do fechamento de todos os ciclos c\u00e1rmicos, quando o planeta Terra entra em sua fase de desintegra\u00e7\u00e3o, e o respons\u00e1vel por isso n\u00e3o \u00e9 simplesmente &#8220;uma resposta da natureza&#8221;, mas daqueles que a desenvolveram e a mant\u00eam: <strong>os seres elementais.<\/strong><\/p><ol start=\"5\"><li><strong> Poderia ser que aquilo que nos parece como desastres seja de fato algo completamente diferente?<\/strong><\/li><\/ol><p>&#8220;Desastres naturais&#8221; \u00e9 o nome que o intelecto deu a todos esses eventos, uma vez que s\u00e3o desastrosos para todas as obras dele! Enquanto na realidade, da perspectiva espiritual, eles n\u00e3o s\u00e3o desastres, mas um p<strong>rocesso necess\u00e1rio de purifica\u00e7\u00e3o!<\/strong> <\/p><p>Essa purifica\u00e7\u00e3o \u00e9 como um corpo se livrando de toxinas por meio de febre, v\u00f4mito e suor para superar invasores nocivos e retornar \u00e0 boa sa\u00fade. Al\u00e9m disso, no nosso estado atual, o nosso esp\u00edrito n\u00e3o consegue fazer sua voz ser ouvida, nem se libertar de seus &#8220;dois carcereiros&#8221;, a consci\u00eancia intelectual e a consci\u00eancia emocional, sem <strong>sofrimento terreno e f\u00edsico extremo.<\/strong> <\/p><p><strong> <\/strong><\/p><p><strong>N\u00f3s humanos temos, por milhares de anos, abusado da paci\u00eancia da Gra\u00e7a Divina, nossa oportunidade de mudar volunt\u00e1ria e alegremente, sem sofrimento! Agora, no Ju\u00edzo Final, esse abuso nos est\u00e1 retornando com for\u00e7a total, e somos compelidos a mudar atrav\u00e9s do sofrimento. <\/strong><\/p><p>Isso ocorre porque apenas o sofrimento extremo pode incapacitar as consci\u00eancias err\u00f4neas para explicar a realidade, e ent\u00e3o finalmente, a consci\u00eancia espiritual pode come\u00e7ar a se desenvolver naquelas pessoas cuja centelha espiritual ainda n\u00e3o foi completamente extinta.<\/p><p>Portanto, <strong>se olharmos para os eventos naturais da perspectiva do esp\u00edrito, que apenas busca ascender e retornar \u00e0 Luz, at\u00e9 mesmo o sofrimento se torna uma forma necess\u00e1ria de gra\u00e7a!<\/strong><\/p><p><strong>Um exemplo perfeito disso pode ser visto hoje:<\/strong><\/p><p>Quando as pessoas se encontram no meio do que chamam de &#8220;desastre natural&#8221;, muito frequentemente o que sai de suas bocas s\u00e3o estas duas palavras:<\/p><p><strong>&#8220;Meu Deus!&#8221; <\/strong><\/p><p>\u00c9 triste que nos lembremos da exist\u00eancia do Criador apenas em situa\u00e7\u00f5es t\u00e3o extremas, mas estas tr\u00eas palavras testemunham exatamente o que dissemos antes:<\/p><p>Apenas quando o inteleto e as emo\u00e7\u00f5es j\u00e1 n\u00e3o t\u00eam palavras para argumentar e fazer as suas afirma\u00e7\u00f5es rid\u00edculas, s\u00f3 ent\u00e3o o esp\u00edrito finalmente far\u00e1 o que sempre deveria fazer: olhar para cima!<\/p><ol start=\"6\"><li><strong>  O que podemos fazer agora para sermos poupados do pior? Ainda podemos fazer alguma coisa?  <\/strong><\/li><\/ol><p><strong>Sim, reconhecer a nossa culpa, examinar-nos impiedosamente, transformar e reconstruir toda a nossa<\/strong> <strong>exist\u00eancia numa funda\u00e7\u00e3o espiritual em vez de numa intelectual e emocional.<\/strong><\/p><p>Por outras palavras: em vez de nos tornarmos peritos em e &#8220;tirarmos um doutoramento&#8221; em toda a Escurid\u00e3o e mal \u00e0 nossa volta e desviarmos toda a responsabilidade espiritual de n\u00f3s mesmos, devemos tirar um <strong>&#8220;doutoramento no nosso pr\u00f3prio ego&#8221;!<\/strong><\/p><p>Mesmo que seja na d\u00e9cima primeira hora, devemos cair de joelhos, baixar as nossas cabe\u00e7as, e come\u00e7ar a corrigir e purificar tudo o que se desenvolveu erroneamente dentro de n\u00f3s!<\/p><p>Apenas se nos focarmos nisto com honestidade, humildade, e com toda a nossa for\u00e7a, inten\u00e7\u00e3o e dedica\u00e7\u00e3o\u2014podemos reparar o nosso karma e tamb\u00e9m merecer prote\u00e7\u00e3o e tutela dos Seres Elementais (como aconteceu, por exemplo, ao longo do \u00caxodo do Egito, onde os Seres Elementais &#8220;protagonizaram&#8221; sob a orienta\u00e7\u00e3o de Mois\u00e9s, como \u00e9 apresentado na nossa s\u00e9rie de palestras, Hist\u00f3rias B\u00edblicas como C\u00f3digos para Decifrar a Realidade do Mundo Hoje).<\/p><p><strong>No entanto, aqueles que j\u00e1 hoje verdadeiramente<\/strong> <strong>embarcaram no caminho necess\u00e1rio de corre\u00e7\u00e3o e purifica\u00e7\u00e3o j\u00e1 n\u00e3o t\u00eam medo!<\/strong><\/p><p>Com confian\u00e7a completa em Deus, vivem em gratid\u00e3o alegre ao Criador e a todos os Seus servos fi\u00e9is, que atrav\u00e9s do Ju\u00edzo Final\u2014que \u00e9 tamb\u00e9m uma express\u00e3o de amor!\u2014finalmente lhes d\u00e3o a oportunidade de voltar atr\u00e1s e tornar-se um ser humano no sentido mais pleno da palavra.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1943\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1943\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cap\u00edtulo Tr\u00eas: As Atividades dos Grandes Seres Elementais (Os Senhores da Natureza) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1943\" class=\"elementor-element elementor-element-69a471b e-con-full e-flex e-con e-child\" data-id=\"69a471b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1839010 elementor-widget elementor-widget-text-editor\" data-id=\"1839010\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p> Come\u00e7amos este cap\u00edtulo com uma explica\u00e7\u00e3o de como as v\u00e1rias mitologias chegaram \u00e0 conclus\u00e3o errada de que os <strong>grandes Seres Elementais<\/strong> s\u00e3o deuses que governam sobre os elementos b\u00e1sicos: <strong>Fogo, \u00c1gua, Ar e Terra<\/strong>.<\/p><p>Os m\u00e9diuns de <strong>na\u00e7\u00f5es primitivas<\/strong> podiam ver <strong>apenas<\/strong> o seu ambiente <strong>astral<\/strong>, nem sequer o <strong>et\u00e9reo<\/strong>, e certamente n\u00e3o as Esferas <strong>Anim\u00edsticas<\/strong> e <strong>Espirituais<\/strong>.<\/p><p>Portanto, podiam ver apenas <strong>dem\u00f3nios<\/strong>: seres criados unicamente do <strong>medo, ansiedade, ci\u00fame, ressentimento, inveja, gan\u00e2ncia ou lux\u00faria<\/strong> dos seres humanos e que tamb\u00e9m s\u00e3o alimentados por essas mesmas emo\u00e7\u00f5es.<\/p><p>Por esta raz\u00e3o, encontramos entre povos primitivos <strong>medo e adora\u00e7\u00e3o de dem\u00f3nios<\/strong>, porque era isso que viam e isso que os assustava!<\/p><p>Estes dem\u00f3nios n\u00e3o t\u00eam vida pr\u00f3pria e s\u00e3o completamente dependentes das emo\u00e7\u00f5es de medo e ansiedade daqueles que os criaram, assim como da energia de outros seres humanos assustados.<\/p><p>Aqui tamb\u00e9m opera a Lei da Atra\u00e7\u00e3o entre Esp\u00e9cies Similares, e portanto qualquer um que seja governado pelo medo atrai magneticamente estes dem\u00f3nios de medo e ansiedade para si, o que apenas aumenta o seu medo e ansiedade at\u00e9 ao ponto do desespero e loucura!<\/p><p>Em contraste, a <strong>aus\u00eancia de medo<\/strong> naturalmente repele estes seres, e portanto \u00e9 sabido que uma pessoa corajosa ter\u00e1 sempre vantagem sobre algu\u00e9m que est\u00e1 constantemente com medo.<\/p><p>Portanto, n\u00e3o \u00e9 surpreendente que entre estes povos primitivos, que tinham uma consci\u00eancia espiritual <strong>subdesenvolvida<\/strong>, v\u00e1rios tipos de <strong>feiticeiros<\/strong> emergiram que descobriram como os dem\u00f3nios podiam ser repelidos atrav\u00e9s da paz interior, saltos, dan\u00e7as, ou can\u00e7\u00f5es de exorcismo que inspiram coragem!<\/p><p>Este assunto \u00e9 fascinante por dois motivos: primeiro, porque muitas pessoas sofrem de depress\u00e3o e ansiedade no nosso tempo, e segundo, porque hoje em dia est\u00e3o surgindo todo tipo de <strong>xam\u00e3s<\/strong> cujas t\u00e9cnicas\u2014como as <strong>cerim\u00f4nias de ayahuasca<\/strong>\u2014apenas abrem a porta para o mundo dos dem\u00f4nios para pessoas espiritualmente inconscientes que se tornam v\u00edtimas dessas pr\u00e1ticas.<\/p><p>No entanto, este assunto vai al\u00e9m do prop\u00f3sito da palestra de hoje, ent\u00e3o vamos continuar com os est\u00e1gios mais elevados da habilidade clarividente. Aqueles com habilidades clarividentes entre os <strong>gregos, romanos e germ\u00e2nicos<\/strong> conseguiam ver ainda mais longe! Sua vis\u00e3o alcan\u00e7ava al\u00e9m do mundo material at\u00e9 a esfera anim\u00edstica existente acima dele, que fica abaixo da esfera espiritual que \u00e9 o Para\u00edso.  <\/p><p>Durante o desenvolvimento dessas na\u00e7\u00f5es, eles tamb\u00e9m eram capazes de perceber <strong>os governantes dos elementos<\/strong> e sentir uma profunda conex\u00e3o com eles, porque essas criaturas est\u00e3o pr\u00f3ximas daquela mesma parte anim\u00edstica que os humanos tamb\u00e9m carregam, al\u00e9m do esp\u00edrito.<\/p><p>A capacidade de ver, sentir e ouvir os Seres Elementais era a maior conquista desses povos naquela \u00e9poca, e, portanto, era natural que eles vissem esses governantes dos elementos\u2014que eram t\u00e3o sublimes e diferentes\u2014como os mais elevados de todos e os chamassem de:<\/p><p><strong>&#8220;Deuses&#8221;<\/strong> e sua morada inacess\u00edvel: <strong>Olimpo ou Valhalla<\/strong>.<\/p><p>O par governante mais elevado reside no topo da Esfera Anim\u00edstica. Apesar de receberem nomes diferentes em diferentes tradi\u00e7\u00f5es, todos simbolizam o mesmo significado. <\/p><p>Os povos germ\u00e2nicos e n\u00f3rdicos chamavam este par de: <strong>&#8220;Odin e Freya&#8221; ou &#8220;Wotan e Frigga&#8221;; os gregos os chamavam de &#8220;Zeus e Hera&#8221;; os romanos de &#8220;J\u00fapiter e Juno&#8221;; os eg\u00edpcios de &#8220;Os\u00edris e \u00cdsis&#8221;<\/strong> entre outros.<\/p><p>Todos os nomes, por seu pr\u00f3prio significado, refletem a verdadeira natureza e papel desses seres.<\/p><p>Por exemplo, Odin e Wotan significam: &#8220;portador de luz no universo&#8221;; J\u00fapiter: &#8220;trazedor de luz&#8221;; Os\u00edris: &#8220;luz dos c\u00e9us&#8221;.<\/p><p><strong>Portanto, Odin, Wotan, Zeus, J\u00fapiter e Os\u00edris s\u00e3o\u2014apesar de seus nomes diferentes\u2014sempre o mesmo ser e sempre se referem ao guia e governante supremo do Olimpo.<\/strong><\/p><p>Mas se voc\u00ea agora for ler as v\u00e1rias mitologias esperando aprender mais sobre os grandes Seres Elementais, certamente ficar\u00e1 surpreso com os muitos atos cru\u00e9is descritos nessas hist\u00f3rias. (<strong>Por exemplo: o mito de Cronos<\/strong>, que devorava seus filhos imediatamente ap\u00f3s o nascimento, porque foi profetizado que um deles o derrubaria.)<\/p><p>Portanto, deve-se notar que esses atos foram apenas atribu\u00eddos aos &#8220;deuses&#8221;, mas s\u00e3o na verdade produto da influ\u00eancia luciferiana.<\/p><p>Nos \u00faltimos sete mil anos, essa influ\u00eancia tamb\u00e9m causou o apagamento completo do verdadeiro conhecimento que os seres humanos uma vez possu\u00edram sobre a atividade ben\u00e9fica desses seres supremos.<\/p><p>Assim, quase imperceptivelmente, as pr\u00e1ticas de adora\u00e7\u00e3o tamb\u00e9m mudaram: Em todos os lugares, imagens e est\u00e1tuas foram erguidas com o \u00fanico prop\u00f3sito de obscurecer e destruir a verdade sobre esses grandes seres, e at\u00e9 &#8220;novos deuses&#8221; foram proclamados que exigiam formas imorais ou cru\u00e9is de adora\u00e7\u00e3o de \u00eddolos.<\/p><p><strong>***<\/strong><\/p><p><strong>Atrav\u00e9s da atividade dos poderosos seres do Olimpo (Valhalla), as sete partes do mundo tamb\u00e9m foram criadas\u2014cada uma das quais \u00e9, por sua vez, um universo\u2014cujos tamanhos imensos nunca podem ser compreendidos pelo intelecto humano, que n\u00e3o consegue nem mesmo examinar a aparente infinidade de seu pr\u00f3prio universo (cosmos).<\/strong><\/p><p><strong>Nosso cosmos consiste em milh\u00f5es de gal\u00e1xias. Cada gal\u00e1xia cont\u00e9m bilh\u00f5es de estrelas, e algumas dessas estrelas s\u00e3o os centros de sistemas planet\u00e1rios como nosso pr\u00f3prio sistema solar\u2014e existem incont\u00e1veis sistemas desse tipo. <\/strong><\/p><p>Estes s\u00e3o agora os nomes das sete partes do mundo (mencionadas no <em>Livro do Apocalipse<\/em>, mas interpretadas erroneamente como cidades terrestres\u2014j\u00e1 que existem realmente cidades com os mesmos nomes na Terra): <strong>\u00c9feso, Esmirna, P\u00e9rgamo, Tiatira, Sardes, Filad\u00e9lfia e Laodiceia.<\/strong><\/p><p>Nosso planeta pertence \u00e0 parte do mundo <strong>\u00c9feso<\/strong>. Todos os objetos vis\u00edveis no c\u00e9u noturno, seja a olho nu ou atrav\u00e9s dos maiores telesc\u00f3pios, fazem parte de \u00c9feso. Sem exce\u00e7\u00e3o, tudo isso consiste em mat\u00e9ria grosseira, mesmo quando tamb\u00e9m envolve nebulosas difusas. No entanto, a humanidade nunca ser\u00e1 capaz de olhar para qualquer uma das outras partes do mundo (universos) com seus instrumentos de mat\u00e9ria grosseira.   <\/p><p>O esp\u00edrito humano, por outro lado, recebeu o poder n\u00e3o apenas de transformar e moldar seu pr\u00f3prio universo, mas tamb\u00e9m de exercer influ\u00eancia em todos os planos et\u00e9reos. Isso, no entanto, nunca ser\u00e1 compreens\u00edvel para o intelecto, ent\u00e3o n\u00e3o deve ser abordado mais aqui.  <\/p><p>No entanto, h\u00e1 uma coisa que podemos entender at\u00e9 certo ponto com o intelecto: a profunda signific\u00e2ncia da afirma\u00e7\u00e3o: os pensamentos criam a realidade. Ainda assim, n\u00f3s tamb\u00e9m reduzimos tudo isso ao m\u00ednimo para alcan\u00e7ar apenas objetivos terrenos-pessoais: dinheiro, um corpo em forma, fama, etc. Este assunto \u00e9 certamente fascinante, mas n\u00e3o podemos elabor\u00e1-lo no \u00e2mbito desta palestra.  <\/p><p>No entanto, o pouco que compartilhamos nos ajuda a desenvolver uma perspectiva muito mais ampla sobre nossa verdadeira exist\u00eancia como esp\u00edritos humanos e perceber que <strong>precisamos parar de nos obcecar e fixar em &#8220;nosso pequeno canto&#8221;\u2014aquelas quatro paredes com uma hipoteca de 30 anos que se tornou nosso mundo inteiro e que estamos dispostos a defender com nossas vidas&#8230;<\/strong><\/p><p><strong>***<\/strong><\/p><p><strong>Para resumir:<\/strong> Embora olhemos apenas para baixo, nestes Dias do Ju\u00edzo Final, n\u00f3s <strong>devemos<\/strong> olhar para cima!<\/p><p>Isso porque nossa origem \u00e9 mais elevada do que a dos Seres Elementais, e, portanto, se aspirarmos para cima, os reconheceremos. Mas ent\u00e3o tamb\u00e9m deixaremos de consider\u00e1-los como deuses, porque eles n\u00e3o s\u00e3o deuses, mas fi\u00e9is servos de Deus, que podem nos ensinar o verdadeiro significado do servi\u00e7o alegre na Cria\u00e7\u00e3o. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1944\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1944\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cap\u00edtulo Quatro: As Atividades dos Pequenos Seres Elementais <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1944\" class=\"elementor-element elementor-element-666e0a2 e-con-full e-flex e-con e-child\" data-id=\"666e0a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d4580e elementor-widget elementor-widget-text-editor\" data-id=\"0d4580e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>N\u00e3o somos apenas obrigados a reconhecer os grandes governantes elementais, os Senhores da Natureza, mas tamb\u00e9m devemos reconhecer a atividade dos <strong>pequenos Seres Elementais<\/strong>, que est\u00e3o muito mais pr\u00f3ximos de n\u00f3s. No entanto, tendemos a descartar hist\u00f3rias sobre eles como meros contos de fadas, <strong>lendas e fantasias<\/strong>. Estes incluem, entre outros:  <\/p><p><strong>Os gigantes, os gnomos, os elfos, as fadas e as salamandras.<\/strong><\/p><p>Esses pequenos seres criaram o planeta Terra com suas pr\u00f3prias m\u00e3os em sublime beleza, e at\u00e9 hoje, eles fortalecem e preservam a natureza.<\/p><p>Durante o tempo em que ainda existia uma rela\u00e7\u00e3o de amor m\u00fatuo entre os seres humanos e os Seres Elementais, eles faziam tudo ao seu alcance para guiar e facilitar a vida da humanidade.<\/p><p>Mas essa conex\u00e3o entre humanos e os elementos foi destru\u00edda h\u00e1 muito tempo. Os fi\u00e9is servos do Criador fugiram dos seres humanos. <\/p><p>O abismo que separa esses seres da natureza dos humanos tornou-se quase imposs\u00edvel de transpor.<\/p><p>No entanto, evid\u00eancias de sua exist\u00eancia ainda podem ser encontradas em v\u00e1rios lugares:<\/p><p><strong>O Alcor\u00e3o<\/strong>, por exemplo, confirma que al\u00e9m de anjos e seres humanos, Deus tamb\u00e9m criou os <strong>Jinn.<\/strong> (<strong>O g\u00eanio que emerge da l\u00e2mpada de Aladdin nos contos de &#8220;As Mil e Uma Noites&#8221;, comumente conhecidos como &#8220;As Noites \u00c1rabes&#8221;, nada mais \u00e9 do que um Ser Elemental.<\/strong>) Estes n\u00e3o consistem de mat\u00e9ria, mas existem no mundo da mat\u00e9ria grosseira. Eles s\u00e3o os arquitetos da mat\u00e9ria e, portanto, realizam muitas atividades no mundo material. <\/p><p>Na Europa do s\u00e9culo XVI, foi o famoso m\u00e9dico Paracelso quem preservou o conhecimento sobre os Seres Elementais.<\/p><p>Ele dedicou uma de suas muitas obras a esses seres, que ele afirmava conhecer pessoalmente, j\u00e1 que podia perceb\u00ea-los: <strong>&#8220;Um Livro sobre Ninfas, Silfos, Pigmeus e Salamandras, e sobre os Outros Esp\u00edritos.&#8221;<\/strong><\/p><p>\u00c0s vezes, <strong>crian\u00e7as<\/strong> conseguem v\u00ea-los, mas quando contam aos adultos sobre isso, os adultos zombam delas, pensando que as &#8220;pessoas pequenas&#8221; s\u00e3o apenas frutos da imagina\u00e7\u00e3o de seus filhos.<\/p><p><strong>Animais<\/strong> tamb\u00e9m\u2014cuja origem est\u00e1 na Esfera Anim\u00edstica\u2014podem perceb\u00ea-los e, portanto, recebem avisos sobre eventos naturais dos Seres Elementais, que ent\u00e3o comunicam aos seus donos de v\u00e1rias maneiras. (Isso n\u00e3o \u00e9 porque os animais t\u00eam um <strong>&#8220;sexto sentido&#8221;<\/strong> como a ci\u00eancia especula em sua tentativa de encontrar uma explica\u00e7\u00e3o racional para esse fen\u00f4meno.) <\/p><p>Em nossa s\u00e9rie &#8220;Hist\u00f3rias de Karma&#8221; em nosso site, descrevemos como uma mulher e sua fam\u00edlia foram salvas de um terremoto no Peru porque ela ouviu os sinais de alerta dados por seus p\u00e1ssaros engaiolados.<\/p><p>O exemplo mais famoso disso na B\u00edblia \u00e9 a hist\u00f3ria da jumenta de Bala\u00e3o <strong>(N\u00fameros Cap\u00edtulo 22):<\/strong><\/p><p>Por ordem do rei de Moabe, o profeta Bala\u00e3o partiu para amaldi\u00e7oar o povo de Israel. No caminho, um anjo apareceu para det\u00ea-lo, mas apenas a jumenta podia v\u00ea-lo. Claro, aqui tamb\u00e9m n\u00e3o estamos falando de um anjo\u2014que n\u00e3o desce diretamente \u00e0 terra\u2014mas de um Ser Elemental alado. (A prop\u00f3sito, a palavra hebraica para &#8220;anjo&#8221; vem da raiz <strong>que significa &#8220;fazer trabalho&#8221;,<\/strong> que \u00e9 exatamente o que os Seres Elementais fazem!)   <\/p><p>A jumenta desviou-se do caminho tr\u00eas vezes, e cada vez Bala\u00e3o a golpeou. Finalmente, a jumenta falou e perguntou por que ele a estava batendo. <\/p><p>S\u00f3 ent\u00e3o Bala\u00e3o viu o ser que explicou a Bala\u00e3o que a jumenta havia salvado sua vida.<\/p><p>\u00c0s vezes, situa\u00e7\u00f5es extremas podem ampliar nossa capacidade de percep\u00e7\u00e3o, como Charles Lindbergh descreveu. Ele foi o primeiro piloto a voar sozinho atrav\u00e9s do Oceano Atl\u00e2ntico em 1927. Em seu livro <strong>&#8220;O Esp\u00edrito de St. Louis&#8221;,<\/strong> ele descreve como\u2014exausto pelo frio, condi\u00e7\u00f5es clim\u00e1ticas severas e falta de sono\u2014conseguiu chegar ao seu destino <strong>gra\u00e7as \u00e0 orienta\u00e7\u00e3o dos Seres Elementais.<\/strong>  <\/p><p><strong>Deixe-me compartilhar uma hist\u00f3ria pessoal:<\/strong> Uma vez me perdi em uma floresta onde lobos vagam \u00e0 noite\u2014qualquer um que me conhece sabe que eu n\u00e3o tenho absolutamente nenhum senso de dire\u00e7\u00e3o\u2014e rezei aos Seres Elementais por ajuda para encontrar meu caminho. Em cinco minutos, um bando de p\u00e1ssaros apareceu de repente do nada e voou de forma muito consp\u00edcua ao longo de um certo caminho. Eu sabia que este era o sinal vis\u00edvel que os Seres Elementais haviam me enviado, e seguindo a dire\u00e7\u00e3o que os p\u00e1ssaros indicaram, encontrei meu caminho de volta para casa.  <\/p><p>  ***  <\/p><p>Hoje, nestes tempos do Ju\u00edzo Final, h\u00e1 pessoas que j\u00e1 possuem conhecimento sobre os Seres Elementais\u2014conhecimento que muitos de voc\u00eas est\u00e3o encontrando pela primeira vez.<\/p><p>Eles anseiam por se tornarem capazes de ver\u2014pelo menos uma vez em suas vidas terrenas\u2014os gigantes, gnomos, elfos, fadas, salamandras e muitos outros.<\/p><p>Com saudade e tristeza, eles se perguntam por que\u2014apesar de sua f\u00e9 absoluta\u2014seu desejo n\u00e3o pode ser realizado.<\/p><p>A resposta \u00e9 que \u00e9 quase imposs\u00edvel perceber os Seres Elementares devido ao atual estado da humanidade. <\/p><p>Nunca os veremos com o olho f\u00edsico, j\u00e1 que eles n\u00e3o s\u00e3o f\u00edsicos. Portanto, precisar\u00edamos aprender a ver com o olho espiritual. <\/p><p>No entanto, atrav\u00e9s do <strong>dar<\/strong>, uma pessoa com uma vontade pura pode ganhar o favor dos Seres Elementais para que eles se aproximem dela novamente!<\/p><p>Isso porque <strong>s\u00f3 atrav\u00e9s do dar se pode receber!<\/strong><\/p><p>Assim, primeiro precisamos aprender a dar algo \u00e0 natureza!<\/p><p>E dar n\u00e3o significa apenas proteger a natureza\u2014que \u00e9 o melhor que normalmente fazemos, embora a maioria da humanidade nem sequer consiga isso. Em vez disso, significa entender que, como seres espirituais, fomos feitos para <strong>ir \u00e0 natureza e compartilhar nosso poder espiritual com os elementos,<\/strong> que ent\u00e3o protegeriam nossos corpos e sa\u00fade em troca. <\/p><p>Al\u00e9m disso, embora os Seres Elementais n\u00e3o possam libertar ningu\u00e9m do karma, sua prote\u00e7\u00e3o \u00e9 inestim\u00e1vel, uma vez que eles podem aliviar e at\u00e9 mesmo desviar grande parte do karma, por exemplo, prevenindo les\u00f5es e acidentes.<\/p><p><strong>&#8220;Pois Ele dar\u00e1 aos Seus anjos ordem a seu respeito, para guard\u00e1-lo em todos os seus caminhos. Eles o sustentar\u00e3o em suas m\u00e3os, para que voc\u00ea n\u00e3o tropece com o p\u00e9 em uma pedra.&#8221;<\/strong><\/p><p>Este \u00e9 um vers\u00edculo muito famoso\u2014do Salmo 91, vers\u00edculos 11-12\u2014que promete a prote\u00e7\u00e3o de anjos para aqueles que confiam em Deus, embora, como vimos, <strong>os seres que fornecem esta prote\u00e7\u00e3o<\/strong> n\u00e3o sejam anjos, mas os Seres Elementais.<\/p><p>No entanto, como esta verdade foi esquecida por n\u00f3s, hoje, <strong>at\u00e9 mesmo os amantes da natureza realmente protegem a natureza para seu pr\u00f3prio benef\u00edcio!<\/strong> Para que <strong>eles<\/strong> possam desfrutar dela e serem energizados por ela!<\/p><p>Em outras palavras, at\u00e9 mesmo os protetores e amantes da natureza est\u00e3o completamente inconscientes de que drenam energia dos Seres Elementais como vampiros, sem dar nada em troca! (E nem vamos mencionar o que acontece em <strong>&#8220;festas na natureza&#8221; com m\u00fasica trance, drogas e at\u00e9 mesmo mera fuma\u00e7a de cigarro<\/strong>&#8230; Isso \u00e9 t\u00e3o terr\u00edvel para os Seres Elementais que ningu\u00e9m poderia possivelmente pensar que receberia prote\u00e7\u00e3o deles em tais situa\u00e7\u00f5es&#8230;)  <\/p><p>***<\/p><p>Vamos agora descrever uma pequena parte das atividades dos v\u00e1rios Seres Elementais. (Livros inteiros foram escritos sobre este assunto.) <\/p><p>Os gigantes possuem enormes poderes de magnitude inimagin\u00e1vel. Eles n\u00e3o s\u00f3 podem desenraizar montanhas e construir novas, mas tamb\u00e9m constru\u00edram <strong>a Grande Pir\u00e2mide de Giz\u00e9, Stonehenge e as Linhas de Nazca<\/strong>. <\/p><p>Os guardi\u00f5es da floresta tamb\u00e9m trabalham com a radia\u00e7\u00e3o que emitem, o que d\u00e1 \u00e0 floresta seu frescor e fragr\u00e2ncia.<\/p><p>Os gnomos dos campos e prados podem nos ajudar a resolver um dos grandes mist\u00e9rios do nosso tempo: <strong>c\u00edrculos nas planta\u00e7\u00f5es!<\/strong> Pois s\u00e3o eles que os criaram, com o prop\u00f3sito de nos transmitir mensagens.<\/p><p>No mar, in\u00fameros seres aqu\u00e1ticos se movem. Seu senhor \u00e9 <strong>Netuno com seu tridente<\/strong>. (Conhecido nas mitologias como o deus da \u00e1gua, mas j\u00e1 sabemos que ele \u00e9 um grande Ser Elemental, um Senhor da Natureza, respons\u00e1vel pela \u00e1gua).  <\/p><p>Seu tridente n\u00e3o \u00e9 um mito\u2014ele realmente o carrega em sua m\u00e3o direita, e este tridente\u2014que as pessoas ainda podiam ver em tempos anteriores, quando ainda estavam conectadas com os Seres Elementais\u2014\u00e9 carregado com poderes superiores.<\/p><p>Quando lemos em jornais hist\u00f3rias sobre como \u00e1guas que antes eram calmas se intensificam em for\u00e7as furiosas que destroem tudo em seu caminho\u2014devemos saber que isso \u00e9 feito pelos elementos da \u00e1gua sob o comando de Netuno.<\/p><p>No momento atual, a principal tarefa dos Seres Elementais do ar \u00e9 varrer a Terra de toda a escurid\u00e3o, incluindo as formas de pensamento escuras e t\u00f3xicas pairando sobre a terra como gases venenosos.<\/p><p>Existem tamb\u00e9m pequenos Seres Elementais que guardam e protegem nossas casas, a quem devemos muito mais gratid\u00e3o do que temos demonstrado at\u00e9 agora. Em sua lealdade, eles trabalham constantemente para manter influ\u00eancias nocivas longe de n\u00f3s. <\/p><p>Nas casas de pessoas generosas e boas, eles removem as formas de pensamento feias e maliciosas que tentam entrar e se estabelecer ali.<\/p><p>Mas em casas onde ocorrem brigas, ci\u00fame, gan\u00e2ncia, mentiras e imoralidade, os pequenos seres tristemente partem e n\u00e3o podem cumprir sua miss\u00e3o. A b\u00ean\u00e7\u00e3o ent\u00e3o est\u00e1 ausente dessas casas. <\/p><p>Existem seres adicionais que a maioria de n\u00f3s n\u00e3o conhece, e estes s\u00e3o nossos ajudantes do corpo, a quem tamb\u00e9m devemos tanta gratid\u00e3o, porque eles ajudam nosso corpo a permanecer saud\u00e1vel.<\/p><p>Quando dormimos \u00e0 noite e nosso esp\u00edrito parte em jornadas para outros planos, eles podem trabalhar sem serem perturbados em nosso corpo, e eles trabalham incansavelmente para que estejamos sempre saud\u00e1veis, a fim de cumprir nossa miss\u00e3o prim\u00e1ria para a qual encarnamos na Terra.<\/p><p>Quando nosso alinhamento interno est\u00e1 correto, eles at\u00e9 ajudam a <strong>mudar a estrutura do nosso c\u00e9rebro<\/strong> para que nosso pequeno c\u00e9rebro, o cerebelo, possa ser mais ativo!<\/p><p>Mas devemos apoiar este trabalho, dando ao nosso corpo o que ele precisa: nutri\u00e7\u00e3o adequada, descanso adequado, higiene e, especialmente, mantendo a calma interior e evitando o estresse.<\/p><p>Ao mesmo tempo, devemos lembrar que <strong>os Seres Elementais ajudar\u00e3o especialmente aqueles cujo esp\u00edrito est\u00e1 direcionado para cima, em servi\u00e7o \u00e0 Luz!<\/strong><\/p><p>Eles proteger\u00e3o os seus corpos com cuidado extra\u2014mesmo que n\u00e3o sigam uma dieta org\u00e2nica rigorosa\u2014em virtude de uma esp\u00e9cie de pacto secreto entre eles que diz:<\/p><p><strong>&#8220;Tu trabalhar\u00e1s para a Luz e n\u00f3s protegeremos o teu corpo para que possas cumprir a tua miss\u00e3o.&#8221;<\/strong><\/p><p>O conhecimento sobre os Seres Elementais e a conex\u00e3o com eles ser\u00e1 a base para os cuidados de sa\u00fade no novo mundo!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1945\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1945\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cap\u00edtulo Cinco: Um Olhar para um Novo Mundo <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1945\" class=\"elementor-element elementor-element-72086e3 e-con-full e-flex e-con e-child\" data-id=\"72086e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2616e2b elementor-widget elementor-widget-text-editor\" data-id=\"2616e2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este cap\u00edtulo baseia-se num livro profundo para a nova era: &#8220;A Glimpse into Another World and the Failure of Mankind&#8221;, que est\u00e1 dispon\u00edvel para compra em v\u00e1rias l\u00ednguas atrav\u00e9s de https:\/\/letitbegin.net\/index.php\/en\/home .<\/p><p>Este livro revolucion\u00e1rio \u00e9 um <strong>apelo<\/strong> aos <strong>cientistas<\/strong>, que devem descobri-lo e tornar-se pioneiros da ci\u00eancia no novo mundo.<\/p><p>Entre outras coisas, este livro cria uma <strong>ponte<\/strong> entre o conhecimento da atividade dos Seres Elementais e a ci\u00eancia. Aborda particularmente a conex\u00e3o entre estes seres, as descobertas da <strong>f\u00edsica qu\u00e2ntica<\/strong> e a possibilidade de criar <strong>energia livre<\/strong> (como <strong>Nikola Tesla<\/strong> j\u00e1 vislumbrava). <\/p><p>Mas primeiro, vamos compreender a principal diferen\u00e7a entre a f\u00edsica cl\u00e1ssica e a f\u00edsica qu\u00e2ntica, que come\u00e7ou a desenvolver-se no in\u00edcio do s\u00e9culo XX.<\/p><p>Enquanto a f\u00edsica cl\u00e1ssica procurava explicar o mundo apenas atrav\u00e9s de leis materiais, a f\u00edsica qu\u00e2ntica descobriu que as part\u00edculas de mat\u00e9ria se comportam de maneiras que as leis materiais n\u00e3o conseguem explicar ou justificar. (A prop\u00f3sito, o termo &#8220;qu\u00e2ntico&#8221; refere-se \u00e0s menores unidades fundamentais que comp\u00f5em tudo ao nosso redor.) <\/p><p>Vamos elaborar:<\/p><p>O \u00e1tomo \u00e9 composto por part\u00edculas extremamente pequenas\u2014<strong>eletr\u00f5es, prot\u00f5es e neutr\u00f5es.<\/strong> (Alguns de n\u00f3s ainda se lembram disto das aulas de f\u00edsica na escola&#8230;)<\/p><p>No entanto, a f\u00edsica qu\u00e2ntica descobriu que mesmo essas pequenas part\u00edculas (os prot\u00f5es e neutr\u00f5es) s\u00e3o elas pr\u00f3prias compostas por<strong> componentes ainda mais min\u00fasculos,<\/strong> conhecidos como<strong> part\u00edculas fundamentais, que n\u00e3o podem ser observadas diretamente, mas cuja atividade pode ser detetada.<\/strong><\/p><p><strong>No entanto, a atividade invis\u00edvel de todas essas part\u00edculas fundamentais \u00e9, na verdade, o resultado direto da coopera\u00e7\u00e3o entre o espiritual e o anim\u00edstico!<\/strong><\/p><p><strong>Mais precisamente: A intera\u00e7\u00e3o das part\u00edculas espirituais e das part\u00edculas anim\u00edsticas cria radia\u00e7\u00f5es que, por sua vez, formam a casca material em torno desses componentes fundamentais, que percebemos como mat\u00e9ria. \u00c9 assim que a massa da mat\u00e9ria \u00e9 criada em todas as suas v\u00e1rias formas! <\/strong><\/p><p><strong>Para resumir: aquilo que cria a mat\u00e9ria n\u00e3o \u00e9 a pr\u00f3pria mat\u00e9ria!<\/strong><\/p><p><strong>Portanto, sem as radia\u00e7\u00f5es espirituais e anim\u00edsticas, todo o desenvolvimento material cessaria e ocorreria a decomposi\u00e7\u00e3o, j\u00e1 que as suas radia\u00e7\u00f5es fornecem a for\u00e7a de liga\u00e7\u00e3o que conecta e mant\u00e9m tudo unido.<\/strong><\/p><p>***<\/p><p>Ao longo da evolu\u00e7\u00e3o, tudo o que \u00e9 elemental cumpriu fielmente o seu papel.<\/p><p>No entanto, o espiritual\u2014ao qual foi dada livre vontade para exercer o seu poder criativo e refinador\u2014traiu o Plano da Luz ao focar todas as suas aspira\u00e7\u00f5es <strong>apenas<\/strong> para baixo, em dire\u00e7\u00e3o ao terreno e ao material.<\/p><p>Por outras palavras, o poder criativo do esp\u00edrito foi mal utilizado e, assim, tudo o que \u00e9 elemental\u2014que <strong>n\u00e3o<\/strong> possui livre vontade\u2014foi inevitavelmente for\u00e7ado a submeter-se \u00e0 vontade distorcida do espiritual. Isto teve um enorme impacto <strong>tamb\u00e9m<\/strong> na estrutura da massa da <strong>mat\u00e9ria<\/strong>: tornou-se cada vez mais densa e pesada porque o esp\u00edrito humano n\u00e3o canalizou Luz suficiente para a mat\u00e9ria. <\/p><p>Assim, <strong>as for\u00e7as de liga\u00e7\u00e3o<\/strong>\u2014que s\u00e3o as for\u00e7as que conectam todas as partes do \u00e1tomo e que, como mencionado, n\u00e3o s\u00e3o mais do que as radia\u00e7\u00f5es das part\u00edculas espirituais e das part\u00edculas anim\u00edsticas\u2014tornaram-se cada vez mais r\u00edgidas no seu efeito dentro da mat\u00e9ria.<\/p><p>Como resultado, o planeta Terra\u2014com toda a mat\u00e9ria dentro dele\u2014tornou-se pesado e denso.<\/p><p>Este processo pode ser sentido intuitivamente quando observamos uma pessoa cuja centelha espiritual se apagou e reconhecemos a sua &#8220;pesadez&#8221;. Ou quando nos encontramos numa grande cidade cheia de gente e sentimos qu\u00e3o grosseiros, feios e distantes da Luz s\u00e3o todos aqueles edif\u00edcios (raz\u00e3o pela qual os Seres Elementais n\u00e3o gostam de habitar neles&#8230;). <\/p><p>Em contraste, quando os seres humanos est\u00e3o conectados \u00e0 sua consci\u00eancia espiritual, afetam a mat\u00e9ria na dire\u00e7\u00e3o oposta: as for\u00e7as de liga\u00e7\u00e3o tornam-se ent\u00e3o mais soltas, a rigidez dissolve-se e a mat\u00e9ria torna-se menos densa e pesada. Por outras palavras, torna-se mais leve, mais &#8220;a\u00e9rea&#8221; e luminosa. <\/p><p>Como \u00e9 que tudo isto se relaciona com a <strong>energia livre<\/strong>, sobre a qual Tesla falou? Ou seja, energia que n\u00e3o polui nem explora a natureza, que \u00e9 inesgot\u00e1vel e que est\u00e1 dispon\u00edvel para cada pessoa sem custo? <\/p><p>Aqui precisamos descrever um tipo muito espec\u00edfico dessas part\u00edculas fundamentais:<\/p><p><strong>Neutrinos.<\/strong><\/p><p><strong>As part\u00edculas de neutrinos\u2014que s\u00e3o, na verdade, part\u00edculas fundamentais anim\u00edsticas<\/strong> que n\u00e3o fazem parte do \u00e1tomo\u2014penetram constantemente a mat\u00e9ria em incont\u00e1veis bili\u00f5es, mas no atual estado denso da mat\u00e9ria, n\u00e3o a conseguem afetar.<\/p><p><strong>Isto pode ser comparado a uma turbina e\u00f3lica: quando as p\u00e1s s\u00e3o demasiado pesadas, o vento n\u00e3o as consegue mover para gerar energia.<\/strong><\/p><p>Por outras palavras, no nosso estado atual, os Seres Elementais n\u00e3o nos conseguem ajudar a gerar<strong> energia livre.<\/strong><\/p><p>Isto era poss\u00edvel nos tempos antigos, quando os seres humanos ainda mantinham uma conex\u00e3o com a Luz. Em contraste, n\u00f3s\u2014que nos percebemos como t\u00e3o &#8220;avan\u00e7ados&#8221;\u2014perdemos essa possibilidade precisamente porque &#8220;avan\u00e7\u00e1mos&#8221; apenas com o inteleto! <\/p><p>A energia livre \u00e9, na verdade, <strong>energia de neutrinos,<\/strong> que os povos antigos j\u00e1 conseguiam usar e simplesmente chamavam por um nome diferente:<strong> For\u00e7a-Luz. Portanto, a capacidade de obter tal energia novamente est\u00e1 intimamente ligada ao nosso estado espiritual! <\/strong><\/p><p>Se a mat\u00e9ria se tornar realmente leve, a\u00e9rea e luminosa\u2014gra\u00e7as \u00e0 renovada orienta\u00e7\u00e3o do esp\u00edrito humano para cima\u2014os \u00e1tomos da mat\u00e9ria tornar-se-\u00e3o mais semelhantes aos neutrinos.<strong> Isto permitir\u00e1 uma intera\u00e7\u00e3o entre eles e levar\u00e1 \u00e0 cria\u00e7\u00e3o de energia livre inesgot\u00e1vel!<\/strong><\/p><p>Voltando ao nosso exemplo anterior, se a mat\u00e9ria se tornar mais leve e luminosa, isto significaria que as p\u00e1s da turbina e\u00f3lica se tornariam mais leves e ent\u00e3o o vento conseguiria mov\u00ea-las.<\/p><p>Nikola Tesla j\u00e1 havia conduzido experi\u00eancias bem-sucedidas nesta \u00e1rea e, segundo relat\u00f3rios, at\u00e9 construiu prot\u00f3tipos iniciais de dispositivos que funcionavam com esta energia livre. Ele chamava-lhe <strong>for\u00e7a c\u00f3smica<\/strong> porque as part\u00edculas de neutrinos ainda n\u00e3o eram conhecidas na \u00e9poca. Tesla foi um dos importantes <strong>Chamados<\/strong> que deveria fazer avan\u00e7ar esta tecnologia usando o conhecimento que reside na obra <strong>&#8220;\u00c0 Luz da Verdade\u2014A Mensagem do Graal.&#8221;<\/strong> No curso avan\u00e7ado da nossa escola, estudamos a edi\u00e7\u00e3o original de 1941 desta obra-prima (que s\u00f3 pode ser encontrada em <a href=\"https:\/\/letitbegin.net\/index.php\/en\/home\/\" target=\"_blank\" rel=\"noopener\">https:\/\/letitbegin.net\/index.php\/en\/home\/<\/a> ou <a href=\"https:\/\/shop.letitbeginuk.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/shop.letitbeginuk.com\/<\/a>), juntamente com todas as explica\u00e7\u00f5es e orienta\u00e7\u00f5es necess\u00e1rias para os nossos tempos.  <\/p><p>No entanto, muito antes da morte de Tesla em 1943, o conceito de energia livre foi completamente abandonado porque parou de produzir resultados favor\u00e1veis. Isto aconteceu porque a mat\u00e9ria come\u00e7ou ent\u00e3o a tornar-se mais densa, tornando imposs\u00edveis as intera\u00e7\u00f5es entre a mat\u00e9ria e essas part\u00edculas. <\/p><p>Nessa \u00e9poca, o sucesso das experi\u00eancias s\u00f3 era poss\u00edvel porque <strong>o Filho do Homem<\/strong> estava na Terra, e o Seu Poder ajudou a soltar as for\u00e7as de liga\u00e7\u00e3o.<\/p><p>Desde ent\u00e3o, desenvolvemos e promovemos ativamente energia poluente que explora o planeta Terra porque este tipo de energia funciona bem em condi\u00e7\u00f5es densas. Em planos mais leves e luminosos, ningu\u00e9m consideraria usar a nossa tecnologia atual, mas aqui\u2014neste ambiente pesado e denso\u2014n\u00e3o h\u00e1 alternativa. <\/p><p>No entanto, \u00e0 medida que a densidade diminui, isto tornar-se-\u00e1 cada vez mais poss\u00edvel\u2014para grande espanto de todos os f\u00edsicos\u2014e a energia livre ficar\u00e1 dispon\u00edvel para uso pr\u00e1tico na tecnologia e de outras formas.<\/p><p>A humanidade aprender\u00e1 a conectar-se com esta fonte de energia limpa e inesgot\u00e1vel.<\/p><p>Inicialmente, esta tecnologia pode funcionar em algumas regi\u00f5es mas n\u00e3o noutras, dependendo de certas condi\u00e7\u00f5es e do estado espiritual das pessoas que l\u00e1 vivem.<\/p><p>***<\/p><p><strong>O esp\u00edrito humano possui tanto poder! Poderia ter elevado \u00c9feso para se tornar um reflexo do Para\u00edso, mas em vez disso transformou-o num inferno na terra! <\/strong><\/p><p>Portanto, mesmo aqueles que n\u00e3o compreendem todas as explica\u00e7\u00f5es cient\u00edficas devem perceber que podem facilmente contribuir para o al\u00edvio das for\u00e7as de liga\u00e7\u00e3o e permitir a ascens\u00e3o do planeta Terra. Isto pode ser alcan\u00e7ado atrav\u00e9s de uma coisa simples: fazer da Luz o seu \u00fanico anseio na vida! <\/p><p><strong>(Isto, a prop\u00f3sito, \u00e9 exatamente o que as pessoas justas fazem, que normalmente sabem pouco ou nada sobre f\u00edsica em geral, e f\u00edsica qu\u00e2ntica em particular!)<\/strong><\/p><p>Isto porque este \u00e9 realmente o \u00fanico anseio natural do esp\u00edrito quando n\u00e3o \u00e9 suprimido pelo inteleto e pelas emo\u00e7\u00f5es: <strong>o anseio de obter consci\u00eancia espiritual esfor\u00e7ando-se para cima!<\/strong> (Enquanto as duas consci\u00eancias terrenas\u2014o inteleto e as emo\u00e7\u00f5es\u2014por sua pr\u00f3pria natureza sempre dirigem o seu olhar <strong>para baixo&#8230;<\/strong>)<\/p><p>O esp\u00edrito sabe que o mundo material <strong>n\u00e3o<\/strong> \u00e9 o seu lar!<\/p><p>Tal esp\u00edrito maduro nunca destruiria, por ignor\u00e2ncia e arrog\u00e2ncia, o lugar de hospitalidade que abriu as suas portas para ele, nem sequer consideraria fazer do mundo da mat\u00e9ria grosseira a sua morada permanente, como se esse fosse o objetivo mais alto da sua exist\u00eancia.<\/p><p>Sabe que \u00e9 apenas um h\u00f3spede que veio para dar a sua contribui\u00e7\u00e3o \u00fanica e agradecer pela hospitalidade, mas depois deve continuar para o seu verdadeiro lar&#8230; para o Para\u00edso!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1946\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1946\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cap\u00edtulo Seis: O Grande Cometa <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1946\" class=\"elementor-element elementor-element-a01bf9e e-con-full e-flex e-con e-child\" data-id=\"a01bf9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f90c96f elementor-widget elementor-widget-text-editor\" data-id=\"f90c96f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Muitas pessoas temem asteroides e cometas.<\/p><p>Portanto, embora a maioria das pessoas n\u00e3o esteja familiarizada com a combina\u00e7\u00e3o dos conceitos: <strong>&#8220;O Ju\u00edzo Final&#8221;<\/strong> e <strong>&#8220;O Grande Cometa&#8221;,<\/strong> estes evocam nelas um medo inexplicado.<\/p><p>Isto \u00e9, na verdade, um <strong>medo antigo e primordial<\/strong> que est\u00e1 gravado nas suas almas sobre um tempo quando vir\u00e1 o acerto de contas final por todo o comportamento errado da humanidade ao longo de milhares de anos, do qual nenhuma pessoa conseguir\u00e1 escapar.<\/p><p>E de facto, mesmo antes deste grande e \u00fanico cometa se tornar vis\u00edvel, a sua influ\u00eancia resultar\u00e1 na escalada intensificada de eventos que chamamos: desastres naturais.<\/p><p><strong>E \u00e9 exatamente isto que est\u00e1 a acontecer agora!<\/strong><\/p><p>Claro, n\u00e3o podemos ajudar aqueles que n\u00e3o querem ouvir sobre isto e tamb\u00e9m n\u00e3o compreendem qu\u00e3o rid\u00edculo \u00e9 negar todos os <strong>eventos extraordin\u00e1rios<\/strong>\u2014que acontecem diante dos nossos pr\u00f3prios olhos todos os dias!\u2014e trat\u00e1-los como eventos que sempre aconteceram, da mesma maneira. Ou pensar que a engenharia clim\u00e1tica pode causar todos estes fen\u00f3menos em todo o lado ao redor do mundo, porque as elites est\u00e3o essencialmente a desempenhar o papel dos &#8220;novos senhores do mundo&#8230;&#8221;<\/p><p>Mas aqueles que seguiram toda a palestra at\u00e9 este ponto j\u00e1 sabem por que isto est\u00e1 a acontecer.<\/p><p>Neste cap\u00edtulo, vamos apenas aprofundar a quest\u00e3o sob uma perspetiva diferente.<\/p><p>***<\/p><p>Devido ao fracasso da humanidade\u2014que, como mencionado, se ligou cada vez mais \u00e0 mat\u00e9ria\u2014o planeta Terra tornou-se mais pesado e mais lento. Afundou-se para baixo e foi empurrado para uma \u00f3rbita que quase n\u00e3o \u00e9 mais influenciada pela Luz. <\/p><p>Portanto, a execu\u00e7\u00e3o de &#8220;O Ju\u00edzo Final&#8221;, que estar\u00e1 sob a influ\u00eancia do Grande Cometa, far\u00e1 regressar todo o \u00c9feso \u00e0 \u00f3rbita que foi originalmente designada para ele.<\/p><p>Este cometa destacou-se do reino espiritual primordial eterno e est\u00e1 a avan\u00e7ar na sua trajet\u00f3ria numa linha <strong>reta<\/strong> em dire\u00e7\u00e3o a esta parte do mundo.<\/p><p>O seu n\u00facleo est\u00e1 cheio de alto poder espiritual; envolve-se em mat\u00e9ria e assim finalmente tornar-se-\u00e1 vis\u00edvel tamb\u00e9m para a humanidade na Terra.<\/p><p>Com a chegada do Grande Cometa, a Terra tremar\u00e1 com as suas radia\u00e7\u00f5es, e uma nova era da humanidade come\u00e7ar\u00e1: <strong>a Era da Verdade!<\/strong><\/p><p>Entretanto, o Grande Cometa envia <strong>mensageiros<\/strong> de dentro de si mesmo, que devem intensificar a radia\u00e7\u00e3o e revitalizar diretamente a densidade, sem imediatamente destru\u00ed-la:<\/p><p><strong>Em 2012<\/strong> chegou o primeiro mensageiro: O cometa Ison.<\/p><p><strong>Em maio de 2020<\/strong>, a radia\u00e7\u00e3o do segundo mensageiro: O cometa Atlas, come\u00e7ou a afetar o planeta Terra e a sua influ\u00eancia continua at\u00e9 hoje.<\/p><p><strong>***<\/strong><\/p><p><strong>O que devemos fazer para nos prepararmos para esta era?<\/strong><\/p><p>Quando ouvimos essas descri\u00e7\u00f5es, inicialmente parece que n\u00e3o h\u00e1 nada que possamos fazer e que estamos destinados a colher o nosso mau karma.<\/p><p><strong>No entanto, o karma n\u00e3o se destina a punir, mas a permitir que uma pessoa experimente as consequ\u00eancias das suas a\u00e7\u00f5es erradas, para que escolha mudar para melhor!<\/strong><\/p><p><strong>O karma \u00e9 uma oportunidade para corre\u00e7\u00e3o interna, realinhamento e purifica\u00e7\u00e3o!<\/strong><\/p><p>Portanto, n\u00e3o devemos ficar sentados sem fazer nada ou resignar-nos derrotisticamente a esperar pelo pior.<\/p><p>Tamb\u00e9m n\u00e3o devemos atribuir \u00e0 nossa indol\u00eancia espiritual v\u00e1rios t\u00edtulos como: &#8220;esperar pela reden\u00e7\u00e3o&#8221; ou &#8220;confiar em Deus&#8221;.<\/p><p>Pois se j\u00e1 compreendemos que, devido ao nosso fracasso em ouvir o nosso esp\u00edrito, trouxemos o mundo ao estado em que est\u00e1, devemos\u2014e at\u00e9 <strong>temos de<\/strong>\u2014agora <strong>inverter o curso<\/strong> na <strong>dire\u00e7\u00e3o oposta!<\/strong><\/p><p><strong>O homem n\u00e3o pode ser t\u00e3o ativo na destrui\u00e7\u00e3o e depois permanecer de maneira completamente passiva quando \u00e9 necess\u00e1rio reparar esse dano.<\/strong><\/p><p>Portanto, <strong>devemos ser ativos e contribuir com a nossa parte para o processo de reden\u00e7\u00e3o tanto de n\u00f3s mesmos como de todo o mundo!<\/strong><\/p><p>Quando nos tornarmos um novo ser humano\u2014que \u00e9 o que aprendemos nos v\u00e1rios cursos da Escola Alma para a Humanidade\u2014seremos magnetizados pelos raios do cometa, de acordo com a Lei da Atra\u00e7\u00e3o entre Esp\u00e9cies Similares. Isto porque a sua origem tamb\u00e9m est\u00e1 na esfera espiritual. <\/p><p>Isto pode ser explicado com a seguinte imagem:<\/p><p>H\u00e1 dois magnetos: um forte = o cometa, e um fraco = o nosso esp\u00edrito.<\/p><p>Se o nosso esp\u00edrito se tornar mais forte, ser\u00e1 atra\u00eddo pelo cometa forte. E vamos realmente sentir isto porque resultar\u00e1 em liberdade das correntes internas e numa sensa\u00e7\u00e3o de for\u00e7a e alegria que nunca conhecemos antes! <\/p><p><strong>Portanto, toda a pessoa que acredita em Deus e na Sua Justi\u00e7a absoluta deve olhar para a frente e para cima com calma e confian\u00e7a, e n\u00e3o temer o que est\u00e1 por vir nos anos \u00e0 frente.<\/strong><\/p><p><strong>Se escolher levantar os olhos para cima, confiadamente em dire\u00e7\u00e3o a Deus, nenhum mal lhe acontecer\u00e1.<\/strong><\/p><p>Em contraste, se mostrarmos indiferen\u00e7a ou fraqueza face a todos os eventos do Ju\u00edzo Final, ent\u00e3o o nosso esp\u00edrito ser\u00e1 um magneto demasiado fraco para o cometa magnetizar, e ent\u00e3o ocorrer\u00e1 o processo oposto: as correntes internas\u2014que s\u00e3o a consci\u00eancia intelectual e a consci\u00eancia emocional\u2014puxar-nos-\u00e3o para baixo e experimentaremos medo, desespero, depress\u00e3o e ansiedade como nunca conhecemos antes!<\/p><p><strong>Este trabalho interno n\u00e3o \u00e9 apenas para a salva\u00e7\u00e3o de cada um dos nossos esp\u00edritos individuais, mas tamb\u00e9m para a salva\u00e7\u00e3o de todo o planeta!<\/strong><\/p><p>E para este trabalho precisamente, <strong>os 144.000 Chamados<\/strong> devem avan\u00e7ar\u2014aqueles que menciono em todas as palestras dadas ao p\u00fablico geral e aos quais chamo repetidamente para virem, para que juntos possamos cumprir a nossa antiga promessa!<\/p><p>***<\/p><p>Agora, vamos descrever a coopera\u00e7\u00e3o necess\u00e1ria entre os Chamados e o Cometa, e finalmente explicaremos tamb\u00e9m como isto se relaciona com os Seres Elementais e os eventos naturais.<\/p><p>Como j\u00e1 mencionado, o papel dos Seres Elementais \u00e9 trazer o Julgamento atrav\u00e9s das for\u00e7as da natureza.<\/p><p>Mas para que destruam apenas o que est\u00e1 errado e n\u00e3o <strong>toda<\/strong> a Terra, precisam das radia\u00e7\u00f5es do Cometa, que primeiro t\u00eam de ser <strong>transformadas<\/strong> pelos esp\u00edritos dos Chamados.<\/p><p>Isto \u00e9 necess\u00e1rio porque apenas os esp\u00edritos dos Chamados podem servir como elo de liga\u00e7\u00e3o entre as radia\u00e7\u00f5es do Cometa, cuja origem est\u00e1 na Esfera Espiritual Primordial, e a Esfera Anim\u00edstica.<\/p><p>Portanto, o esp\u00edrito do ser humano Chamado \u00e9 obrigado a abrir-se e absorver essas radia\u00e7\u00f5es atrav\u00e9s do seu intenso anseio de servir a Luz, e depois transform\u00e1-las <strong>atrav\u00e9s do seu pr\u00f3prio ser<\/strong>: atrav\u00e9s da purifica\u00e7\u00e3o interior e alinhamento, compreens\u00e3o profunda das conex\u00f5es, e acima de tudo, amor e confian\u00e7a em Deus.<\/p><p>O trabalho dos Chamados no processo de reden\u00e7\u00e3o tamb\u00e9m pode ser ilustrado da seguinte forma:<\/p><p>De um lado, de cima, est\u00e1 o Cometa, enviando-nos as suas radia\u00e7\u00f5es, que abra\u00e7am e impedem que o Planeta Terra caia na destrui\u00e7\u00e3o!<\/p><p>Do outro lado, de baixo, cada um dos Chamados tem um poder enorme para elevar \u00c9feso em dire\u00e7\u00e3o ao Cometa!<\/p><p>Para compara\u00e7\u00e3o, se uma pessoa comum tem o poder de uma gota de \u00e1gua, cada Chamado tem o poder de um oceano.<\/p><p><strong>Portanto, se todos os 144.000 Chamados trabalharem para se purificar de dentro e se manterem eretos na Vontade da Luz, juntos conseguir\u00e3o ajudar a elevar \u00c9feso de baixo!<\/strong><\/p><p>Assim, atrav\u00e9s desta coopera\u00e7\u00e3o, quando chegar o momento em que o Cometa finalmente eleve o planeta Terra e todas as profecias se cumpram, o planeta Terra e toda a humanidade n\u00e3o estar\u00e3o condenados.<\/p><p>Claro, tudo o que acabou de ser explicado<strong> n\u00e3o pode <\/strong>ser compreendido de forma alguma pelo intelecto muito limitado da maioria das pessoas. As pessoas intelectuais geralmente rejeitam o &#8220;trabalho espiritual&#8221; e pensam que apenas algo <strong>pr\u00e1tico<\/strong>\u2014como manifesta\u00e7\u00f5es contra o establishment\u2014pode realmente ajudar! <\/p><p>Mas a raz\u00e3o para isto \u00e9 a sua ignor\u00e2ncia do facto de que<strong> o esp\u00edrito humano recebeu um poder t\u00e3o grande que pode influenciar n\u00e3o apenas a condi\u00e7\u00e3o do planeta Terra, mas tamb\u00e9m sistemas solares e gal\u00e1xias inteiras!<\/strong><\/p><p><strong>***<\/strong><\/p><p><strong>Onde ser\u00e3o vistos os efeitos do Grande Cometa?<\/strong><\/p><p>Contrariamente \u00e0 l\u00f3gica do intelecto e das emo\u00e7\u00f5es, \u00e9 precisamente nos lugares onde os seres humanos est\u00e3o a sofrer\u2014de guerras, pobreza, etc.\u2014que os raios do Cometa e os eventos naturais purificadores ocorrer\u00e3o primeiro. Pois essas pessoas j\u00e1 n\u00e3o podem procurar satisfa\u00e7\u00e3o nas suas vidas terrenas e, portanto, depositaram as suas esperan\u00e7as bem alto.<\/p><p><strong>Por outras palavras, a cura come\u00e7a onde existe o anseio mais genu\u00edno pela Luz.<\/strong><\/p><p>Portanto, n\u00e3o significa que estamos mais pr\u00f3ximos da Luz se, protegidos pela densidade\u2014isto \u00e9, atrav\u00e9s da tecnologia e das finan\u00e7as\u2014permanecemos ilesos, mas sim o contr\u00e1rio!<\/p><p>Devemos apenas lembrar-nos de que quando os raios do Cometa rodearem completamente o planeta Terra, eles afetar\u00e3o tudo, chegando mesmo aos cantos mais remotos e densos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1947\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1947\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cap\u00edtulo Sete: Tudo Est\u00e1 Previsto, Contudo, o Livre-Arb\u00edtrio \u00c9 Concedido <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1947\" class=\"elementor-element elementor-element-6864686 e-con-full e-flex e-con e-child\" data-id=\"6864686\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff6012d elementor-widget elementor-widget-text-editor\" data-id=\"ff6012d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A humanidade enfrenta agora <strong>dois cen\u00e1rios poss\u00edveis: cura ou destrui\u00e7\u00e3o.<\/strong><\/p>\n<p>Os Seres Elementais est\u00e3o prontos e preparados para executar <strong>qualquer um dos dois<\/strong> cen\u00e1rios.<\/p>\n<p><strong>O primeiro cen\u00e1rio<\/strong> representa o caminho misericordioso do Julgamento, trazendo esperan\u00e7a para o futuro da humanidade. Este resultado otimista s\u00f3 ocorrer\u00e1 se os Chamados cumprirem o seu papel. <\/p>\n<p>De facto, mesmo este caminho de miseric\u00f3rdia envolve tremendas convuls\u00f5es, mas leva n\u00e3o \u00e0 destrui\u00e7\u00e3o de quase toda a humanidade, mas sim \u00e0 transforma\u00e7\u00e3o que ocorrer\u00e1 ao longo de v\u00e1rias gera\u00e7\u00f5es\u2014transforma\u00e7\u00e3o do mundo bem como daqueles esp\u00edritos humanos que escolhem a purifica\u00e7\u00e3o interior e se alinham com a Vontade de Deus.<\/p>\n<p>Os Chamados devem tamb\u00e9m servir como <strong>o exemplo e modelo do novo ser humano<\/strong>. Seguindo a sua lideran\u00e7a, o resto da humanidade\u2014em quem a centelha do esp\u00edrito ainda n\u00e3o foi extinta\u2014conseguir\u00e1 seguir. <\/p>\n<p>No entanto, se os Chamados <strong>n\u00e3o<\/strong> cumprirem a sua miss\u00e3o, <strong>enfrentaremos<\/strong> <strong>o segundo cen\u00e1rio:<\/strong><\/p>\n<p>O Planeta Terra ser\u00e1, no entanto, elevado pela press\u00e3o da Luz\u2014pois isto \u00e9 o que Deus exige agora\u2014mas ent\u00e3o, durante esta ascens\u00e3o, a Terra ser\u00e1 transformada sob esta press\u00e3o de tal forma que quase toda a humanidade ser\u00e1 aniquilada.<\/p>\n<p>Apenas muito poucos esp\u00edritos humanos\u2014cujo anseio pela Luz n\u00e3o foi extinto\u2014conseguir\u00e3o sobreviver a tal cen\u00e1rio no planeta Terra.<\/p>\n<p>Estes poucos tornar-se-\u00e3o ent\u00e3o a funda\u00e7\u00e3o para a nova gera\u00e7\u00e3o na Terra purificada.<\/p>\n<p>Se\u2014Deus nos livre\u2014chegarmos a este cen\u00e1rio, ent\u00e3o o planeta Terra ser\u00e1 como <strong>a Arca de No\u00e9<\/strong>, onde apenas o que \u00e9 necess\u00e1rio e apenas aqueles que s\u00e3o dignos sobreviver\u00e3o.<\/p>\n<p><strong>A que se pode comparar isto? <\/strong><\/p>\n<p>A uma pessoa que tratou o seu corpo com tremenda neglig\u00eancia, e depois um dia descobre que uma doen\u00e7a grave se apoderou do seu corpo.<\/p>\n<p>No primeiro cen\u00e1rio, ap\u00f3s uma cirurgia dolorosa e um processo de recupera\u00e7\u00e3o que exige uma mudan\u00e7a completa de estilo de vida\u2014ele curar\u00e1 com sucesso, apesar do sofrimento envolvido neste processo.<\/p>\n<p>No segundo cen\u00e1rio, a doen\u00e7a ser\u00e1 descoberta demasiado tarde, e ent\u00e3o a pessoa n\u00e3o ter\u00e1 escolha sen\u00e3o tomar muitos analg\u00e9sicos, que, no entanto, n\u00e3o impedir\u00e3o a sua morte.<\/p>\n<p>Que cen\u00e1rio escolheremos?<\/p>\n<p><b>Tudo Est\u00e1 Previsto, Contudo, o Livre-Arb\u00edtrio \u00c9 Concedido<\/b><br\/>N\u00f3s da &#8220;Alma Escola para a Humanidade&#8221; escolhemos nos esfor\u00e7ar e aplicar nossa for\u00e7a espiritual e terrena ao m\u00e1ximo, atrav\u00e9s de nosso alinhamento interior, vontade e a\u00e7\u00f5es, para o cumprimento do primeiro cen\u00e1rio: uma purifica\u00e7\u00e3o que trar\u00e1 cura, transforma\u00e7\u00e3o completa para um futuro de esperan\u00e7a para a humanidade atual!<\/p>\n<p>Portanto, se voc\u00ea ouve o chamado, junte-se a n\u00f3s!<\/p>\n<p>Que possamos inclinar as nossas cabe\u00e7as e dobrar os nossos joelhos em gratid\u00e3o a Deus, cuja Miseric\u00f3rdia e Bondade para connosco perduram, mesmo no Julgamento Final.<\/p>\n<p>Assim como toda a Cria\u00e7\u00e3o serve e louva o seu Senhor e Criador, que possamos finalmente fazer o mesmo!<\/p>\n<p>Que tenhamos apenas um \u00fanico e profundo desejo: Que haja Luz \u2013 em todo o lado! Que a santa Luz de Deus brilhe vitoriosamente sobre tudo! <\/p>\n<p>Am\u00e9m!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f089e92 e-con-full e-flex e-con e-parent\" data-id=\"f089e92\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-70d7f72 e-con-full FORM e-grid e-con e-child\" data-id=\"70d7f72\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-64513bc e-con-full e-flex e-con e-child\" data-id=\"64513bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aea2c9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5aea2c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Para receber alertas sobre futuros eventos ou apresentar perguntas sobre este conte\u00fado a Hagit, por favor forne\u00e7a suas informa\u00e7\u00f5es:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec4745a e-con-full e-flex e-con e-child\" data-id=\"ec4745a\" data-element_type=\"container\" data-e-type=\"container\" style=\"\">\n\t\t<div class=\"elementor-element elementor-element-9b6aa85 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"9b6aa85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7e1876 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c7e1876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d033291 e-con-full e-flex e-con e-child\" data-id=\"d033291\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e23509 elementor-widget elementor-widget-heading\" data-id=\"5e23509\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">Participe do grupo do WhatsApp<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd8daca elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"dd8daca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>receba comunicados sobre encontros, palestras e novos conte\u00fados!<br><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\" rel=\"noopener\"><strong>Clique aqui<\/strong><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd335a7 e-con-full e-flex e-con e-child\" data-id=\"bd335a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-60a7078 e-con-full elementor-hidden-desktop e-flex e-con e-child\" data-id=\"60a7078\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3633209 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3633209\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5eac281 e-con-full e-flex e-con e-child\" data-id=\"5eac281\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d814816 elementor-widget elementor-widget-heading\" data-id=\"d814816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">Participe do grupo do WhatsApp<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0766a50 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0766a50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>receba comunicados sobre encontros, palestras e novos conte\u00fados!<\/p><p><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\" rel=\"noopener\"><strong>Clique aqui<\/strong><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-652d118 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"652d118\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Pr\\u00f3ximo&quot;,&quot;step_previous_label&quot;:&quot;Anterior&quot;,&quot;button_width&quot;:&quot;60&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"PvE\" name=\"Desastres naturais - Perguntas Antecipadas\" aria-label=\"Desastres naturais - Perguntas Antecipadas\" novalidate=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"18290\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"652d118\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-first_name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-first_name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[first_name]\" id=\"form-field-first_name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-last_name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-last_name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tSobrenome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[last_name]\" id=\"form-field-last_name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-country elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-country\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPa\u00eds\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[country]\" id=\"form-field-country\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-question elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-question\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVoc\u00ea tem uma pergunta para Hagit?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[question]\" id=\"form-field-question\" rows=\"4\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-a34ga34ga elementor-col-100\">\n\t\t\t\t\tPoderemos utilizar o endere\u00e7o de e-mail que voc\u00ea usou para fazer sua inscri\u00e7\u00e3o\/compra, de tempos em tempo, para enviar, a voc\u00ea, conte\u00fado de marketing e ofertas relativas a produtos e servi\u00e7os similares \u00e0queles que voc\u00ea comprou ou para o qual se inscreveu, nos termos da se\u00e7\u00e3o 30A(c) da Lei de Comunica\u00e7\u00f5es Israelenses (Telecomunica\u00e7\u00e3o e difus\u00e3o) Lei no. 5742-1982. Voc\u00ea poder\u00e1 nos notificar caso n\u00e3o queira receber esses conte\u00fados respondendo ao e-mail com \"Remover\/Cancelar Inscri\u00e7\u00e3o\" ou utilizando o link \"Cancelar Inscri\u00e7\u00e3o\" que aparece nas mensagens de marketing. Enquanto n\u00e3o recebermos essa notifica\u00e7\u00e3o de recusa, consideraremos que temos o seu consentimento para enviar tal conte\u00fado.  \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_da71f3aewfeawe elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_da71f3aewfeawe]\" id=\"form-field-field_da71f3aewfeawe\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-mc_tag elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[mc_tag]\" id=\"form-field-mc_tag\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" value=\"Natural_Disasters_SITE_FORM_ORG\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-60 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-403e441 e-flex e-con-boxed e-con e-parent\" data-id=\"403e441\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22bcf20 elementor-widget elementor-widget-text-editor\" data-id=\"22bcf20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-renderer-start-pos=\"1\">Continue a sua jornada:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee6c051 e-grid e-con-full e-con e-child\" data-id=\"ee6c051\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8d9fe08 e-con-full e-flex e-con e-child\" data-id=\"8d9fe08\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5b90ba elementor-widget elementor-widget-text-editor\" data-id=\"b5b90ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Profetas vs Imp\u00e9rios<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e3dfc4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1e3dfc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/almaschool.org\/pt-br\/profetas-vs-imperios\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Clique aqui &gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8af8004 e-con-full e-flex e-con e-child\" data-id=\"8af8004\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff278cd elementor-widget elementor-widget-text-editor\" data-id=\"ff278cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Agenda de L\u00facifer<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40bf4e6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"40bf4e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/almaschool.org\/pt-br\/a-agenda-de-lucifer-post\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Clique aqui &gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2f457d e-flex e-con-boxed e-con e-parent\" data-id=\"e2f457d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c33caa elementor-widget elementor-widget-text-editor\" data-id=\"1c33caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">Sobre a palestrante:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d74e4 elementor-position-left elementor-widget__width-initial elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"d8d74e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6.png\" class=\"attachment-full size-full wp-image-18131\" alt=\"\" srcset=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6.png 1080w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-300x300.png 300w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-1024x1024.png 1024w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-150x150.png 150w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hagit Rabbi<\/h3><p class=\"elementor-image-box-description\">\nHagit \u00e9 professora e fundadora da Alma School for Humanity. Formada pela Universidade de Israel, Departamento do Talmud e Filosofia, de Jerusal\u00e9m, Ela dedicou mais de 20 anos em pesquisas sobre as perguntas profundas relativas \u00e0 exist\u00eancia humana, recebendo inspira\u00e7\u00e3o de fontes elevadas de sabedoria, que v\u00e3o al\u00e9m dos estudos intelectuais. \n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c424f60 elementor-widget elementor-widget-image\" data-id=\"c424f60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"106\" src=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/ASFH-\u05e6\u05d1\u05e2\u05d5\u05e0\u05d9-300x106-1.png\" class=\"attachment-large size-large wp-image-18140\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a82c156 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a82c156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">A escola oferece palestras, artigos, podcasts e cursos online que visam o desenvolvimento da consci\u00eancia espiritual de acordo com as Leis Universais da Cria\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens.&nbsp;Clique em configura\u00e7\u00f5es para ativar as legendas no seu&nbsp;idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da &#8230; <a title=\"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?\" class=\"read-more\" href=\"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/\" aria-label=\"Read more about Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?\">Ler mais<\/a><\/p>\n","protected":false},"author":11,"featured_media":31099,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-18290","page","type-page","status-publish","has-post-thumbnail"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\u00e7\u00f5es para ativar as legendas no seu idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Alma School for Humanity - Calling for the Human Spirit\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? - Alma School for Humanity #\" \/>\n\t\t<meta property=\"og:description\" content=\"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\u00e7\u00f5es para ativar as legendas no seu idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1128\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-10-20T18:00:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-24T07:41:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? - Alma School for Humanity #\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\u00e7\u00f5es para ativar as legendas no seu idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#listItem\",\"name\":\"Desastres Naturais: Altera\\u00e7\\u00f5es Clim\\u00e1ticas ou o Ju\\u00edzo Final?\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#listItem\",\"position\":2,\"name\":\"Desastres Naturais: Altera\\u00e7\\u00f5es Clim\\u00e1ticas ou o Ju\\u00edzo Final?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/#organization\",\"name\":\"Alma School for Humanity\",\"description\":\"Calling for the Human Spirit\",\"url\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/almaschool.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/ASFH-\\u05e6\\u05d1\\u05e2\\u05d5\\u05e0\\u05d9.png\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#organizationLogo\",\"width\":5345,\"height\":1891},\"image\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#webpage\",\"url\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/\",\"name\":\"Desastres Naturais: Altera\\u00e7\\u00f5es Clim\\u00e1ticas ou o Ju\\u00edzo Final? - Alma School for Humanity #\",\"description\":\"Desastres Naturais: Altera\\u00e7\\u00f5es Clim\\u00e1ticas ou o Ju\\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\\u00e7\\u00f5es para ativar as legendas no seu idioma preferido. Ou\\u00e7a o artigo Leia o artigo Introdu\\u00e7\\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\\u00edcio da O que est\\u00e1 por tr\\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\\u00e1 acontecendo no mundo.\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/almaschool.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/NATURAL-DISASTER.jpg\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#mainImage\",\"width\":1800,\"height\":1128},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\\\/#mainImage\"},\"datePublished\":\"2025-10-20T21:00:20+03:00\",\"dateModified\":\"2026-06-24T10:41:28+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/\",\"name\":\"Alma School for Humanity\",\"description\":\"Calling for the Human Spirit\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/pt-br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? - Alma School for Humanity #","description":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\u00e7\u00f5es para ativar as legendas no seu idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo.","canonical_url":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/almaschool.org\/pt-br\/#listItem","position":1,"name":"Home","item":"https:\/\/almaschool.org\/pt-br\/","nextItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#listItem","name":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?"}},{"@type":"ListItem","@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#listItem","position":2,"name":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?","previousItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/pt-br\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/almaschool.org\/pt-br\/#organization","name":"Alma School for Humanity","description":"Calling for the Human Spirit","url":"https:\/\/almaschool.org\/pt-br\/","logo":{"@type":"ImageObject","url":"https:\/\/almaschool.org\/wp-content\/uploads\/2023\/04\/ASFH-\u05e6\u05d1\u05e2\u05d5\u05e0\u05d9.png","@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#organizationLogo","width":5345,"height":1891},"image":{"@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#webpage","url":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/","name":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? - Alma School for Humanity #","description":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\u00e7\u00f5es para ativar as legendas no seu idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo.","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/almaschool.org\/pt-br\/#website"},"breadcrumb":{"@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg","@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#mainImage","width":1800,"height":1128},"primaryImageOfPage":{"@id":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/#mainImage"},"datePublished":"2025-10-20T21:00:20+03:00","dateModified":"2026-06-24T10:41:28+03:00"},{"@type":"WebSite","@id":"https:\/\/almaschool.org\/pt-br\/#website","url":"https:\/\/almaschool.org\/pt-br\/","name":"Alma School for Humanity","description":"Calling for the Human Spirit","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/almaschool.org\/pt-br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Alma School for Humanity - Calling for the Human Spirit","og:type":"article","og:title":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? - Alma School for Humanity #","og:description":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\u00e7\u00f5es para ativar as legendas no seu idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo.","og:url":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/","og:image":"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg","og:image:secure_url":"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg","og:image:width":"1800","og:image:height":"1128","article:published_time":"2025-10-20T18:00:20+00:00","article:modified_time":"2026-06-24T07:41:28+00:00","twitter:card":"summary_large_image","twitter:title":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? - Alma School for Humanity #","twitter:description":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final? Assista a Palestra Esta palestra foi apresentada em hebraico e disponibiliza legendas em diversas linguagens. Clique em configura\u00e7\u00f5es para ativar as legendas no seu idioma preferido. Ou\u00e7a o artigo Leia o artigo Introdu\u00e7\u00e3o Esta palestra leva-nos a novas e profundas alturas, enquanto tece os fios desde o in\u00edcio da O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo.","twitter:image":"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg"},"aioseo_meta_data":{"post_id":"18290","title":"#post_title #separator_sa #site_title #","description":"#post_content O que est\u00e1 por tr\u00e1s do aumento dos desastres naturais em todo o mundo? Descubra a verdade espiritual sobre o que realmentte est\u00e1 acontecendo no mundo. ","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"featured","og_image_url":"https:\/\/almaschool.org\/wp-content\/uploads\/2026\/05\/NATURAL-DISASTER.jpg","og_image_width":"1800","og_image_height":"1128","og_image_custom_url":"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/\u05d0\u05e7\u05dc\u05d9\u05dd_-\u05dc\u05d0\u05ea\u05e8.jpg","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-10-29 16:25:15","updated":"2026-06-24 07:42:04","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/almaschool.org\/pt-br\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDesastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/almaschool.org\/pt-br\/"},{"label":"Desastres Naturais: Altera\u00e7\u00f5es Clim\u00e1ticas ou o Ju\u00edzo Final?","link":"https:\/\/almaschool.org\/pt-br\/desastres-naturais-alteracoes-climaticas-ou-o-juizo-final\/"}],"_links":{"self":[{"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/pages\/18290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/comments?post=18290"}],"version-history":[{"count":29,"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/pages\/18290\/revisions"}],"predecessor-version":[{"id":36847,"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/pages\/18290\/revisions\/36847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/media\/31099"}],"wp:attachment":[{"href":"https:\/\/almaschool.org\/pt-br\/wp-json\/wp\/v2\/media?parent=18290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}