{"id":4837,"date":"2026-01-10T22:38:00","date_gmt":"2026-01-10T20:38:00","guid":{"rendered":"https:\/\/almaschool.org\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/"},"modified":"2026-03-07T11:38:42","modified_gmt":"2026-03-07T09:38:42","slug":"nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente","status":"publish","type":"post","link":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/","title":{"rendered":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4837\" class=\"elementor elementor-4837 elementor-151\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecad2bd e-flex e-con-boxed e-con e-parent\" data-id=\"ecad2bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33f9d5f e-con-full e-flex e-con e-child\" data-id=\"33f9d5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b8719a elementor-widget elementor-widget-text-editor\" data-id=\"0b8719a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Cet article est tir\u00e9 directement de la le\u00e7on 10 de LIB\u00c9REZ MON ESPRIT !, notre cours sur le d\u00e9veloppement de la conscience spirituelle. <\/strong>Comme il s&rsquo;agit de la fin du cours, vous y trouverez des r\u00e9f\u00e9rences aux concepts fondamentaux enseign\u00e9s dans les le\u00e7ons pr\u00e9c\u00e9dentes. Si ce que vous lisez ici vous interpelle, nous vous invitons \u00e0 commencer par le d\u00e9but : chaque le\u00e7on s&rsquo;appuie sur les pr\u00e9c\u00e9dentes, cr\u00e9ant ainsi un parcours complet vers le d\u00e9veloppement spirituel. Il vous suffit de cliquer sur le bouton \u00ab S&rsquo;inscrire maintenant \u00bb en bas de la page.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a0debe e-con-full e-flex e-con e-child\" data-id=\"6a0debe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98492d0 elementor-widget elementor-widget-html\" data-id=\"98492d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"position:relative;padding-top:56.25%;\"><iframe src=\"https:\/\/iframe.mediadelivery.net\/embed\/141115\/25551d0a-6adf-4b2a-afe4-3a39572b9ef7?autoplay=false&amp;loop=false&amp;muted=false&amp;preload=false&amp;responsive=true%20\" loading=\"lazy\" style=\"border:0;position:absolute;top:0;height:100%;width:100%;\" allow=\"accelerometer;gyroscope;autoplay;encrypted-media;picture-in-picture;\" allowfullscreen=\"true\"><\/iframe><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e986afc e-con-full e-flex e-con e-child\" data-id=\"e986afc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48966c6 elementor-widget elementor-widget-html\" data-id=\"48966c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/open.spotify.com\/embed\/episode\/2vpehz8gdpAkres0z1IEWW?utm_source=generator\" style=\"      width: min(100%, 600px);     height: 152px;     border: none;     border-radius: 8px;     display: block;     margin: 0 auto;    \" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\">\r\n<\/iframe>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a994872 elementor-widget elementor-widget-text-editor\" data-id=\"a994872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong> <\/strong><strong>LIB\u00c9REZ MON ESPRIT !<br><\/strong><strong>UN GUIDE POUR EXERCER L&rsquo;ESPRIT DANS LA VIE QUOTIDIENNE<\/strong><\/p><p><strong>Le\u00e7on n\u00b0 10 : Les Dix Commandements de la Parentalit\u00e9 dans la Conscience Spirituelle<\/strong><\/p><p style=\"text-align: center;\"> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56149e7 e-flex e-con-boxed e-con e-parent\" data-id=\"56149e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a8baa9 elementor-widget elementor-widget-text-editor\" data-id=\"6a8baa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les relations de couple et la parentalit\u00e9 sont deux exp\u00e9riences qui peuvent grandement contribuer au d\u00e9veloppement spirituel, car elles refl\u00e8tent notre monde int\u00e9rieur avec pr\u00e9cision. C&rsquo;est-\u00e0-dire qu&rsquo;elles r\u00e9v\u00e8lent o\u00f9 nous nous situons <strong>vraiment<\/strong> dans l\u2019interaction entre l&rsquo;intellect, les \u00e9motions et l&rsquo;esprit. <\/p>\n<p>Nous l&rsquo;avons d\u00e9j\u00e0 expliqu\u00e9 dans l&rsquo;introduction du cours : <strong>\u00ab\u00a0Les personnes qui nous sont les plus proches n&rsquo;entravent pas notre d\u00e9veloppement spirituel ; elles en font partie et y contribuent m\u00eame !\u00a0\u00bb<\/strong><\/p>\n<p><\/p>\n<p>Dans ce sens, les enfants sont de merveilleux professeurs qui sont venus nous donner des le\u00e7ons sur notre ego et sur la fa\u00e7on d&rsquo;\u00e9couter simplement l&rsquo;intuition.<\/p>\n<p><strong>J\u00e9sus <\/strong>avait d\u00e9j\u00e0 transmis cet enseignement \u00e0 ses disciples en une phrase : <strong>\u00ab\u00a0Laissez venir \u00e0 moi les enfants et ne les emp\u00eachez pas, car le Royaume des cieux est \u00e0 ceux qui leur ressemblent.\u00a0\u00bb (Matthieu 19:14)<\/strong><\/p>\n<p><\/p>\n<p>Pourtant, alors que les gens doivent suivre des cours pour obtenir leur permis de conduire, il n&rsquo;existe pas de formation ou de pr\u00e9paration spirituelle pour le mariage et la parentalit\u00e9, et nous voyons donc beaucoup de souffrance, particuli\u00e8rement au sein de la famille.<\/p>\n<p>Alors que la le\u00e7on num\u00e9ro neuf fournissait une pr\u00e9paration spirituelle pour les relations de couple, la le\u00e7on d&rsquo;aujourd&rsquo;hui se concentre sur la pr\u00e9paration spirituelle \u00e0 la parentalit\u00e9.<\/p>\n<p>Pour commencer, nous devons d&rsquo;abord nous lib\u00e9rer de l&rsquo;id\u00e9e fausse <strong>que la parentalit\u00e9 vient \u00ab\u00a0naturellement\u00a0\u00bb<\/strong>. C&rsquo;est parce que seul l&rsquo;aspect biologique est, en effet, naturel, mais devenir un parent qui peut vraiment servir de guide sur le chemin de vie de son enfant n\u00e9cessite une <strong>conscience spirituelle<\/strong> et beaucoup d&rsquo;<strong>entra\u00eenement.<\/strong><\/p>\n<p>Cette conscience peut non seulement permettre d\u2019\u00e9viter de graves erreurs dans l&rsquo;\u00e9ducation des jeunes enfants, mais elle nous donne aussi des outils pour corriger les erreurs que nous avons pu commettre dans le pass\u00e9 avec nos enfants maintenant adultes, parce que nous manquions de conscience spirituelle \u00e0 cette \u00e9poque de leur vie.<\/p>\n<p>De plus, une conscience spirituelle nous aide \u00e0 corriger les erreurs que nos parents ont commises, et ainsi non seulement \u00e0 nous gu\u00e9rir et r\u00e9aligner nos vies, mais aussi \u00e0 briser la cha\u00eene des mauvais sch\u00e9mas transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.<\/p>\n<p><strong><u>Premier Commandement : nos enfants ne nous appartiennent pas<\/u><\/strong><\/p>\n<p>Le po\u00e8te libanais <strong>Khalil Gibran <\/strong>a \u00e9crit dans son po\u00e8me <strong>\u00ab\u00a0\u00c0 propos des enfants\u00a0\u00bb :<\/strong><\/p>\n<p><strong>\u00ab\u00a0Vos enfants ne sont pas vos enfants. <\/strong><\/p>\n<p><strong>Ils sont les fils et les filles du d\u00e9sir de la Vie pour elle-m\u00eame.<\/strong><\/p>\n<p><strong>Ils viennent \u00e0 travers vous mais non de vous, <\/strong><\/p>\n<p><strong>Et bien qu&rsquo;ils soient avec vous, ils ne vous appartiennent pas. <\/strong><\/p>\n<p><strong>Vous pouvez leur donner votre amour mais non vos pens\u00e9es, <\/strong><\/p>\n<p><strong>Car ils ont leurs propres pens\u00e9es. <\/strong><\/p>\n<p><strong>Vous pouvez h\u00e9berger leurs corps mais non leurs \u00e2mes&#8230;\u00a0\u00bb<\/strong><\/p>\n<p><\/p>\n<p><strong>Par cons\u00e9quent, mettre un enfant au monde signifie offrir une opportunit\u00e9 \u00e0 une \u00e2me ind\u00e9pendante de grandir et de se d\u00e9velopper \u00e0 travers nous, mais elle ne nous appartiendra jamais.<\/strong><\/p>\n<p><\/p>\n<p>Dans la pratique, ce commandement exige de nous que nous nous lib\u00e9rions de l&rsquo;ancien concept traditionnel de parentalit\u00e9, qui se concentre sur la possession et le contr\u00f4le, car il ne respecte pas l&rsquo;enfant comme une personne ind\u00e9pendante avec son propre destin.<\/p>\n<p>Nous devons nous rappeler que notre enfant n&rsquo;est pas une \u00ab\u00a0version miniature\u00a0\u00bb, un \u00ab\u00a0mini-moi\u00a0\u00bb de nous-m\u00eames ! Notre intellect et nos \u00e9motions n\u2019ont pas \u00e0 \u00eatre fiers de lui comme s&rsquo;il \u00e9tait une partie int\u00e9grante de notre ego. <\/p>\n<p>Les sages ont enseign\u00e9 que <strong>\u00ab\u00a0l\u2019on ne peut apprendre que ce que son c\u0153ur d\u00e9sire\u00a0\u00bb <\/strong>(Avodah Zarah 19a) et ont conseill\u00e9 <strong>\u00ab\u00a0d&rsquo;\u00e9duquer les jeunes selon leur voie\u00a0\u00bb<\/strong><\/p>\n<p><strong>&nbsp;(Proverbes 22:6)<\/strong><\/p>\n<p><\/p>\n<p>pourtant une grande partie de l&rsquo;\u00e9ducation d&rsquo;aujourd&rsquo;hui &#8211; tant \u00e0 la maison qu&rsquo;\u00e0 l&rsquo;\u00e9cole &#8211; ne s&rsquo;adresse pas \u00e0 ce que le c\u0153ur de l&rsquo;enfant d\u00e9sire ou \u00e0 son chemin unique, mais plut\u00f4t \u00e0 ce que <strong>les egos<\/strong> du parent et de l&rsquo;enseignant d\u00e9sirent.<\/p>\n<p>C&rsquo;est-\u00e0-dire que beaucoup de parents aspirent \u00e0 ce que leurs enfants r\u00e9ussissent l\u00e0 o\u00f9 ils ont eux-m\u00eames \u00e9chou\u00e9, ou excellent dans des domaines o\u00f9 eux-m\u00eames n&rsquo;\u00e9taient que m\u00e9diocres.<\/p>\n<p>Par cons\u00e9quent, nous devons regarder courageusement nos propres limitations et comprendre que sans conscience spirituelle, nous risquons d&rsquo;exploiter nos enfants pour combler ces manques.<\/p>\n<p><strong>Concr\u00e8tement, ce commandement exige de nous qu\u2019en tant que parents, nous commencions par nous \u00e9duquer nous-m\u00eames \u00e0 devenir tels que nous sommes cens\u00e9s \u00eatre.<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><u>Deuxi\u00e8me Commandement : nous ne sommes pas n\u00e9s de nos parents par hasard<\/u><\/strong><\/p>\n<p>Ce commandement nous enseigne que nous ne sommes pas n\u00e9s par hasard de nos parents, et que nos enfants n&rsquo;ont pas trouv\u00e9 leur chemin vers nous par co\u00efncidence.<\/p>\n<p>Il n&rsquo;y a pas de hasard dans la r\u00e9incarnation, et elle se produit conform\u00e9ment \u00e0 deux Lois de la Cr\u00e9ation :<\/p>\n<ol>\n<li><strong> La Loi d&rsquo;Attraction du Genre Semblable<\/strong><\/li>\n<li> <strong>La Loi de l\u2019Action R\u00e9ciproque <\/strong>(aussi connue comme <strong>la Loi de Cause \u00e0 Effet ou la Loi du Karma<\/strong>).<\/li>\n<\/ol>\n<p>En d&rsquo;autres termes, <strong>la raison pour laquelle nous sommes n\u00e9s dans une famille sp\u00e9cifique peut \u00eatre soit parce que nous partageons des traits similaires (positifs ou n\u00e9gatifs), soit parce que nous avons un pass\u00e9 commun dans nos vies ant\u00e9rieures qui doit \u00eatre r\u00e9solu ou d\u00e9velopp\u00e9.<\/strong><\/p>\n<p><\/p>\n<p>Par cons\u00e9quent, ce qui est important, c\u2019est d&rsquo;arr\u00eater de bl\u00e2mer nos parents et de nous consid\u00e9rer comme des victimes des circonstances, et plut\u00f4t de d\u00e9couvrir les le\u00e7ons que nous sommes venus apprendre \u00e0 travers eux.<\/p>\n<p>Si vous voulez commencer \u00e0 d\u00e9couvrir pourquoi vous avez choisi votre \u00ab\u00a0laboratoire familial\u00a0\u00bb, vous \u00eates invit\u00e9 \u00e0 faire l&rsquo;exercice suivant :<\/p>\n<p>Prenez une feuille de papier et divisez-la en trois colonnes. Dans la premi\u00e8re colonne, \u00e9crivez vos propres traits de caract\u00e8re, tant positifs que n\u00e9gatifs. Dans la deuxi\u00e8me colonne, faites de m\u00eame pour votre m\u00e8re, et dans la troisi\u00e8me pour votre p\u00e8re. (Si vous avez des enfants adultes, vous pouvez ajouter une colonne pour chacun d&rsquo;eux et lister \u00e9galement leurs traits positifs et n\u00e9gatifs.)   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-872ac2b elementor-widget elementor-widget-text-editor\" data-id=\"872ac2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Apr\u00e8s avoir compl\u00e9t\u00e9 ces listes, comparez-les pour d\u00e9couvrir les motifs qui r\u00e9v\u00e8lent quelles erreurs vous \u00eates venu corriger, ainsi que les talents que vous \u00eates venu d\u00e9velopper.<\/p><p>Une fois que la le\u00e7on sur les raisons pour lesquelles nous nous sommes incarn\u00e9s dans notre famille est apprise, nous sommes libres de continuer notre chemin. Nous comprendrons alors aussi que <strong>notre enfance<\/strong> &#8211; que la psychologie aime tant analyser et \u00e0 laquelle elle rattache tous nos probl\u00e8mes &#8211; <strong>n&rsquo;est qu&rsquo;une petite partie du pass\u00e9 de notre esprit. <\/strong> <\/p><p>Ce pass\u00e9 &#8211; qui est le r\u00e9sultat d&rsquo;incarnations successives &#8211; ne peut \u00eatre d\u00e9couvert et corrig\u00e9 que par le d\u00e9veloppement de la conscience spirituelle.<\/p><p>Ce commandement est aussi tr\u00e8s important <strong>pour les couples qui veulent un enfant et planifient sa venue au monde.<\/strong><\/p><p>Selon les Lois de la Cr\u00e9ation, vous ne pouvez h\u00e9riter que les caract\u00e9ristiques g\u00e9n\u00e9tiques du corps physique de vos parents. Cependant, l&rsquo;esprit, envelopp\u00e9 dans son corps animique avant d&rsquo;entrer dans le corps physique, reste enti\u00e8rement ind\u00e9pendant. <\/p><p>Un couple qui vibre \u00e0 la haute fr\u00e9quence de l&rsquo;amour v\u00e9ritable, qui a une connexion spirituelle et vit harmonieusement peut attirer une \u00e2me \u00e9lev\u00e9e. Cependant, le manque de conscience quant au sens plus profond de l&rsquo;acte sexuel &#8211; dont nous avons d\u00e9j\u00e0 parl\u00e9 dans la le\u00e7on num\u00e9ro neuf &#8211; peut certainement conduire au r\u00e9sultat inverse : attirer une \u00e2me probl\u00e9matique &#8211; un \u00ab\u00a0mouton noir\u00a0\u00bb &#8211; dans la famille. <\/p><p><strong><u>Troisi\u00e8me Commandement : la connexion cr\u00e9e la correction<\/u><\/strong><\/p><p>Avant la maturit\u00e9 sexuelle &#8211; l&rsquo;\u00e2ge o\u00f9 l&rsquo;\u00e2me perce son enveloppe et commence son voyage ind\u00e9pendant &#8211; les enfants ont absolument besoin de <strong>limites.<\/strong> (Comme nous l&rsquo;avons d\u00e9j\u00e0 expliqu\u00e9 dans la le\u00e7on num\u00e9ro trois.) <\/p><p>Vous ne pouvez pas dire \u00e0 un jeune enfant : \u00ab\u00a0Mange ce que tu veux, quand tu veux\u00a0\u00bb (parce que l&rsquo;enfant mangera des sucreries et de la malbouffe toute la journ\u00e9e) ou \u00ab\u00a0Va dormir quand tu en as envie\u00a0\u00bb (parce que l&rsquo;enfant restera coll\u00e9 aux \u00e9crans toute la nuit et finira par s&rsquo;endormir sur le canap\u00e9 du salon<\/p><p>Les enfants ont aussi besoin <strong>d\u2019\u00eatre guid\u00e9s et recadr\u00e9s<\/strong> quand ils se comportent mal. Cependant, l\u2019erreur que font beaucoup de parents quand ils fixent des limites, guident ou recadrent, est qu\u2019ils permettent \u00e0 leur reine du m\u00e9lodrame de le faire dans le stress pour <strong>tenter de corriger imm\u00e9diatement l\u2019erreur de leur enfant. <\/strong> <\/p><p> Ce faisant, ils <strong>coupent <\/strong>le lien avec l&rsquo;\u00e2me de leur enfant, en lui criant des ordres et en lui faisant comprendre que s\u2019il veut retrouver leur amour, il doit leur ob\u00e9ir imm\u00e9diatement.<\/p><p>En d&rsquo;autres termes, le message qui est transmis \u00e0 l&rsquo;enfant est : <strong>\u00ab\u00a0Change ton comportement et alors seulement tu retrouveras ton lien avec nous.\u00a0\u00bb<\/strong><\/p><p>Souvent, ce processus se passe sans que l\u2019on s\u2019en rende compte, mais pour un jeune enfant &#8211; qui a besoin de l&rsquo;amour de ses parents comme de l&rsquo;oxyg\u00e8ne -, cette exp\u00e9rience d\u2019abandon peut entra\u00eener des effets dommageables qui l\u2019accompagneront toute sa vie.<\/p><p>Ces enfants deviennent souvent soit <strong>des personnes qui cherchent \u00e0 plaire<\/strong> pour \u00eatre aim\u00e9es, m\u00eame si au fond elles ne sont pas s\u00fbres d\u2019agir correctement, soit des personnes agressives qui recourent \u00e0 l&rsquo;hostilit\u00e9 ou au repli sur soi pour \u00e9viter de ressentir \u00e0 nouveau la douleur de l&rsquo;abandon.<\/p><p>Maintenir une connexion int\u00e9rieure avec nos enfants &#8211; m\u00eame pendant leurs pires comportements et les moments les plus difficiles &#8211; devient particuli\u00e8rement crucial <strong>pendant l&rsquo;adolescence.<\/strong><\/p><p>\u00c0 cet \u00e2ge, l&rsquo;\u00e2me a d\u00e9j\u00e0 commenc\u00e9 son voyage ind\u00e9pendant, et donc il est tr\u00e8s probable que si les parents utilisent la manipulation pour corriger le comportement de leurs adolescents en se d\u00e9connectant d&rsquo;eux, les adolescents ne r\u00e9pondront pas par la soumission &#8211; comme les jeunes enfants &#8211; mais plut\u00f4t par la r\u00e9bellion et l&rsquo;escalade de leurs mauvaises actions.<\/p><p>Par cons\u00e9quent, nous devons toujours nous rappeler qu&rsquo;une <strong>connexion est ce qui permet finalement la correction, alors que demander la correction comme condition pour une connexion ne donnera aucun bon r\u00e9sultat.<\/strong><\/p><p><strong><u><strong><u>Quatri\u00e8me Commandement : jusqu&rsquo;\u00e0 la maturit\u00e9 sexuelle, le r\u00f4le principal des parents est de prot\u00e9ger la sant\u00e9 physique et le monde int\u00e9rieur de leur enfant<\/u><\/strong><\/u><\/strong><\/p><p>Le premier commandement nous a appris que nous ne devons jamais voir notre enfant comme un moyen pour r\u00e9aliser nos propres aspirations.<\/p><p>Un enfant n&rsquo;est pas un jouet, une possession ou un troph\u00e9e qu\u2019un parent peut exhiber parce qu\u2019il est fier de son apparence ou de ses r\u00e9alisations.<\/p><p>Cette conception destructrice conduit beaucoup de parents \u00e0 pousser leurs jeunes enfants vers des performances intellectuelles (ou, \u00e0 d\u00e9faut, \u00e0 les pousser vers l&rsquo;excellence sportive ou artistique). Pourtant, les Lois de la Cr\u00e9ation ne demandent qu&rsquo;une chose aux parents : prot\u00e9ger la sant\u00e9 physique et la paix int\u00e9rieure de leur enfant, en fournissant un <strong>terrain sain et fertile<\/strong> \u00e0 l&rsquo;esprit ind\u00e9pendant de l&rsquo;enfant, esprit qui \u00e9merge de son enveloppe protectrice \u00e0 la maturit\u00e9 sexuelle. <\/p><p>Un terrain sain et fertile signifie un foyer avec :<\/p><ul><li>de l\u2019harmonie entre les parents et les autres membres de la famille (les batailles entre les reines du m\u00e9lodrame et les commandants en chef effraient profond\u00e9ment les enfants, comme nous l&rsquo;avons vu dans l&rsquo;introduction du cours)<\/li><li>une nourriture saine<\/li><li>de l\u2019activit\u00e9 physique<\/li><li>des gestes affectueux<\/li><li>du temps pass\u00e9 dans la nature<\/li><li>un lien avec les animaux<\/li><li>de l\u2019activit\u00e9 artistique<\/li><\/ul><p>Souvenez-vous que les Lois de la Cr\u00e9ation sont aussi les Lois de la Nature, et \u00ab\u00a0Il y a un temps pour tout, et un moment pour chaque chose sous le ciel\u00a0\u00bb (Eccl\u00e9siaste 3:1).<\/p><p>Tout comme il ne faut pas cueillir et manger un fruit avant qu&rsquo;il ne soit m\u00fbr, nous ne devons pas pr\u00e9cipiter le processus naturel de d\u00e9veloppement de nos enfants.<\/p><p><strong><u>Cinqui\u00e8me Commandement : tout comme nous voulons voir nos enfants heureux, nos enfants, eux aussi, veulent nous voir heureux<\/u><\/strong><\/p><p>\u00catre heureux signifie bien plus que simplement survivre et fonctionner comme un \u00eatre humain. Par cons\u00e9quent, tout comme nous souffrons quand nous voyons nos enfants simplement survivre et fonctionner plut\u00f4t que de trouver de la joie dans l&rsquo;accomplissement de leur but, ils souffrent \u00e9galement quand ils nous voient uniquement survivre et fonctionner, sans trouver de joie dans l&rsquo;accomplissement de notre propre but. <\/p><p>Les parents qui croient que <strong>sacrifier leur vie pour leurs enfants fait d&rsquo;eux de bons parents<\/strong> se trompent. Vivre selon cette fausse conception les transforme en r\u00e9alit\u00e9 en personnes am\u00e8res qui se consid\u00e8rent comme des victimes. <\/p><p>L&rsquo;enfant peut alors se sentir coupable d&rsquo;avoir perturb\u00e9 la vie de ses parents et se bl\u00e2mer pour leur malheur. Cette perception \u2013 qui se transmet automatiquement \u00e0 l&rsquo;enfant \u2013 le transformera soit en un parent qui voit ses propres enfants comme un fardeau, soit le conduira \u00e0 renoncer compl\u00e8tement \u00e0 la parentalit\u00e9 dans sa qu\u00eate du bonheur. <\/p><p>En revanche, si les parents agissent selon la compr\u00e9hension qu&rsquo;<strong>\u00ab\u00a0un bon parent est un parent qui est spirituellement \u00e9veill\u00e9\u00a0\u00bb<\/strong>, leur enfant grandira en faisant l&rsquo;exp\u00e9rience de parents heureux et, avec le temps, deviendra lui-m\u00eame un parent heureux.<\/p><p><strong>Erich Fromm<\/strong>, dans son livre <strong>\u00ab\u00a0L&rsquo;Art d&rsquo;aimer\u00a0\u00bb<\/strong>, illustre magnifiquement cela \u00e0 travers la distinction qu\u2019il fait entre la plupart des m\u00e8res qui peuvent fournir \u00e0 leurs enfants du <strong>lait <\/strong>\u2013 symbolisant les besoins fondamentaux \u2013 et ces m\u00e8res qui peuvent aussi offrir du <strong>miel <\/strong>\u2013 symbolisant la douceur de la vie.<\/p><p><strong>Pourtant, le miel ne peut couler que des m\u00e8res qui ont trouv\u00e9 leur propre bonheur, et ainsi leur influence sur le bonheur de leurs enfants s&rsquo;\u00e9tend bien au-del\u00e0 de l&rsquo;enfance, et les accompagne tout au long de leur vie !<\/strong><\/p><p><strong>Car une bonne m\u00e8re est une m\u00e8re heureuse !<\/strong><\/p><p>Par cons\u00e9quent, si nous ne sommes pas heureux dans notre propre vie, nous laisserons \u00e0 nos enfants de lourdes <strong>\u00ab\u00a0dettes\u00a0\u00bb<\/strong> qu&rsquo;ils devront soit <strong>\u00ab\u00a0payer\u00a0\u00bb <\/strong>tout au long de leur vie sous forme de souffrance personnelle, soit <strong>\u00ab\u00a0r\u00e9gler\u00a0\u00bb<\/strong> \u00e0 travers un travail spirituel intensif. <\/p><p>Cependant, si nous prenons la responsabilit\u00e9 de notre d\u00e9veloppement spirituel, qui nous r\u00e9compense avec un bonheur inconditionnel \u2013 nous laissons \u00e0 nos enfants des <strong>\u00ab\u00a0h\u00e9ritages\u00a0\u00bb <\/strong>qui les guident naturellement vers le chemin d\u2019une vie heureuse.<\/p><p>\u00c0 ce stade, il est important de faire une pause et de se demander : Qu&rsquo;est-ce que le bonheur ? Et plus pr\u00e9cis\u00e9ment : Comment les parents d\u00e9finissent-ils le bonheur pour leurs enfants ? <\/p><p>Tous les parents dans le monde diraient que leur seul d\u00e9sir est de voir leurs enfants <strong>heureux<\/strong>, mais en fait, ce qu\u2019ils veulent dire, c\u2019est qu\u2019ils veulent voir leurs enfants <strong>r\u00e9ussir !<\/strong><\/p><p>Et puisque la plupart des gens sont programm\u00e9s pour <strong>lier la r\u00e9ussite au bonheur,<\/strong> tous les parents veulent essentiellement que leurs enfants r\u00e9ussissent \u2013 mais selon leurs propres crit\u00e8res !<\/p><p>Pour un parent, la r\u00e9ussite menant au bonheur signifie avoir une famille avec des enfants ; pour un autre, la r\u00e9ussite signifie accumuler des richesses mat\u00e9rielles, obtenir un dipl\u00f4me universitaire, ou m\u00eame appartenir \u00e0 un groupe religieux sp\u00e9cifique.<\/p><p>Cependant, dans tous les cas, la d\u00e9claration des parents \u00ab\u00a0Je veux juste que tu sois heureux\u00a0\u00bb \u2013 quand elle est li\u00e9e \u00e0 leur concept de r\u00e9ussite \u2013 cr\u00e9e une pression \u00e9norme sur l&rsquo;enfant et l&rsquo;\u00e9loigne en r\u00e9alit\u00e9 de la possibilit\u00e9 d&rsquo;\u00eatre heureux.<\/p><p>En fait, <strong>le bonheur est une exp\u00e9rience int\u00e9rieure intimement li\u00e9e \u00e0 l&rsquo;authenticit\u00e9.<\/strong><\/p><p>En d&rsquo;autres termes, le bonheur vient de notre capacit\u00e9 \u00e0 exprimer notre unique \u00ab\u00a0empreinte spirituelle\u00a0\u00bb dans le monde sans inhibitions ni masques (tout comme chaque personne a ses empreintes digitales uniques).<\/p><p>Par cons\u00e9quent, si nous voulons des enfants heureux, nous devons respecter le chemin unique de chaque enfant.<\/p><p>De plus, nous devons arr\u00eater d&rsquo;essayer d&rsquo;\u00e9lever nos enfants dans une <strong>\u00ab\u00a0bulle de <strong>bonheur<\/strong>\u00ab\u00a0<\/strong>, en les prot\u00e9geant de toute difficult\u00e9. Si nous sommes honn\u00eates avec nous-m\u00eames, nous savons que la vie n&rsquo;est pas faite que d&rsquo;arcs-en-ciel et de papillons, mais qu\u2019elle apporte aussi des d\u00e9fis et des luttes. C&rsquo;est pr\u00e9cis\u00e9ment en surmontant ces d\u00e9fis et en en tirant des le\u00e7ons que nous gagnons le v\u00e9ritable bonheur \u2013 le fruit de la maturit\u00e9 spirituelle.  <\/p><p>L&rsquo;approche traditionnelle de la parentalit\u00e9 \u2013 tout comme la m\u00e9decine conventionnelle \u2013 cherche \u00e0 supprimer la douleur et \u00e0 la faire taire avec des m\u00e9dicaments. Cependant, dans la parentalit\u00e9 spirituellement consciente, nous comprenons que faire face \u00e0 la douleur et aux d\u00e9fis aide nos enfants \u00e0 devenir qui ils sont vraiment destin\u00e9s \u00e0 \u00eatre. <\/p><p>Notre r\u00f4le en tant que parents est simplement de marcher \u00e0 leurs c\u00f4t\u00e9s sur leur chemin, en soutenant leur croissance et leur d\u00e9veloppement \u00e0 travers les diverses le\u00e7ons de la vie.<\/p><p><strong><u>Sixi\u00e8me Commandement : nos enfants prennent inconsciemment sur eux des difficult\u00e9s pour nous \u00e9veiller \u00e0 la n\u00e9cessit\u00e9 de nous corriger <\/u><\/strong><\/p><p>Comme indiqu\u00e9 dans le deuxi\u00e8me commandement, nous avons appris que l&rsquo;incarnation d&rsquo;une \u00e2me n&rsquo;est pas al\u00e9atoire, et de cela nous pouvons d\u00e9duire qu&rsquo;il existe un <strong>accord de confiance<\/strong> entre nos enfants et nous.<\/p><p>Qu&rsquo;est-ce qu&rsquo;un accord de confiance, et en quoi diff\u00e8re-t-il d&rsquo;une relation contractuelle ?<\/p><p>Contrairement \u00e0 un <strong>contrat<\/strong>, qui peut \u00eatre rompu ou r\u00e9sili\u00e9, de sorte que l&rsquo;une des parties peut partir si elle est insatisfaite, un <strong>accord de confiance<\/strong> est fondamentalement diff\u00e9rent.<\/p><p>Car l\u00e0 o\u00f9 existe un accord, en vertu de celui-ci, si une partie est malheureuse, l&rsquo;autre partie ne peut pas \u00eatre heureuse non plus, et elle ne peut pas simplement rompre ce lien et laisser l&rsquo;autre derri\u00e8re.<\/p><p><strong>Dans l&rsquo;accord de confiance entre l&rsquo;enfant et les parents, le message inconscient de l&rsquo;enfant est : \u00ab\u00a0Maman\/Papa, je ne peux pas avancer dans ma vie si vous n&rsquo;\u00eates pas l\u00e0 o\u00f9 vous devez \u00eatre, et pour cela, je vous servirai de miroir pour que vous puissiez vous \u00e9veiller, <\/strong><strong>m\u00eame si je dois en souffrir.\u201d<\/strong><\/p><p><strong><u>Et ainsi il arrive que les enfants, sans le savoir, prennent sur eux des maladies, aussi bien que des difficult\u00e9s sociales ou d\u2019apprentissage, dans le but de refl\u00e9ter les r\u00e9ajustements et changements que leurs parents doivent faire ! <\/u><\/strong><\/p><p>La plupart des parents sont inconscients de ceci et, de ce fait, ils essaient de r\u00e9soudre la probl\u00e9matique de leur enfant comme \u00e9tant son propre probl\u00e8me sans lien avec eux.<\/p><p>Les parents sont pr\u00eats \u00e0 payer d\u2019importantes sommes d\u2019argent pour l\u2019\u00e9ducation et la sant\u00e9 de leurs enfants ; cependant, ils ne comprennent pas qu\u2019ils ne peuvent pas se permettre d\u2019appr\u00e9hender tout probl\u00e8me auquel leurs enfants font face sans s\u2019examiner eux-m\u00eames \u00e9galement.<\/p><p>De plus, ils n\u2019entendent pas l\u2019appel de leurs enfants leur demandant de se d\u00e9velopper spirituellement eux-m\u00eames en tant qu\u2019\u00eatres humains et devenir ainsi de meilleurs parents.<\/p><p>Pour aider \u00e0 \u00e9claircir cela, voici un exercice appel\u00e9 <strong>l&rsquo;Exercice du Miroir<\/strong> que les parents peuvent faire en priv\u00e9 lorsque leurs enfants font face \u00e0 des probl\u00e8mes de sant\u00e9, sociaux ou scolaires.<\/p><p>Cet exercice n\u00e9cessite de l&rsquo;intuition (mais, si nous sommes arriv\u00e9s \u00e0 ce point du cours, notre conscience spirituelle devrait \u00eatre assez d\u00e9velopp\u00e9e pour que nous commencions \u00e0 \u00e9couter notre intuition).<\/p><p>Voici les \u00e9tapes de l&rsquo;exercice :<\/p><ol><li>Concentrez-vous sur <strong>un<\/strong> enfant qui \u00e9prouve une difficult\u00e9 sp\u00e9cifique (si d&rsquo;autres enfants dans la famille ont des difficult\u00e9s, effectuez cet exercice pour eux s\u00e9par\u00e9ment \u00e0 un autre moment).<\/li><li>Est-ce qu&rsquo;une partie de cette difficult\u00e9 est directement li\u00e9e \u00e0 vous ? Par exemple : votre enfant est constamment en col\u00e8re, refl\u00e9tant votre propre col\u00e8re constante. Ou est-ce indirectement li\u00e9 ? Par exemple : votre enfant souffre du rejet de ses amis \u00e0 l\u2019\u00e9cole parce que vous rejetez votre conjoint ou m\u00eame vos propres parents. (Rappelez-vous que l&rsquo;interpr\u00e9tation indirecte n\u00e9cessite toujours plus d&rsquo;intuition !)    <\/li><li>Voyez-vous une partie de cette difficult\u00e9 comme directement li\u00e9e \u00e0 votre conjoint ? Par exemple : l&rsquo;enfant et le p\u00e8re luttent tous les deux contre des probl\u00e8mes de poids. Ou indirectement ? Par exemple : l&rsquo;enfant affirme avoir des difficult\u00e9s \u00e0 avaler \u2013 bien que les m\u00e9decins ne trouvent aucun probl\u00e8me m\u00e9dical \u2013 refl\u00e9tant en r\u00e9alit\u00e9 la m\u00e8re qui a du mal \u00e0 exprimer ce qu&rsquo;elle traverse.   <\/li><li>Cette difficult\u00e9 est-elle directement ou indirectement li\u00e9e \u00e0 l&rsquo;espace entre vous et votre conjoint ? (Vous souvenez-vous de l&rsquo;espace contamin\u00e9 de la le\u00e7on num\u00e9ro neuf, que nos enfants \u00ab\u00a0photographient\u00a0\u00bb constamment ?) <\/li><li>Begin working on and correcting what your child is showing you.<\/li><li>Le matin au r\u00e9veil ou le soir avant de vous endormir, visualisez votre enfant, souriez-lui et remerciez-le de vous pousser \u00e0 vous d\u00e9velopper.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2882b33 elementor-widget elementor-widget-text-editor\" data-id=\"2882b33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Cet exercice peut produire de v\u00e9ritables miracles pour vos enfants !<\/strong> M\u00eame si votre intellect et vos \u00e9motions peuvent en douter.<\/p><p>Cependant, il est important que les parents ne se sentent pas coupables de ne pas \u00eatre parfaits et d&rsquo;amener leurs enfants \u00e0 refl\u00e9ter ces imperfections.<\/p><p>La conscience spirituelle dans la parentalit\u00e9 est un processus sans fin, et nos enfants ne demandent pas des parents <strong>parfaits,<\/strong> mais plut\u00f4t des parents qui sont dans un processus constant de <strong>d\u00e9veloppement <\/strong>personnel.<\/p><p><strong><u>Septi\u00e8me Commandement : nos enfants ne sont pas la chose la plus importante dans nos vies<\/u><\/strong><\/p><p>Demandez \u00e0 la plupart des gens qui ont \u00e9lev\u00e9 des enfants : \u00ab\u00a0Quelle est la chose la plus importante dans votre vie ?\u00a0\u00bb et ils r\u00e9pondront sans h\u00e9sitation : \u00ab\u00a0Mes enfants !\u00a0\u00bb<\/p><p>Cependant, comme nous l&rsquo;avons vu dans la le\u00e7on num\u00e9ro sept, placer nos enfants au sommet de nos priorit\u00e9s revient en fait \u00e0 de l&rsquo;idol\u00e2trie, ce qui s\u2019oppose au Premier Commandement : \u00ab\u00a0Tu n&rsquo;auras pas d&rsquo;autres dieux devant Moi.\u00a0\u00bb<\/p><p>Rappelons les principes cl\u00e9s que nous avons d\u00e9j\u00e0 appris : <strong>\u00ab\u00a0D&rsquo;autres dieux\u00a0\u00bb <\/strong>ne signifie pas seulement les idoles et les statues, mais fait en r\u00e9alit\u00e9 r\u00e9f\u00e9rence \u00e0 tout ce \u00e0 quoi une personne attribue la plus grande importance dans sa vie et dont elle tire sa force.<\/p><p>Pour l&rsquo;un, ce peut \u00eatre l&rsquo;argent ; pour un autre, le statut social ou professionnel ; pour un troisi\u00e8me, l&rsquo;apparence ext\u00e9rieure ; et pour un quatri\u00e8me, ses enfants.<\/p><p>Nous avons d\u00e9j\u00e0 dit que nos enfants ne sont pas venus pour r\u00e9aliser nos r\u00eaves ou combler notre vide int\u00e9rieur. Par cons\u00e9quent, si nous nous nourrissons d&rsquo;eux, et qu&rsquo;un jour ils veulent simplement suivre leur propre chemin, nous pourrions recourir \u00e0 la manipulation pour \u00e9viter de nous retrouver seuls, ou alors, tomber dans la d\u00e9pression du syndrome du nid vide. <\/p><p>Si nos enfants sont notre plus haute priorit\u00e9 et que &#8211; Dieu nous en pr\u00e9serve &#8211; quelque chose leur arrive, nous pourrions compl\u00e8tement nous effondrer et peut-\u00eatre m\u00eame \u00eatre incapables de les aider, car nous avons fait d&rsquo;eux notre source de force et de nourriture au lieu de nous nourrir de l&rsquo;unique Source et de recevoir la force directement de Dieu.<\/p><p> <\/p><p><strong><u>Huiti\u00e8me Commandement : nos enfants ont \u00e0 la fois le droit et l&rsquo;obligation d&rsquo;examiner tout ce qu&rsquo;ils ont re\u00e7u de nous<\/u><\/strong><\/p><p>La vision dominante de la parentalit\u00e9 pr\u00e9conise que les enfants devraient poursuivre les traditions pratiqu\u00e9es par leurs parents et les transmettre \u00e0 leurs propres enfants, une g\u00e9n\u00e9ration apr\u00e8s l\u2019autre.<\/p><p>Cependant, comme nous l&rsquo;avons d\u00e9j\u00e0 expliqu\u00e9, nos enfants ne sont pas nos possessions, et une fois qu&rsquo;ils sortent de l&rsquo;enfance, ils ont la libre volont\u00e9 et ils ont le <strong>devoir <\/strong>de l&rsquo;utiliser s&rsquo;ils souhaitent devenir des \u00eatres humains dans le sens le plus complet du terme.<\/p><p>Par cons\u00e9quent, nous devons accorder \u00e0 nos enfants le <strong>droit <\/strong>d&rsquo;examiner objectivement et ind\u00e9pendamment <strong>tout <\/strong>ce qu&rsquo;ils re\u00e7oivent de nous. Par exemple : l\u2019appartenance religieuse, l&rsquo;obligation du service militaire et la loyaut\u00e9 nationale, les attitudes envers la science et divers traitements m\u00e9dicaux, et plus encore. <\/p><p>Nous devons leur permettre de choisir ce qui est juste \u00e0 travers leur propre exp\u00e9rience personnelle et <strong>non <\/strong>par ob\u00e9issance aveugle.<\/p><p> <\/p><p><strong><u>Neuvi\u00e8me Commandement : une fois que nos enfants atteignent l&rsquo;\u00e2ge adulte, nous ne leur devons plus rien <\/u><\/strong><\/p><p><strong>Selon les Lois de la Cr\u00e9ation, une fois qu&rsquo;une personne a atteint l\u2019\u00e2ge adulte, elle doit voler de ses propres ailes, et ses parents ne lui doivent plus rien.<\/strong><\/p><p>Les parents ne sont pas oblig\u00e9s de laisser leurs enfants vivre chez eux pour toujours ni de continuer \u00e0 nettoyer leur chambre, \u00e0 laver leurs v\u00eatements et \u00e0 servir leurs repas.<\/p><p>Ils ne sont pas oblig\u00e9s de fournir une aide financi\u00e8re \u00e0 leurs enfants ou de leur acheter une maison quand ils se marient \u2013 et ils ne devraient pas se sentir coupables de ne pas \u00eatre de bons parents s&rsquo;ils ne peuvent pas faire ces choses-l\u00e0.<\/p><p>Ils ne sont pas oblig\u00e9s de garder les petits-enfants chaque fois que leurs enfants le demandent.<\/p><p>Et ils ne sont pas non plus oblig\u00e9s de laisser un h\u00e9ritage \u00e0 leurs enfants apr\u00e8s leur d\u00e9part.<\/p><p>Tout ce que les parents donnent \u00e0 leurs enfants adultes est un cadeau.<\/p><p>Cela am\u00e8nera les enfants \u00e0 ressentir de la <strong>gratitude<\/strong> pour ce qu&rsquo;ils re\u00e7oivent et les aidera \u00e0 devenir plus <strong>cr\u00e9atifs et ind\u00e9pendants.<\/strong><\/p><p>Pour les parents, cela leur permettra de poursuivre leur propre chemin de d\u00e9veloppement, qui ne devrait pas se terminer simplement parce qu&rsquo;ils ont choisi de devenir parents.<br><br><\/p><p><strong><u>Dixi\u00e8me Commandement : nous devons aspirer \u00e0 une connexion spirituelle avec nos enfants et prier pour l\u2019obtenir<\/u><\/strong><\/p><p><strong>La chose la plus merveilleuse qui puisse arriver \u00e0 des parents spirituellement conscients est que, un jour, leurs enfants soient li\u00e9s \u00e0 eux non seulement par des liens biologiques, mais aussi par des liens spirituels. <\/strong><\/p><p>C&rsquo;est un \u00e9tat o\u00f9 les parents et leurs enfants sont engag\u00e9s dans un processus profond de d\u00e9veloppement spirituel commun, et leurs rencontres et conversations touchent les couches les plus profondes de leur existence.<\/p><p>En conclusion : Les parents qui vivent selon les \u00ab\u00a0Dix Commandements de la Parentalit\u00e9 dans la Conscience Spirituelle\u00a0\u00bb sont des parents qui comprennent l&rsquo;immense importance de d\u00e9velopper leur propre conscience spirituelle.<\/p><p>Cela leur permet de devenir \u00ab\u00a0<strong>l&rsquo;\u00c9toile du Nord<\/strong>\u00a0\u00bb vers laquelle leurs enfants l\u00e8vent les yeux lorsqu&rsquo;ils s&rsquo;engagent sur leurs chemins, \u00e9toile qui illumine leurs parcours m\u00eame dans les nuits les plus sombres.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. <\/p>\n<p>Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l&rsquo;\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.  <\/p>\n","protected":false},"author":11,"featured_media":4839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[110],"tags":[],"class_list":["post-4837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l&#039;\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hagit Rabbi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Alma School for Humanity - Calling for the Human Spirit\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle - Alma School for Humanity\" \/>\n\t\t<meta property=\"og:description\" content=\"Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l&#039;\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2024\/07\/250X250-\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-\u05dc\u05d0\u05ea\u05e8\u05d9\u05dd.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2024\/07\/250X250-\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-\u05dc\u05d0\u05ea\u05e8\u05d9\u05dd.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-10T20:38:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-07T09:38:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle - Alma School for Humanity\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l&#039;\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2024\/07\/250X250-\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-\u05dc\u05d0\u05ea\u05e8\u05d9\u05dd.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#blogposting\",\"name\":\"Les dix commandements de la parentalit\\u00e9 dans la conscience spirituelle - Alma School for Humanity\",\"headline\":\"Les dix commandements de la parentalit\\u00e9 dans la conscience spirituelle\",\"author\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/author\\\/jaguitrabbigmail-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/almaschool.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/\\u05de\\u05d0\\u05de\\u05e8_\\u05d4\\u05d5\\u05e8\\u05d5\\u05ea-\\u05de\\u05d5\\u05d3\\u05e2\\u05ea.png\",\"width\":1920,\"height\":1280},\"datePublished\":\"2026-01-10T22:38:00+02:00\",\"dateModified\":\"2026-03-07T11:38:42+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#webpage\"},\"articleSection\":\"Articles, Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/category\\\/articles\\\/#listItem\",\"name\":\"Articles\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/category\\\/articles\\\/#listItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/category\\\/articles\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#listItem\",\"name\":\"Les dix commandements de la parentalit\\u00e9 dans la conscience spirituelle\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#listItem\",\"position\":3,\"name\":\"Les dix commandements de la parentalit\\u00e9 dans la conscience spirituelle\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/category\\\/articles\\\/#listItem\",\"name\":\"Articles\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/#organization\",\"name\":\"Alma School for Humanity\",\"description\":\"Calling for the Human Spirit\",\"url\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/almaschool.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/ASFH-\\u05e6\\u05d1\\u05e2\\u05d5\\u05e0\\u05d9.png\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#organizationLogo\",\"width\":5345,\"height\":1891},\"image\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/author\\\/jaguitrabbigmail-com\\\/#author\",\"url\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/author\\\/jaguitrabbigmail-com\\\/\",\"name\":\"Hagit Rabbi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#authorImage\",\"url\":\"https:\\\/\\\/almaschool.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/hagit-rabbi_avatar-1080x1080.png\",\"width\":96,\"height\":96,\"caption\":\"Hagit Rabbi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#webpage\",\"url\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/\",\"name\":\"Les dix commandements de la parentalit\\u00e9 dans la conscience spirituelle - Alma School for Humanity\",\"description\":\"Cet article pose les bases n\\u00e9cessaires \\u00e0 une parentalit\\u00e9 dans la conscience spirituelle. Cette compr\\u00e9hension peut aider \\u00e0 \\u00e9viter des erreurs critiques dans l'\\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\\u00e9rir, mais aussi de briser le cycle des sch\\u00e9mas dysfonctionnels transmis de g\\u00e9n\\u00e9ration en g\\u00e9n\\u00e9ration.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/author\\\/jaguitrabbigmail-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/author\\\/jaguitrabbigmail-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/almaschool.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/\\u05de\\u05d0\\u05de\\u05e8_\\u05d4\\u05d5\\u05e8\\u05d5\\u05ea-\\u05de\\u05d5\\u05d3\\u05e2\\u05ea.png\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#mainImage\",\"width\":1920,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\\\/#mainImage\"},\"datePublished\":\"2026-01-10T22:38:00+02:00\",\"dateModified\":\"2026-03-07T11:38:42+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/\",\"name\":\"Alma School for Humanity\",\"description\":\"Calling for the Human Spirit\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle - Alma School for Humanity","description":"Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l'\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.","canonical_url":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#blogposting","name":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle - Alma School for Humanity","headline":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle","author":{"@id":"https:\/\/almaschool.org\/fr\/author\/jaguitrabbigmail-com\/#author"},"publisher":{"@id":"https:\/\/almaschool.org\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/almaschool.org\/wp-content\/uploads\/2023\/03\/\u05de\u05d0\u05de\u05e8_\u05d4\u05d5\u05e8\u05d5\u05ea-\u05de\u05d5\u05d3\u05e2\u05ea.png","width":1920,"height":1280},"datePublished":"2026-01-10T22:38:00+02:00","dateModified":"2026-03-07T11:38:42+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#webpage"},"isPartOf":{"@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#webpage"},"articleSection":"Articles, Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/almaschool.org\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/almaschool.org\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/fr\/category\/articles\/#listItem","name":"Articles"}},{"@type":"ListItem","@id":"https:\/\/almaschool.org\/fr\/category\/articles\/#listItem","position":2,"name":"Articles","item":"https:\/\/almaschool.org\/fr\/category\/articles\/","nextItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#listItem","name":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle"},"previousItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#listItem","position":3,"name":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle","previousItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/fr\/category\/articles\/#listItem","name":"Articles"}}]},{"@type":"Organization","@id":"https:\/\/almaschool.org\/fr\/#organization","name":"Alma School for Humanity","description":"Calling for the Human Spirit","url":"https:\/\/almaschool.org\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/almaschool.org\/wp-content\/uploads\/2023\/04\/ASFH-\u05e6\u05d1\u05e2\u05d5\u05e0\u05d9.png","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#organizationLogo","width":5345,"height":1891},"image":{"@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/almaschool.org\/fr\/author\/jaguitrabbigmail-com\/#author","url":"https:\/\/almaschool.org\/fr\/author\/jaguitrabbigmail-com\/","name":"Hagit Rabbi","image":{"@type":"ImageObject","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#authorImage","url":"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/11\/hagit-rabbi_avatar-1080x1080.png","width":96,"height":96,"caption":"Hagit Rabbi"}},{"@type":"WebPage","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#webpage","url":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/","name":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle - Alma School for Humanity","description":"Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l'\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/almaschool.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#breadcrumblist"},"author":{"@id":"https:\/\/almaschool.org\/fr\/author\/jaguitrabbigmail-com\/#author"},"creator":{"@id":"https:\/\/almaschool.org\/fr\/author\/jaguitrabbigmail-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/almaschool.org\/wp-content\/uploads\/2023\/03\/\u05de\u05d0\u05de\u05e8_\u05d4\u05d5\u05e8\u05d5\u05ea-\u05de\u05d5\u05d3\u05e2\u05ea.png","@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#mainImage","width":1920,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/#mainImage"},"datePublished":"2026-01-10T22:38:00+02:00","dateModified":"2026-03-07T11:38:42+02:00"},{"@type":"WebSite","@id":"https:\/\/almaschool.org\/fr\/#website","url":"https:\/\/almaschool.org\/fr\/","name":"Alma School for Humanity","description":"Calling for the Human Spirit","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/almaschool.org\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Alma School for Humanity - Calling for the Human Spirit","og:type":"article","og:title":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle - Alma School for Humanity","og:description":"Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l'\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.","og:url":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/","og:image":"https:\/\/almaschool.org\/wp-content\/uploads\/2024\/07\/250X250-\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-\u05dc\u05d0\u05ea\u05e8\u05d9\u05dd.png","og:image:secure_url":"https:\/\/almaschool.org\/wp-content\/uploads\/2024\/07\/250X250-\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-\u05dc\u05d0\u05ea\u05e8\u05d9\u05dd.png","og:image:width":250,"og:image:height":250,"article:published_time":"2026-01-10T20:38:00+00:00","article:modified_time":"2026-03-07T09:38:42+00:00","twitter:card":"summary_large_image","twitter:title":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle - Alma School for Humanity","twitter:description":"Cet article pose les bases n\u00e9cessaires \u00e0 une parentalit\u00e9 dans la conscience spirituelle. Cette compr\u00e9hension peut aider \u00e0 \u00e9viter des erreurs critiques dans l'\u00e9ducation des jeunes enfants, fournir des outils pour corriger les erreurs que nous avons pu commettre avec nos enfants adultes et gu\u00e9rir les blessures transmises par nos propres parents. Cela nous permet non seulement de gu\u00e9rir, mais aussi de briser le cycle des sch\u00e9mas dysfonctionnels transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.","twitter:image":"https:\/\/almaschool.org\/wp-content\/uploads\/2024\/07\/250X250-\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-\u05dc\u05d0\u05ea\u05e8\u05d9\u05dd.png"},"aioseo_meta_data":{"post_id":"4837","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-01-29 19:54:34","updated":"2026-03-07 09:39:06","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/almaschool.org\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/almaschool.org\/fr\/category\/articles\/\" title=\"Articles\">Articles<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLes dix commandements de la parentalit\u00e9 dans la conscience spirituelle\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/almaschool.org\/fr\/"},{"label":"Articles","link":"https:\/\/almaschool.org\/fr\/category\/articles\/"},{"label":"Les dix commandements de la parentalit\u00e9 dans la conscience spirituelle","link":"https:\/\/almaschool.org\/fr\/nouvel-etre-humain-nouveau-monde-les-dix-commandements-de-la-parentalite-consciente\/"}],"_links":{"self":[{"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/posts\/4837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/comments?post=4837"}],"version-history":[{"count":13,"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/posts\/4837\/revisions"}],"predecessor-version":[{"id":29729,"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/posts\/4837\/revisions\/29729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/media\/4839"}],"wp:attachment":[{"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/media?parent=4837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/categories?post=4837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/almaschool.org\/fr\/wp-json\/wp\/v2\/tags?post=4837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}