{"id":13679,"date":"2025-07-21T22:18:55","date_gmt":"2025-07-21T19:18:55","guid":{"rendered":"https:\/\/almaschool.org\/luzifers-agenda\/"},"modified":"2026-06-03T13:22:11","modified_gmt":"2026-06-03T10:22:11","slug":"luzifers-agenda","status":"publish","type":"page","link":"https:\/\/almaschool.org\/de\/luzifers-agenda\/","title":{"rendered":"Luzifers Agenda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13679\" class=\"elementor elementor-13679 elementor-11232\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87ecb95 e-con-full e-flex e-con e-parent\" data-id=\"87ecb95\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-33ab8e1 e-con-full e-flex e-con e-child\" data-id=\"33ab8e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-facc507 elementor-widget elementor-widget-text-editor\" data-id=\"facc507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [\"bulletList\",null,\"listItem\",null]\"><span style=\"color: #f8c016;\">Luzifers <\/span>Agenda<br\/>Von Hagit Rabbi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7034838 elementor-widget elementor-widget-text-editor\" data-id=\"7034838\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\"><strong data-prosemirror-content-type=\"mark\" data-prosemirror-mark-name=\"strong\">Die Methoden der Versuchung<br\/>und Kontrolle \u00fcber die Menschheit enth\u00fcllen<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e53ac0a e-con-full e-flex e-con e-child\" data-id=\"e53ac0a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18aceed5 e-flex e-con-boxed e-con e-parent\" data-id=\"18aceed5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-85a0b34 e-con-full e-flex e-con e-child\" data-id=\"85a0b34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92c7d7a elementor-widget elementor-widget-text-editor\" data-id=\"92c7d7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">Den Vortrag ansehen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6daa62a e-con-full e-flex e-con e-child\" data-id=\"6daa62a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec2bdf9 elementor-widget elementor-widget-text-editor\" data-id=\"ec2bdf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">*Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6f1732 elementor-widget elementor-widget-html\" data-id=\"b6f1732\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"position:relative;padding-top:56.25%;\"><iframe src=\"https:\/\/iframe.mediadelivery.net\/embed\/141115\/7f1de138-7224-4ac5-8879-2caab467f40b?autoplay=false&loop=false&muted=false&preload=false&responsive=true\n%20\" loading=\"lazy\" style=\"border:0;position:absolute;top:0;height:100%;width:100%;\" allow=\"accelerometer;gyroscope;autoplay;encrypted-media;picture-in-picture;\" allowfullscreen=\"true\"><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d66cea elementor-widget elementor-widget-text-editor\" data-id=\"0d66cea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">Den Artikel anh\u00f6ren:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22c3140 e-con-full e-flex e-con e-child\" data-id=\"22c3140\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-534477e elementor-widget elementor-widget-html\" data-id=\"534477e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/open.spotify.com\/embed\/episode\/5moQDT6nShf86uSX12rL1f?utm_source=generator\" style=\"      width: min(100%, 600px);     height: 152px;     border: none;     border-radius: 8px;     display: block;     margin: 0 auto;    \" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\">\n<\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-premium-element-link=\"{&quot;type&quot;:&quot;url&quot;,&quot;link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/open.spotify.com\\\/episode\\\/5moQDT6nShf86uSX12rL1f?si=duK4ppQNT9OKDzPsJ_oiIg&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;href&quot;:&quot;https:\\\/\\\/open.spotify.com\\\/episode\\\/5moQDT6nShf86uSX12rL1f?si=duK4ppQNT9OKDzPsJ_oiIg&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-cc811a3 premium-wrapper-link-yes elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"cc811a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/open.spotify.com\/episode\/5moQDT6nShf86uSX12rL1f?si=duK4ppQNT9OKDzPsJ_oiIg\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/almaschool.org\/wp-content\/uploads\/elementor\/thumbs\/Spotify_Primary_Logo_RGB_Green-r80k0knz8rkvftnqlfonrlskh2kd38sdkome60vxbo.png\" title=\"Spotify_Primary_Logo_RGB_Green\" alt=\"Spotify_Primary_Logo_RGB_Green\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Anh\u00f6ren auf Spotify<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41465ad8 elementor-widget elementor-widget-n-accordion\" data-id=\"41465ad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1090\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1090\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1090\" class=\"elementor-element elementor-element-4036e012 e-con-full e-flex e-con e-child\" data-id=\"4036e012\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39303d34 elementor-widget elementor-widget-text-editor\" data-id=\"39303d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen und mehr\u2014ist <strong>unsere unmittelbare, typische emotionale Reaktion<\/strong>, nach jemandem zu suchen, den wir beschuldigen k\u00f6nnen.&nbsp;<\/p>\n<p>Um pr\u00e4zise zu sein, unser emotionales Bewusstsein erlebt die Realit\u00e4t als unertr\u00e4glich, und unser intellektuelles Bewusstsein versucht, die Schuldigen zu finden und sie \u201evor Gericht zu stellen.&#8220;<\/p>\n<p>Diese beiden Bewusstseine schaffen ein <strong>automatisches Reaktions<\/strong><strong>muster,<\/strong> das<strong> alle<\/strong> Menschen beherrscht\u2014unabh\u00e4ngig von Religion, Rasse oder Geschlecht\u2014nicht nur w\u00e4hrend globaler Krisen, sondern auch w\u00e4hrend pers\u00f6nlicher Krisen. (\u201eMeine Eltern sind <strong>schuld<\/strong>&#8222;, \u201eMein Ex ist <strong>schuld<\/strong>&#8222;, usw.) <\/p>\n<p>Warum ist das so?<\/p>\n<p>Weil Menschen w\u00e4hrend einer Krise <strong>Hilflosigkeit<\/strong> erfahren, was ein Zustand ist, den sie sehr schwer handhaben oder akzeptieren k\u00f6nnen. Aus diesem Grund versp\u00fcren sie einen enormen Drang, so schnell wie m\u00f6glich sowohl ihre \u00e4u\u00dfere als auch ihre innere Realit\u00e4t zu rekonstruieren, die zu zerfallen droht.<\/p>\n<p>Daher projizieren sie ihre Schwierigkeit auf einen externen Faktor, und dabei gewinnen sie scheinbar die Kontrolle \u00fcber ihr Leben zur\u00fcck:<\/p>\n<p>\u201eJetzt wei\u00df ich, <strong>wer<\/strong> oder <strong>was<\/strong> die Quelle des Problems ist, und ich werde <strong>es<\/strong> bek\u00e4mpfen, bis <strong>es eliminiert<\/strong> ist, und dann wird mein Problem gel\u00f6st sein!&#8220;<\/p>\n<p>Jedoch schafft das Beschuldigen eines externen Faktors f\u00fcr unsere Probleme nur <strong>eine Illusion von Sicherheit\u2014einen tr\u00fcgerischen Glauben, dass wir die Realit\u00e4t kontrollieren und dass wir die L\u00f6sung haben.<\/strong><\/p>\n<p>Aber da keine Krise durch das Beschuldigen externer Quellen gel\u00f6st werden kann, wird sie sich nur intensivieren und verschlimmern. Diejenigen, die weiterhin jemanden zum Beschuldigen suchen, riskieren, ihr wahres Bewusstsein zu verlieren und einen kompletten Zusammenbruch zu erleiden, da sie sich lediglich auf ihre Gef\u00fchle und ihren Verstand konzentrieren. <\/p>\n<p>Daher ist der Schl\u00fcssel, um sowohl aus dem \u00e4u\u00dferen als auch dem inneren Chaos herauszukommen, damit zu beginnen, die Wirklichkeit durch unser h\u00f6heres Bewusstsein zu betrachten, welches das <strong>spirituelle Bewusstsein<\/strong> ist. Dieses Bewusstsein stammt nicht aus dem Gehirn. Es vergeht nicht beim Tod, sondern ist ewig und verbindet sich durch <strong>den Solarplexus<\/strong> mit unserem physischen K\u00f6rper.  <\/p>\n<p>In dem Moment, in dem wir beginnen, unser spirituelles Bewusstsein zu erkennen und zu entwickeln, werden wir anfangen, v\u00f6llig andere Antworten auf die Fragen zu erhalten, die in uns \u00fcber den Zustand der Welt entstehen.<\/p>\n<p>Dann wird uns auch der Weg zu unserer eigenen Erl\u00f6sung und der Erl\u00f6sung der Menschheit offenbart werden.<\/p>\n<p>Der \u201ekurze&#8220; Weg zur Erl\u00f6sung\u2014zu dem uns die Emotionen und der Intellekt dr\u00e4ngen\u2014wird unsere Reise nur endlos verl\u00e4ngern.<\/p>\n<p>W\u00e4hrend die Entwicklung unseres spirituellen Bewusstseins anfangs wie ein l\u00e4ngerer Weg erscheinen mag, ist es tats\u00e4chlich der k\u00fcrzeste Weg von allen: der Weg zur\u00fcck nach Hause ins Paradies.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1091\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1091\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kapitel Eins: Luzifer\u2014Satan\u2014Die Schlange:<br \/>Die Versuchung und Versklavung an den Intellekt <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1091\" class=\"elementor-element elementor-element-0c18cab e-con-full e-flex e-con e-child\" data-id=\"0c18cab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2556dc1 elementor-widget elementor-widget-text-editor\" data-id=\"2556dc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Verst\u00e4ndnis der korrekten Beziehung zwischen Geist, Intellekt und Emotionen wird auch durch diesen Vortrag gewoben, dessen Thema lautet: <strong>Luzifer, <\/strong>oder unter seinem anderen Namen, <strong>Satan.<\/strong><\/p><p>Angesichts all des B\u00f6sen, das in der Welt offenbart wird, ist dies ein Thema, das viele Menschen stark besch\u00e4ftigt, da sie Luzifer-Satan als die Quelle allen \u00dcbels identifizieren.<\/p><p>Doch obwohl sie nicht wirklich identifizieren k\u00f6nnen, wer er ist, wirft allein der Gedanke an ihn sofort Fragen auf, die ernsthafte Suchende beunruhigen und Antworten fordern:<\/p><p>Ist es m\u00f6glich, dass die Welt zwei Autorit\u00e4ten hat\u2014einen guten Gott und einen b\u00f6sen Gott\u2014wie die <strong>dualistische religi\u00f6se Lehre <\/strong>lehrt?<\/p><p>Dieses Konzept selbst ist zutiefst entmutigend, denn tief im Inneren k\u00e4mpfen die Menschen damit, zu akzeptieren, dazu bestimmt zu sein, f\u00fcr immer gefangen in einem Krieg zwischen zwei G\u00f6ttern zu leben. (Und in der Realit\u00e4t scheint es, dass der \u201eb\u00f6se Gott&#8220; derjenige ist, der gewinnt&#8230;) <\/p><p>Und tats\u00e4chlich ist dieses Konzept falsch.<\/p><p>Aber wenn <strong>die monotheistische Sichtweise<\/strong>, die an einen Gott glaubt, der \u00fcber alles herrscht\u2014wie im Judentum, Christentum und Islam\u2014richtig ist, warum handelt Gott dann nicht, um all das B\u00f6se in der Welt zu stoppen? Warum stoppt Gott Satan nicht? Warum hat Er ihn \u00fcberhaupt in seiner Art zugelassen?  <\/p><p>Um mit der Beantwortung dieser Fragen zu beginnen, erinnern wir uns zun\u00e4chst an die Geschichte von <strong>Adam und Eva, die von der Schlange \u2013 die niemand anderes als Luzifer war \u2013 versucht wurden, vom Baum der Erkenntnis zu essen, und aus dem Garten Eden verbannt wurden.<\/strong><\/p><p>In unserer Serie:<strong> \u201eBiblische Geschichten als Codes zur Entschl\u00fcsselung der Realit\u00e4t der heutigen Welt&#8220; <\/strong>wird erkl\u00e4rt, dass diese Geschichte nichts anderes als ein Code ist, der die <strong>Erbs\u00fcnde <\/strong>beschreibt. Das hei\u00dft, die <strong>Trennung der Menschheit vom spirituellen Bewusstsein und ihre Versklavung an das intellektuelle Bewusstsein<\/strong>, das nichts jenseits von Zeit und Raum erfassen kann. <\/p><p>Was bedeutet das eigentlich? Es bedeutet, dass wir aus freiem Willen gew\u00e4hlt haben, unsere Existenz auf die materielle Welt zu beschr\u00e4nken. Mit anderen Worten, auf einen endlosen <strong>Hamsterrad-Wettlauf<\/strong>, in dem wir alle dem materiellen Erfolg nachjagen, aber niemals wahre Zufriedenheit erreichen.  <\/p><p>\u00dcbrigens stammt der Ursprung dieses Ausdrucks aus Experimenten, die an Ratten in Laboratorien durchgef\u00fchrt wurden, wo die Ratten auf einem Rad in einem K\u00e4fig liefen. Sie liefen kontinuierlich auf dem Rad und investierten gro\u00dfe Anstrengungen, machten aber in der Praxis keinen Fortschritt \u2013 sie blieben an derselben Stelle innerhalb des K\u00e4figs. <\/p><p><strong>Ja! Auch wir leben in einem K\u00e4fig. In einem Gef\u00e4ngnis. Innerhalb der Mauern der Matrix, die wir f\u00fcr uns selbst geschaffen haben!   <\/strong><\/p><p>Wir rennen herum, hetzen und eilen st\u00e4ndig, aber <strong>unser Geist<\/strong> ist gefangen und unterdr\u00fcckt und kommt nirgendwo hin.<\/p><p>So liegt es nicht in unserem Bewusstsein, dass diese Welt <strong>nur eine Schule f\u00fcr die Entwicklung unseres Geistes sein sollte, aber niemals unsere bleibende Heimat ist. Das Paradies ist unsere Heimat <\/strong>\u2013 zu der wir als bewusste Geister zur\u00fcckkehren sollten.<\/p><p>Wir haben vergessen, <strong>dass wir nicht die Eigent\u00fcmer sind, sondern nur G\u00e4ste, die den Planeten durch die Entwicklung unseres sch\u00f6pferischen Geistes erheben sollten.<\/strong><\/p><p>Jedoch haben wir uns nicht nur zu schlechten Verwaltern gemacht, sondern wir zerst\u00f6ren den Planeten Erde mit unseren eigenen H\u00e4nden! Das liegt daran, dass in dem Moment, in dem der Intellekt die Vorherrschaft \u00fcbernimmt und der Zweck unserer Existenz ausschlie\u00dflich irdisch und materiell wird \u2013 es damit kein Entkommen vor endlosen Kriegen gibt, deren einziges Ziel es ist, Macht und Kontrolle \u00fcber nat\u00fcrliche Ressourcen und \u00fcber andere Menschen zu erlangen. <\/p><p>\u00dcbrigens sind die gro\u00dfen Kriege nur der greifbarste Ausdruck all der kleinen Kriege, die <strong>wir alle<\/strong> f\u00fchren, um einen irdischen und materiellen Vorteil zu erlangen.<\/p><p>Wir haben das Privileg, G\u00e4ste auf diesem Planeten zu sein, schamlos missbraucht, und aus unvorstellbarer Eitelkeit und Einbildung ma\u00dfen wir uns an, Herrscher eines Planeten zu sein, der tats\u00e4chlich nur dem Allm\u00e4chtigen Sch\u00f6pfer geh\u00f6rt.<\/p><p>Heute ist nichts so, wie es urspr\u00fcnglich sein sollte.<\/p><p>Die Natur beh\u00e4lt ihre volle Sch\u00f6nheit nur an Orten, wo menschliche F\u00fc\u00dfe kaum gewandelt sind und keine h\u00e4sslichen, mechanischen, industriellen menschlichen Sch\u00f6pfungen errichtet wurden.<\/p><p>Aber selbst diese wenigen isolierten Orte sind nicht mehr so sch\u00f6n wie sie vor Millionen von Jahren waren, vor der Erbs\u00fcnde der Menschheit. Orte, die um ein Vielfaches sch\u00f6ner h\u00e4tten sein sollen, wenn der menschliche Geist seine F\u00e4higkeiten zum Ausdruck gebracht und mit den Elementarwesen zusammengearbeitet h\u00e4tte, deren Aufgabe es ist, die Natur zu h\u00fcten und zu erhalten. <\/p><p>Um es unverbl\u00fcmt zu sagen: <strong>Heute, in Abwesenheit spirituellen Bewusstseins, ist alles, was wir als sch\u00f6n wahrnehmen, nichts als die Spitze des Eisbergs wahrer Sch\u00f6nheit.<\/strong><\/p><p>Ich m\u00f6chte Sie f\u00fcr einige Augenblicke in die Welt vor der Erbs\u00fcnde mitnehmen (wie von <strong>Roselis von Sass<\/strong> in ihrem Buch <strong>\u201eDie Geburt der Menschheit&#8220;<\/strong> im Kapitel <strong>\u201eDer Verfall der Menschheit&#8220; <\/strong>beschrieben. Diese Beschreibung basiert auf den hellseherischen F\u00e4higkeiten der brasilianischen Autorin, \u201eDateien&#8220; \u00fcber die Menschheitsgeschichte \u201eherunterzuladen&#8220;): <\/p><p>Das Leben vor der Erbs\u00fcnde und dem S\u00fcndenfall war voller Freude f\u00fcr die Menschen. Die Erde war ein Spiegelbild des Paradieses, frei von allem B\u00f6sen. Es gab nichts, was Harmonie, Gl\u00fcck und Sch\u00f6nheit h\u00e4tte st\u00f6ren k\u00f6nnen\u2026. Gottes Wille allein herrschte \u00fcber die Welt\u2026. Nichts st\u00f6rte die Heilige Ordnung in der Sch\u00f6pfung.    <\/p><p>W\u00e4hrend dieser Zeit herrschte Frieden auf Erden. Frieden, Vertrauen und Gl\u00fcck\u2026. <\/p><p>Das goldene Zeitalter dauerte etwa eine Million achthunderttausend Jahre.<\/p><p>Jedoch begann der Mensch vor etwa einer Million zweihunderttausend Jahren zum ersten Mal, die vollkommene Harmonie und das Gleichgewicht in der Sch\u00f6pfung zu st\u00f6ren und handelte somit gegen den Willen Gottes, indem er sich willentlich seinem Intellekt unterwarf. Anstatt ihn lediglich als Instrument zu verwenden, erhob der Mensch ihn zum obersten Herrscher. <\/p><p>Dies geschah, als Luzifer und seine Hilfsarmee sich zuerst nur den Seelen der Frauen n\u00e4herten, da es einfacher war, Einfluss \u00fcber sie zu gewinnen als \u00fcber die Seelen der M\u00e4nner, und sie dazu verf\u00fchrten, sich vom Geist zu trennen.<\/p><p>Luzifer konnte jedoch die Menschen nur verlocken, hatte aber niemals die Macht, sie von ihrem Geist zu entfernen oder zu trennen und die wahren spirituellen F\u00fchrer der Menschheit zu distanzieren.<\/p><p>Dieselben F\u00fchrer sind mit dem Licht verbunden und wirken durch die Intuition, die vom Geist ausgeht, w\u00e4hrend die luziferischen Einfl\u00fcsse nur den Intellekt beeinflussen.<\/p><p>Mit der Vorherrschaft, die die Menschheit dem Intellekt zuschrieb, ver\u00e4nderten sich auch beide Teile des Gehirns, die urspr\u00fcnglich gleich gro\u00df waren. Der Teil, der dazu bestimmt war, spirituelle Schwingungen zu assimilieren, wurde vernachl\u00e4ssigt und unterdr\u00fcckt, bis er schlie\u00dflich v\u00f6llig verk\u00fcmmerte. Heute wird dieser Teil des Gehirns als Kleinhirn bezeichnet, auch bekannt als das \u201ekleine Gehirn&#8220;.  <\/p><p>Der andere Teil des Gehirns \u2013 genannt Gro\u00dfhirn, das gro\u00dfe Gehirn \u2013 erfuhr aufgrund seiner einseitigen Aktivit\u00e4t eine \u00fcbertriebene Entwicklung. So entstand ein Ungleichgewicht, eine Disharmonie, die sich mit der Zeit zu einem erblichen Defekt entwickelte. Die Erbs\u00fcnde.  <\/p><p>Diese Transformation war der Beginn allen \u00dcbels auf der Erde&#8230;<\/p><p>Der Planet Erde wurde immer dunkler und die Menschen entfernten sich mehr und mehr von Gott und begannen stattdessen, Luzifers Prinzipien anzubeten. (Dies durch verschiedene Anbetungsrituale \u2013 wie die Anbetung von Baal und Aschera \u2013 die sexuelle Ekstase und Selbstverst\u00fcmmelung beinhalteten und durch die die Kraft des menschlichen Geistes auf die fortgesetzte Aufrechterhaltung von Satans Herrschaft \u00fcber die Menschheit gerichtet wurde.) <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1092\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1092\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kapitel Zwei: Der gefallene Engel <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1092\" class=\"elementor-element elementor-element-09348b2 e-con-full e-flex e-con e-child\" data-id=\"09348b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f654370 elementor-widget elementor-widget-text-editor\" data-id=\"f654370\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nun stellt sich die Frage: Wer ist Luzifer \u00fcberhaupt, und warum erlaubte Gott ihm, uns zu verf\u00fchren?<\/p><p>Luzifer war tats\u00e4chlich ein <strong>Erzengel <\/strong>und die Bedeutung seines Namens ist: <strong>\u201eLichttr\u00e4ger&#8220; <\/strong>(Wie erw\u00e4hnt, ist sein Name auf Hebr\u00e4isch <strong>\u201eSatan&#8220;, was \u201eWidersacher oder Gegner&#8220; bedeutet <\/strong>\u2013 und wir werden bald sehen, wem und was er genau entgegenstand.)<\/p><p>Er war weder monstr\u00f6s noch h\u00e4sslich, wie viele sich vorstellen. Im Gegenteil, von allen Erzengeln \u2013 deren Ursprung in der G\u00f6ttlichen Sph\u00e4re liegt \u2013 war er der sch\u00f6nste und strahlendste. <\/p><p><strong>Urspr\u00fcnglich wurde er in die materielle Welt gesandt, um den Menschen bei ihrer Entwicklung zu helfen: ihnen das Werkzeug des Intellekts zu geben, damit sie die F\u00e4higkeiten ihres Geistes vollst\u00e4ndig auch im irdischen ausdr\u00fccken konnten.<\/strong><\/p><p>Mit anderen Worten, der Intellekt selbst ist keine schlechte Sache, solange er nur <strong>als Werkzeug<\/strong> dient. (Zum Beispiel kann jede wahrhaft gro\u00dfe k\u00fcnstlerische Sch\u00f6pfung\u2014die ihre Inspiration vom Geist erh\u00e4lt\u2014nicht ohne die Hilfe des Intellekts ausgedr\u00fcckt werden, weil sie in Worte, in Kl\u00e4nge oder durch Pinselstriche umgesetzt werden muss) <\/p><p>Und tats\u00e4chlich ging anfangs alles ordnungsgem\u00e4\u00df vonstatten.<\/p><p>Luzifer brachte den Menschen sein Licht und half ihnen, weiser und geschickter zu werden, und dadurch auch gl\u00fccklicher in ihrem Leben auf der Erde.<\/p><p>Aber dann <strong>begann Luzifer seinen eigenen Eigenwillen zu entwickeln, der sich Gottes Willen widersetzte (Satan=Widersacher) <\/strong>(und wir werden bald <strong>unseren eigenen Eigenwillen<\/strong> n\u00e4her erl\u00e4utern\u2014den Luzifer uns zu entwickeln inspirierte\u2014und auf den wir so stolz sind, ohne zu erkennen, wohin er uns f\u00fchrt oder wer dahinter steht).<\/p><p><strong>Stolz <\/strong>entstand in Luzifer \u00fcber das Licht, das er gebracht hatte, und Eigenwille erwachte in ihm, die Menschen zu versuchen, das Licht des Intellekts dem Licht des Geistes vorzuziehen.<\/p><p><strong>Anfangs schien es nicht so, als w\u00fcrde er rebellieren und Gottes Willen missachten, sondern vielmehr, dass er glaubte, es einfach besser als Gott zu wissen, was im Stoffe richtig war: <\/strong>\u201eJa, er vermeinte, der Intellekt ist besser als der Geist!&#8220;<\/p><p>\u00dcbrigens, selbst als die Israeliten w\u00e4hrend ihrer Wanderung in der W\u00fcste die Statue des <strong>Goldenen Kalbes<\/strong> erschufen, geschah dies nicht aus dem Wunsch heraus, Gott zu verraten, sondern es entsprang dem Gedanken, sie h\u00e4tten eine <strong>bessere Vorstellung<\/strong> davon, wie man Gott anbeten sollte, als das, was Moses gelehrt hatte.<\/p><p><strong>Judas Iskariot <\/strong>wollte anfangs auch nicht Jesus verraten, sondern dachte einfach,<strong> er w\u00fcsste besser <\/strong>als Jesus, was Jesus&#8216; Mission sein sollte.<\/p><p>Er strebte danach, Jesus zu einem politischen F\u00fchrer zu machen, w\u00e4hrend Jesus <strong>nur<\/strong> spirituelle Erl\u00f6sung bringen sollte.<\/p><p>Als sein Plan abgelehnt wurde, verwandelte sich Judas Iskariots Liebe zu Jesus in Hass und er verriet ihn.<\/p><p>Aber kehren wir zu Luzifer zur\u00fcck.<\/p><p>Allm\u00e4hlich begann Luzifer, sich selbst als Gott wahrzunehmen und entwickelte<strong> Sturheit <\/strong>bez\u00fcglich seines Weges als dem einzig richtigen.<\/p><p>So veranlasste er, w\u00e4hrend er die Menschen dazu <strong>verf\u00fchrte<\/strong>, Macht und materiellen Reichtum anzustreben, sie dazu, seinen Willen zu tun.<\/p><p>Durch den Missbrauch der ihm gew\u00e4hrten Macht f\u00fchrte er zum ersten Mal <strong>das Prinzip der Versuchung des Verstandes<\/strong> anstelle <strong>des Prinzips der G\u00f6ttlichen Liebe <\/strong>ein, welches auf spirituellen Aufstieg abzielt.<\/p><p>Luzifer weigerte sich, <strong>geduldig<\/strong> auf die allm\u00e4hliche Reifung und St\u00e4rkung der Menschheit zu warten. Er weigerte sich, der liebevolle G\u00e4rtner zu sein, der er h\u00e4tte sein sollen\u2014ein G\u00e4rtner, der sich um die ihm anvertrauten Pflanzen k\u00fcmmert, sie unterst\u00fctzt und pflegt. <\/p><p>Und dann begann er, <strong>intensive, grenzenlose Verachtung <\/strong>f\u00fcr die schwachen Gesch\u00f6pfe zu entwickeln, die so leicht in die Falle fielen, die er f\u00fcr sie aufgestellt hatte, und er begann, ihre Vernichtung zu begehren.<\/p><p>Au\u00dferdem empfand er auch gro\u00dfe Verachtung f\u00fcr die Niedertracht, Korruption und Grausamkeit, die von den Opfern gezeigt wurde, die auf sein Prinzip hereinfielen. Denn er hatte nur das falsche Prinzip eingef\u00fchrt\u2014die Bevorzugung des Verstandes\u2014aber es waren die Menschen selbst, die <strong>allein <\/strong>dieses Prinzip nutzten, um solche grausamen Abscheulichkeiten zu erschaffen. <\/p><p>Dadurch spornten sie Luzifer nur noch mehr dazu an, sie als Gesch\u00f6pfe zu betrachten, die nichts anderes als die Vernichtung verdienen.<\/p><p>Dann begann Luzifer, zus\u00e4tzlich zur Sturheit, auch <strong>die Entschlossenheit zu entwickeln, Gott zu beweisen,<\/strong> dass die Menschen einer f\u00fcrsorglichen Liebe und Barmherzigkeit unw\u00fcrdig sind.<\/p><p>Um sein Prinzip umzusetzen, musste Luzifer <strong>seine Hilfstruppen<\/strong> nutzen, eine Armee von Dienern, die tats\u00e4chlich <strong>das Dunkel<\/strong> erschuf.<\/p><p>Diese Hilfstruppen, Luzifers Armeen, bestehen aus verschiedenen Wesenheiten\u2014die sich w\u00e4hrend seines Abstiegs von der G\u00f6ttlichen Sph\u00e4re zur materiellen Welt mit seiner Macht verbanden\u2014sowie aus Menschengeistern auf der Erde, die sich daf\u00fcr entschieden, seine Diener unter der Menschheit zu werden.<\/p><p>Mit anderen Worten, jene, die weiterhin das falsche Prinzip verbreiten und die Mehrheit der Menschheit in ihrem Netz fangen.<\/p><p>Diesen Dienern gew\u00e4hrte Luzifer enorme Macht und gro\u00dfen Reichtum, und sie kr\u00f6nten ihn im Gegenzug offiziell zu ihrem Anf\u00fchrer.<\/p><p>Diese Menschen der Finsternis sind zum Dunkel gewandelte Geistwesen und wandeln heute noch unter den Reihen der Menschen auf dem Planeten Erde, w\u00e4hrend sie sich selbst als erleuchtet und illuminiert wahrnehmen, entsprechend ihrer Vorliebe f\u00fcr den Intellekt! (Die <strong>Illuminati<\/strong> bedeutet zum Beispiel auf Lateinisch \u201edie Erleuchteten&#8220; oder \u201edie Aufgekl\u00e4rten&#8220;). <\/p><p>Sie f\u00fchren die Menschheit\u2014die dem Intellekt versklavt ist\u2014in blutige Kriege, weil sie, genau wie Luzifer, die Menschheit f\u00fcr unw\u00fcrdig halten.<\/p><p>Deshalb kann nirgendwo auf der Erde wahrer Frieden und Gl\u00fcck mehr gefunden werden.<\/p><p>Nur sehr wenige unter der Menschheit bleiben \u00fcbrig, deren spirituelles Bewusstsein noch stark genug ist und sich nicht leicht Versuchungen hingibt.<\/p><p>Hier stellt sich jedoch deutlich die Frage: Warum hat Gott, der allm\u00e4chtig ist, den gefallenen Engel nicht aus der Welt verbannt, nachdem Luzifer seine wahre Mission verraten hatte, denn dann w\u00e4ren wir vor seiner Versuchung verschont geblieben?<\/p><p>Um diese Frage zu beantworten, m\u00fcssen wir mehrere Dinge verstehen:<\/p><ol><li><strong>Der Planet Erde ist ein Ort, wo Entwicklung durch freien Willen geschieht.<\/strong><\/li><\/ol><p>Der menschliche Geist kann sich <strong>nur <\/strong>durch <strong>freien Willen<\/strong> entwickeln.<\/p><p>Deshalb wurde auch Luzifer freier Wille gew\u00e4hrt, als er in die materielle Welt hinabstieg, und er w\u00e4hlte letztendlich seinen eigenen Eigenwillen anstatt Gottes Willen. (Dies ist in der G\u00f6ttlichen Sph\u00e4re, die der Ursprung aller Engel ist, absolut unm\u00f6glich. Denn dort, in Gottes N\u00e4he, kann sich Eigenwille nicht entwickeln, da alles in Gottes Willen schwingt.) <\/p><p>Ebenso konnte Luzifer die Menschen durchaus dazu verleiten, einen f\u00fcr sie gef\u00e4hrlichen Weg zu gehen, aber er konnte den Menschen in <strong>keiner<\/strong> Weise etwas <strong>aufzwingen<\/strong>\u2014es sei denn, sie selbst entschieden sich daf\u00fcr, aus eigenem freien Willen!<\/p><ol start=\"2\"><li><strong>Die gesamte Sch\u00f6pfung funktioniert nach vollkommenen Gesetzen\u2014den Sch\u00f6pfungsgesetzen\u2014und sie dr\u00fccken Gottes Willen aus.<\/strong><\/li><\/ol><p>Daher war es unm\u00f6glich, Luzifer aus der Sch\u00f6pfung zu \u201eentlassen&#8220;, weil Gott <strong>nicht <\/strong>pers\u00f6nlich in die Sch\u00f6pfung eingreift\u2014wie man uns im Kindergarten beigebracht hat\u2014sondern dies h\u00e4tte nur durch die Sch\u00f6pfungsgesetze geschehen k\u00f6nnen. (Luzifer aber <strong>wurde inzwischen tats\u00e4chlich nach den Gesetzen neutralisiert,<\/strong> und darauf werden wir sp\u00e4ter in der Vorlesung eingehen.) <\/p><ol start=\"3\"><li><strong>Die materielle Welt ist das Wirkungsfeld der Erdenmenschheit, da nur der Geist in einem menschlichen K\u00f6rper inkarnieren und in der materiellen Welt wirken kann. Im Gegensatz dazu ist Luzifers Ursprung zwar g\u00f6ttlich, aber er inkarnierte nicht in einen K\u00f6rper, er konnte nur von seiner Ebene aus manipulieren, und daher ist es h\u00f6chst besch\u00e4mend, dass die Menschheit sich von einer Kraft verleiten und verf\u00fchren l\u00e4sst, die irdisch schw\u00e4cher ist als ihre eigenen M\u00f6glichkeiten in der materiellen Welt. <\/strong><\/li><\/ol><p>Daher, wenn das Paar in der Geschichte vom Garten Eden standhaft geblieben w\u00e4re, h\u00e4tte Luzifer sie nicht verleiten k\u00f6nnen. Standhaft bleiben bedeutet freudigen Gehorsam gegen\u00fcber Gottes Willen\u2014der dem Menschenpaar wohlbekannt war und in den einfachen Naturgesetzen zu finden ist, die ein und dasselbe mit den Sch\u00f6pfungsgesetzen sind. <\/p><p>Zum Beispiel: <strong>Nach den Sch\u00f6pfungsgesetzen k\u00f6nnen wir nur wahrhaft empfangen, indem wir geben.<\/strong> Als die Menschen jedoch von Luzifer verleitet wurden, verletzten sie dieses Gesetz und wurden zu Gesch\u00f6pfen, die nur empfangen wollen, ohne etwas im Gegenzug zu geben.<\/p><p>Tats\u00e4chlich kann der Mensch nur durch Gehorsam gegen\u00fcber Gottes Willen\u2014welcher die Sch\u00f6pfungsgesetze sind\u2014wahrhaft zum \u201eHerrscher der Sch\u00f6pfung&#8220; werden, und wenn er sich nicht in Gegensatz zu diesen Urgesetzen stellt, werden sie ihm dienen und automatisch zu seinem Nutzen wirken!<\/p><p>Daher ist nicht nur der Geist jeder Person, die nach oben strebt, das hei\u00dft, Licht erstrebend, vollkommen imstande, mit Luzifer und seinen Dienern fertig zu werden, sondern er w\u00e4re sogar bei weitem in der Lage, sie an Macht zu \u00fcbertreffen!<\/p><p><strong>Ein einziger, aufrichtiger und echter Wille <\/strong>aus dem Geistigen Bewusstsein gen\u00fcgt, um Luzifers gesamte Armee wirkungslos werden zu lassen.<\/p><p>Auf Erden aber blieben nur wenige \u00fcbrig, die darum k\u00e4mpften, auf Gottes Weg zu wandeln, vielmehr h\u00f6rten sie auf dunkle Einfl\u00fcsterungen, die ihren Verstand und ihren Gef\u00fchlen als eintr\u00e4glich und gut dargestellt wurden.<\/p><p>Um dieser wenigen willen sandte Gott immer wieder m\u00e4chtige Helfer, die den Menschen den <strong>Pfad der Wahrheit <\/strong>aufs Neue zeigten.<\/p><p>Es waren die Wegbereiter, <strong>Tr\u00e4ger der Wahrheit\u2014Moses, Lao-Tse, Zoroaster, Buddha<\/strong> und andere\u2014die gesandt wurden, um jedem Volk die Wahrheit zu bringen und unter den Menschen jenes Volkes lebten und wirkten.<\/p><p>Diese Wegbereiter lie\u00dfen das Licht der Wahrheit machtvoll auf der Erde erstrahlen, und wenn die Menschen das Licht aufnahmen, begannen sie ein neues Leben zu f\u00fchren, und Friede und Ruhe herrschten unter ihnen.<\/p><p>Doch in dem Augenblick, als die Tr\u00e4ger der Wahrheit den Planeten Erde verlie\u00dfen, wurde alles, was sie gesagt hatten, schnell vergessen oder zu einer Religion entstellt.<\/p><p>Propheten und Prophetinnen wurden gesandt, um vor der zunehmenden Verschlechterung der Menschheit zu warnen und dem menschlichen Geist zu helfen, sich aus dem luziferischen Gef\u00e4ngnis zu befreien. Doch gr\u00f6\u00dftenteils verfolgte, folterte und ermordete die Menschheit diese wahren Boten des Lichts sogar. <\/p><p>Platon beschrieb dies gut<strong> im H\u00f6hlengleichnis<\/strong> (das er nach der Hinrichtung seines Lehrers<strong> Sokrates<\/strong> schrieb):<\/p><p>Vom Augenblick ihrer Geburt an sitzen die Menschen gefesselt in einer dunklen H\u00f6hle und sind gewiss, dass diese H\u00f6hle die ganze Welt ist!<\/p><p>Wenn es einem der Gefangenen gelingt\u2014durch enormen Aufwand\u2014sich von den Ketten zu befreien und die H\u00f6hle zu verlassen, entdeckt er die wirkliche Welt, welche die geistige Welt ist, und die Sonne, die die Wahrheit symbolisiert.<\/p><p>Jedoch, als er zur\u00fcckkehrt, um es den anderen zu erz\u00e4hlen, um sie zu befreien, glauben sie ihm nicht und wollen ihn sogar ermorden!<\/p><p>So sank die Erde allm\u00e4hlich, und die Trennung vom Licht und von Gott wurde zu einer realen Gefahr.<\/p><p>Luzifer feierte seinen Sieg, denn die materielle Welt war zu seinem K\u00f6nigreich geworden!<\/p><p>Deshalb wurde vor etwa zweitausend Jahren <strong>Jesus, der Sohn Gottes,<\/strong> zur Rettung der Menschheit in die Welt gesandt.<\/p><p>Ihm wurde g\u00f6ttliche Macht verliehen, die niemals zuvor das Antlitz der Erde erreicht hatte!<\/p><p>Er brachte <strong>die Wahrheit,<\/strong> die allein den Geist befreien kann!<\/p><p>Die Wahrheit versucht nicht, noch schmeichelt sie dem Ego des Menschen. (Das Ego besteht aus dem Intellekt und den Emotionen.) <\/p><p>Die Wahrheit ist scharf wie ein Rasiermesser, denn sie kommt, um den Geist von allen Ketten zu befreien, mit denen er Luzifer erlaubte, ihn zu binden, und um dem Geist zu helfen, Kraft zu sammeln und ein f\u00fcr alle Mal den Kopf der Schlange abzuschlagen!<\/p><p>Im Gegensatz dazu ist derjenige, der die Wahrheit nicht erkennt, zum geistigen Tod verurteilt.<\/p><p>Daher w\u00e4re seine einzige Chance der Rettung durch extremes Leiden, das die Macht des Intellekts und der Emotionen schw\u00e4chen k\u00f6nnte und dann dem sterbenden Geist erlauben k\u00f6nnte zu erwachen.<\/p><p>Jesus wurde gesandt, um einzelnen Menschen zu erm\u00f6glichen, das geistige Bewusstsein und die Verbindung mit dem Licht aufrechtzuerhalten, um das absolute Versinken der Erde bis zu den Tagen des J\u00fcngsten Gerichts zu verhindern.<\/p><p>Ohne diese Hilfe w\u00e4re die Erde mit Sicherheit versunken und kein menschlicher Geist h\u00e4tte mehr gerettet werden k\u00f6nnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1093\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1093\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kapitel Drei: Gottes Wille gegen Eigenwille <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1093\" class=\"elementor-element elementor-element-abcf0f5 e-con-full e-flex e-con e-child\" data-id=\"abcf0f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-681d699 elementor-widget elementor-widget-text-editor\" data-id=\"681d699\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die meisten Menschen denken, dass sie, wenn sie \u201egute Menschen&#8220; sind, zum Lager des Lichts geh\u00f6ren und \u00fcberhaupt nichts mit dem Dunkel und Luzifer zu tun haben.<\/p><p>Aber sie erkennen nicht, dass sie bereits in Luzifers Versuchungsfalle getappt sind, wenn sie ihren Lebenszweck nur im Irdischen suchen und als \u201egut &#8220; definieren, wenn sie in Frieden umgeben von ihrer Familie leben und das Hier und Jetzt auf Erden genie\u00dfen!<\/p><p>Das liegt daran, dass sie nicht begreifen k\u00f6nnen, <strong>dass alles, was den Geist nicht zum Licht f\u00fchrt, bereits zum Dunkel geh\u00f6rt!<\/strong><\/p><p>Die meisten Menschen tr\u00e4umen und sehnen sich nach dem Tag, an dem \u201edie B\u00f6sen&#8220; aus der Sch\u00f6pfung entfernt werden und sie, \u201edie Guten&#8220;, dann frei atmen und in Ruhe und Frieden leben k\u00f6nnen.<\/p><p>Wenn Gott jedoch die Sch\u00f6pfung wirklich unmittelbar von allen Dienern Luzifers reinigen w\u00fcrde \u2013 wie sie tr\u00e4umen und hoffen \u2013, w\u00fcrde die \u00fcberwiegende Mehrheit der Menschheit in dieser Reinigung hinweggefegt werden, denn der weitaus gr\u00f6\u00dfte Teil hat sich durch ihren eigenen freien Willen an Luzifers Prinzip (Werkzeug) gebunden: Den Intellekt!<\/p><p>Mit anderen Worten: Wenn das intellektuelle Bewusstsein einer Person dominiert \u2013 das bedeutet, er nimmt die Realit\u00e4t nur durch seine f\u00fcnf Sinne wahr \u2013, ist er tats\u00e4chlich an Zeit und Raum gebunden und hat sich damit Luzifers Prinzip untergeordnet! (Auch wenn er Verfechter der sozialen Gerechtigkeit ist und Tag und Nacht Beitr\u00e4ge gegen die Illuminaten und Luzifer schreibt.) <\/p><p><strong>Der Antichrist<\/strong>\u2014den so viele in der Welt zu identifizieren versuchen\u2014ist nicht <strong>Napoleon, Hitler oder Putin,<\/strong> sondern Luzifer selbst, der durch den menschlichen Intellekt wirkt.<\/p><p>Da jedoch niemand vermutete, dass der Antichrist hinter dem Intellekt lauert, konnte Luzifer seinen b\u00f6sartigen Einfluss viel leichter in jeden Bereich der menschlichen Gesellschaft ausbreiten!<\/p><p>Luzifer trennte uns von Gott und der Ewigkeit und davon, nach<strong> Gottes Willen <\/strong>zu leben\u2014welcher die Gesetze der Sch\u00f6pfung sind\u2014und ersetzte sie durch seine \u201e<strong>eigenwilligen <\/strong>Gesetze, die an die Erde oder zumindest an Raum und Zeit gebunden sind&#8220;.<\/p><p>Anstatt dass sich unser Geist durch<strong> freudigen Dienst<\/strong> in der Sch\u00f6pfung entwickelt, in dem ihm alles, was er f\u00fcr seine Reise in der materiellen Welt braucht, gegeben wird, bleiben wir bei der Verstandes- und der Gef\u00fchlsherrschaft (Ego) stecken und jagen in st\u00e4ndiger Sorge dem Wohlstand oder irgendeinem Status hinterher.<\/p><p>Luzifer trennte die Menschheit von allem geistigen Begreifen, das jenseits der materiellen Welt existiert! Vom wahren Leben! Von einer Verbindung mit dem Geist, die zur N\u00e4he zu Gott f\u00fchrt!  <\/p><p>Anstatt reichlich Kraft vom Sch\u00f6pfer zu empfangen, denn wahrlich, <strong>\u201eer ist es, der dir Kraft gibt, Reichtum zu erlangen&#8220; (5. Mose 8:18)<\/strong>\u2014hat Luzifer durch den Intellekt uns den Glauben auferlegt, der zum Motto wurde: <strong>\u201eMeine Kraft und die St\u00e4rke meiner Hand haben mir diesen Reichtum verschafft&#8220; (5. Mose 8:17).<\/strong><\/p><p>(Nebenbei bemerkt ist dies genau der Grund, warum <strong>freie Energie<\/strong> f\u00fcr uns nicht verf\u00fcgbar bleibt\u2014obwohl diese M\u00f6glichkeit in der Sch\u00f6pfung durchaus existiert\u2014und uns zwingt, uns um teure und umweltverschmutzende Energiequellen zu k\u00e4mpfen und zu streiten.)<\/p><p>Luzifer will, dass wir denken, wir w\u00fcrden alles <strong>mit der eigenen Kraft <\/strong>des Intellekts schaffen&#8220; und <strong>\u201edarum nur auf uns selbst vertrauen&#8220; <\/strong>und hat uns darauf konditioniert zu meinen, dass das Empfangen der Kraft durch Gott eine religi\u00f6se Illusion ist; er aber wiederrum beherrscht den Menschen \u00fcber den Verstand.<\/p><p>Dies ist jedoch ein h\u00f6chst raffiniertes luziferisches Argument, denn Luzifer infiltrierte die Religionen mit seinem Prinzip und verursachte all die Verzerrungen in ihnen\u2014Verzerrungen und Widerspr\u00fcche, die Millionen von aufrichtigen Suchenden dazu bringen, sich als Atheisten zu definieren, da das von den verschiedenen Religionen pr\u00e4sentierte Gottesbild Ablehnung und Misstrauen in ihnen hervorruft.<\/p><p>Aber selbst wenn sich eine Person von den Religionen abwendet und durch psychologische Therapie oder die verschiedenen New-Age-Methoden Linderung von seinem Schmerz sucht, kann er Luzifers Agenten nicht entkommen, die ihn von allen Seiten umgeben und st\u00e4ndig die Wichtigkeit des Selbstwertgef\u00fchles <strong>(Ego) <\/strong>betonen und vorantreiben, jedoch ohne den Geist zu ber\u00fccksichtigen.<\/p><p>Ihre Taktik, die nun \u00fcberall weit verbreitet ist, f\u00f6rdert<strong> Selbstwertgef\u00fchl <\/strong>und <strong>Selbstwichtigkeit <\/strong>bis zu einem fast obsessiven Grad. Dies st\u00e4rkt unweigerlich das Ego und trennt uns vom Bewusstsein des Geistes. Zum Beispiel funktioniert diese Taktik, indem sie Konzepte vom Licht verzerrt:  <\/p><p><strong>Vertrauen in Gott<\/strong> bietet Schutz vor vielem B\u00f6sen, und ohne dieses Vertrauen sind wir Schaden ausgesetzt\u2014sogar Schaden, der nicht das Ergebnis von Karma ist. Dieses Vertrauen wurde durch <strong>\u201eSelbstwertgef\u00fchl&#8220;<\/strong> ersetzt, einen zerbrechlichen Ersatz, der verschwinden kann, sobald die Pl\u00e4ne unseres \u201eSelbst&#8220; nicht wie geplant funktionieren. <\/p><p><strong>Liebe zu Gott und Liebe zu unserem N\u00e4chsten<\/strong>\u2014die uns direkt zu einem Leben kontinuierlicher, allgegenw\u00e4rtiger Liebe f\u00fchren w\u00fcrde\u2014wurden durch <strong>\u201eSelbstliebe&#8220; <\/strong>ersetzt, die die Liebe auf wenige Stunden \u201eQualit\u00e4tszeit mit mir selbst&#8220; begrenzt und letztendlich zu Einsamkeit und zur Unf\u00e4higkeit wahrhaft zu lieben f\u00fchrt.<\/p><p><strong>Das Gotterkennen &#8211; was uns alles gegeben h\u00e4tte &#8211; hat sich zur blo\u00dfen Kenntnis \u00fcber Gott gewandelt,<\/strong> es wurde durch ein Verlangen nach Selbstanerkennung ersetzt: \u201eIch muss gesehen und gesch\u00e4tzt werden!&#8220; Dieses Verlangen treibt Menschen dazu, wie Bettler st\u00e4ndig nach Brocken der Anerkennung f\u00fcr ihr \u201eSelbst&#8220; zu suchen, weil sie sich sonst wertlos f\u00fchlen. <\/p><p><strong>Die Heilung durch Gottes Kraft<\/strong>\u2014die Kraft, mit der Jesus Wunder vollbringen und Menschen heilen konnte, die als unheilbar galten und die unter Traumata und S\u00fcchten litten\u2014wurde durch \u201eSelbstsuggestion&#8220; ersetzt. Aber wie arm und begrenzt ist dieses Selbst&#8230;denn es wirkt lediglich, wenn \u00fcberhaupt, wie ein kurzfristiges Schmerzmittel oder eine Bet\u00e4ubung, aber niemals als echte Heilung. <\/p><p>So trennte uns Luzifer <strong>von der Quelle des Lebens <\/strong>und sperrte uns in einen K\u00e4fig, wo wir nicht nur um rationiertes Wasser betteln m\u00fcssen, sondern wo wir sogar Wasser mit s\u00fcchtig machenden &#8211; scheinbar heilenden &#8211; Drogen versetzt bevorzugen!<\/p><p>Das ist genau wie Studien zeigen, dass M\u00e4use und Ratten Wasser mit Kokain (oder anderen Drogen) gegen\u00fcber normalem Wasser bevorzugen, wenn sie in Labork\u00e4fige eingesperrt sind.<\/p><p>Warum aber ist das so?<\/p><p>Weil unser Geist, wenn wir von der Quelle abgeschnitten sind, niemals wirklich gl\u00fccklich mit dem \u201eSelbst&#8220; sein kann, sondern lediglich das Ego in einer Selbstzufriedenheit schwelgen wird. Darum f\u00fchlen wir uns oft, besonders in schweren Zeiten, als w\u00e4re uns die Energie ausgegangen; unsere Batterie ist leer, aber wir haben keine M\u00f6glichkeit, sie nachhaltig aufzuladen, weil sie sich ohne Verbindung zum Licht nicht auf Dauer aufl\u00e4dt. <\/p><p>Dann kommt die Schlange und bietet uns <strong>Kraftersatz <\/strong>an, der uns letztendlich nur schw\u00e4cht und uns in einen <strong>Teufelskreis<\/strong> zwingt und gefangen h\u00e4lt, aus dem dann schwer zu entkommen ist. Das wohl heute offensichtlichste Beispiel ist der &#8211; aus geistiger Sicht &#8211; unsachgem\u00e4\u00dfe Gebrauch von <strong>Drogen<\/strong>, aber auch <strong>psychiatrischen Medikamenten<\/strong>). <\/p><p>Wir wandern also weiter durch die Welt, \u00e4ngstlich und allein und erst wenn die Dinge immer schlimmer werden, dann m\u00fcssen wir erkennen, dass all diese verf\u00fchrerischen Ersatzmittel, die uns angeboten wurden, nie wirklich funktioniert haben. <\/p><p>Wir sp\u00fcren dann, wir sind kraftlos, weil wir in keiner Verbindung zu Gott stehen.<\/p><p>Also suchen wir nach <strong>romantischen Partnern<\/strong> und erwarten von der Beziehung, dass <strong>sie<\/strong> uns Kraft gibt. Aber wir vergessen, dass diese Partner genauso wenig \u00fcber Gottes Kraft verf\u00fcgen, denn sie sind ebenso unwissende Menschen und darum genauso machtlos wie wir. Der Versuch, Kraft aus ihnen zu \u201esch\u00f6pfen&#8220;, f\u00fchrt also nur irgendwann zur bitteren Entt\u00e4uschung innerhalb der Beziehungen.  <\/p><p>(Im Gegensatz dazu w\u00fcrden beide Partner, wenn sie Gott an die erste Stelle setzen \u2013 wie es <strong>das Erste Gebot<\/strong> lehrt \u2013 mit der Quelle der Kraft verbunden sein. Sie w\u00fcrden die Beziehung nicht aus gegenseitiger <strong>Bed\u00fcrftigkeit <\/strong>eingehen, sondern aus dem Drang heraus, ihre Kraft zu vereinen und sie gemeinsam zu vervielfachen.) <\/p><p>Aber die meisten Paare kennen dieses Geheimnis nicht. Das Eheleben gibt ihnen darum nicht nur keine Energie, sondern ersch\u00f6pft sie sogar, also suchen sie wieder anderswo nach Kraft&#8230; <\/p><p>Einige von ihnen sind ernsthafte Suchende, die beginnen, nach Kraft an Orten und in Lehren zu suchen, die eine Alternative bieten, die auf den ersten Blick sehr verlockend erscheint.<\/p><p>Aber wir wissen bereits, wer sich hinter dieser Versuchung verbirgt&#8230;<\/p><p>Tats\u00e4chlich wei\u00df das Dunkel, dass die Menschen nach dem Licht suchen, also bietet es Ersatz und lockt sie da hinein. Es sind <strong>die esoterischen Ebenen<\/strong>, und dort werden <strong>die Bedeutungen der wahren lichten Werte in das Ego und die Gef\u00fchle anlockende Werte verzerrt und verdreht.<\/strong><\/p><p>Der Vers aus <strong>Jesaja 5:20<\/strong> beschreibt perfekt die Situation, in der wir uns heute befinden: <strong>\u201eWehe denen, die B\u00f6ses gut und Gutes b\u00f6se nennen, die aus Dunkel Licht und aus Licht Dunkel machen, die aus bitter s\u00fc\u00df und aus s\u00fc\u00df bitter machen.&#8220;<\/strong><\/p><p>Die esoterischen Ebenen &#8211; wozu auch die New-Age-Bewegung geh\u00f6rt \u2013 haben eine \u00e4hnliche Wirkung wie Platons H\u00f6hle, da sie den Weg einer Person zum wahren spirituellen Aufstieg blockieren. <strong>Die Person lebt in der Illusion, dass sie bereits die h\u00f6chste Ebene erreicht hat, die sie von der Matrix befreit, aber sie wei\u00df nicht, dass sie nun in der Matrix der astralen und \u00e4therischen materiellen Welt gefangen ist.<\/strong><\/p><p>Durch die Geschichte hindurch haben alle<strong> falschen Propheten und falschen Lehrer <\/strong>ihre Lehren aus den verschiedenen Schichten dieser esoterischen Ebenen gesch\u00f6pft.<\/p><p>Ein klares Beispiel f\u00fcr die Verzerrung des Konzepts der G\u00f6ttlichkeit ist die Erkl\u00e4rung, die f\u00fcr Gottes Existenz innerhalb dieser esoterischen Gew\u00f6lbe gegeben wird.<\/p><p>Was wird dort gerne gelehrt? <strong>Dass Gott in uns selbst ist!<\/strong><\/p><p>Wenn es nicht so traurig w\u00e4re \u2013 da dies nur beweist, wie gro\u00df die menschliche Arroganz und Torheit sind \u2013 w\u00e4re es l\u00e4cherlich, denn schon alleine die Entfernung zwischen der spirituellen Sph\u00e4re und Gott kann niemals vom menschlichen Geist erfasst werden, da er nur bis zu seinem eigenen Ursprung wahrnehmen kann und nicht weiter!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1094\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1094\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kapitel Vier: Die Bindung Luzifers <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1094\" class=\"elementor-element elementor-element-37fb7c3 e-con-full e-flex e-con e-child\" data-id=\"37fb7c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26c754a elementor-widget elementor-widget-text-editor\" data-id=\"26c754a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Luzifer schlug uns eine Wunde, wodurch wir den Glauben an Gottes Allmacht und die wahre Liebe verloren, und diese offene Wunde blutet weiter und verursacht Leiden.<\/p><p>Unser Geist muss den Kreislauf vollenden und nach Hause zur\u00fcckkehren \u2013 in unsere Heimat, ins Paradies \u2013 \u00e4hnlich dem Blutkreislauf im physischen K\u00f6rper.<\/p><p>Da wir jedoch von der geistigen Sph\u00e4re abgeschnitten wurden, werden wir immer schw\u00e4cher, wie bei einer st\u00e4ndigen Blutung aus einer offenen Wunde.<\/p><p>Wenn jedoch die Not am gr\u00f6\u00dften ist, ist Gottes Hilfe uns n\u00e4her denn je!<\/p><p>Gerade in den Tagen des J\u00fcngsten Gerichts wurde uns die gr\u00f6\u00dfte Hilfe gesandt, um das Schlie\u00dfen dieser offenen Wunde zu erm\u00f6glichen!<\/p><p><strong>Die Offenbarung <\/strong>ist ein Buch, das\u2014in Bildern und Metaphern\u2014die Ereignisse der Tage des J\u00fcngsten Gerichts beschreibt, das hei\u00dft die Zeit, in der wir uns jetzt befinden.<\/p><p>An vielen Stellen\u2014wie in Kapitel 13, Verse 2-4\u2014gibt es eine Beschreibung des<strong> Tieres<\/strong>, dem der <strong>Drache <\/strong>seine Macht gibt.<\/p><p>Wer aber sind der Drache und das Tier?<\/p><p>\u201eDer Drache&#8220; ist Satan, Luzifer, die alte Schlange, und \u201edas Tier&#8220; ist der Verstand.<\/p><p>Warum ein Tier? Weil das Gehirn\u2014welches die physische Wohnst\u00e4tte des Verstandes ist\u2014tats\u00e4chlich als ein Tier beschrieben werden kann, da aus geistiger Sicht das menschliche Gehirn aus dem tierischen K\u00f6rper hervorgegangen ist (<strong>Darwin <\/strong>hatte hierin recht). Es sollte jedoch nur der Diener des Geistes sein, nicht der Herr.  <\/p><p>Das Buch der Offenbarung sagt uns auch, dass der Drache und das Tier den H\u00f6hepunkt ihrer Macht kurz vor dem Endgericht der Endzeit erreichen werden, aber dann wird Luzifer f\u00fcr tausend Jahre gebunden werden:<\/p><p>\u201eDa sah ich einen Engel vom Himmel herabkommen, der den Schl\u00fcssel zum Abgrund und eine gro\u00dfe Kette in seiner Hand hatte. Er ergriff den Drachen, jene alte Schlange, die der Teufel und Satan ist, und band ihn f\u00fcr tausend Jahre; und er warf ihn in den Abgrund und verschloss ihn und setzte ein Siegel auf ihn, damit er die V\u00f6lker nicht mehr verf\u00fchre, bis die tausend Jahre vollendet w\u00e4ren&#8230;&#8220; (Kapitel 20, Verse 1-3)<\/p><p>Es ist unm\u00f6glich f\u00fcr jeden menschlichen Geist, einen Kampf gegen Luzifer selbst zu f\u00fchren, aus dem einfachen Grund, dass Menschen aufgrund des Unterschieds in der Natur und dem Ursprung ihrer Art sein Reich nicht erreichen k\u00f6nnen.<\/p><p>Ein menschlicher Geist kann nur mit jenen in Kontakt kommen, die durch das falsche Prinzip gefallen sind, weil sie grunds\u00e4tzlich derselben Art angeh\u00f6ren.<\/p><p>Luzifers Ursprung erforderte, dass nur jemand, der vom gleichen oder von einem h\u00f6heren Ursprung ist, sich ihm n\u00e4hern und ihm pers\u00f6nlich gegen\u00fcbertreten konnte.<\/p><p>Daher konnte ihn niemand anderes bezwingen au\u00dfer<strong> einem G\u00f6ttlichen Gesandten<\/strong>, bewaffnet mit einem vollkommenen, unersch\u00fctterlichen Vertrauen in die Quelle aller Macht\u2014in Gott selbst!<\/p><p><strong>Diese Mission wurde dem prophezeiten Menschensohn \u00fcbertragen, und tats\u00e4chlich erf\u00fcllte Er sie im vergangenen Jahrhundert, indem Er Luzifer f\u00fcr tausend Jahre band!<\/strong><\/p><p><strong>Die Wunde konnte nun geheilt werden! Der Pfad zu den Lichten H\u00f6hen, zum Paradies, war wieder vor uns ge\u00f6ffnet, im Licht der Wahrheit! <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1095\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1095\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kapitel F\u00fcnf: Der Kollektive Intellekt und das Kollektive Emotionale Zentrum <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1095\" class=\"elementor-element elementor-element-299ec65 e-con-full e-flex e-con e-child\" data-id=\"299ec65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9641a2 elementor-widget elementor-widget-text-editor\" data-id=\"a9641a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da Luzifer gebunden und seiner Macht beraubt wurde, blieb das Dunkel ohne Kraftquelle und war daher dazu bestimmt, von selbst auszutrocknen.<\/p><p>Denken Sie an eine Topfpflanze.<\/p><p>Wie lange kann sie ohne Wasser \u00fcberleben? Die widerstandsf\u00e4higste Pflanze k\u00f6nnte ein Jahr \u00fcberleben und dann verwelkt sie. <\/p><p><strong>Und genau das h\u00e4tte mit dem Dunkel geschehen sollen!<\/strong><\/p><p>So wurde nach dem Willen des Lichts der menschliche Geist befreit und h\u00e4tte dem rechten Pfad der spirituellen Entwicklung und des Aufstiegs folgen k\u00f6nnen.<\/p><p><strong>Aber dann geschah etwas, was selbst das Licht nicht h\u00e4tte vorhersehen k\u00f6nnen.<\/strong><\/p><p><strong>Luzifer wurde gebunden, aber die Menschheit entschied sich, auch ohne ihn auf dem von ihm gesetzten Pfad weiterzugehen und wurde zum Kraftlieferanten f\u00fcr das Dunkel!<\/strong><\/p><p><strong>Luzifer hasste die Menschheit und seine geplante Agenda war es, ihre Vernichtung herbeizuf\u00fchren, w\u00e4hrend das Dunkel die Menschheit nur versklaven will, weil es ihre Energie braucht.<\/strong><\/p><p>Stellen Sie sich vor, Sie stehen unter dem Missbrauch eines Psychopathen und jemand schafft es, Sie vollst\u00e4ndig von seiner Kontrolle zu befreien; aber dann w\u00e4hlen Sie wieder die Gesellschaft eines anderen Psychopathen\u2014und diesmal einen viel schlimmeren!<\/p><p><strong>Was also geschah mit der Menschheit?<\/strong><\/p><p>Der Intellekt blieb nicht mehr nur<strong> im vorderen Gehirn des Menschen, sondern schuf ein kollektives Zentrum, das sich in der astralen Welt befindet.<\/strong><\/p><p>Wir k\u00f6nnen diesen <strong>kollektiven Intellekt <\/strong>mit einem massiven Server vergleichen, mit dem alle spirituell schwachen Menschen\u2014was der Gro\u00dfteil der Menschheit ist\u2014st\u00e4ndig verbunden sind, entweder indem sie Inhalte von ihm \u201eherunterladen&#8220; oder Inhalte zu ihm \u201ehochladen&#8220;.<\/p><p>(\u00dcbrigens sind diejenigen, die ihn am meisten n\u00e4hren und zu ihm hochladen, die Berufenen, also die, die die spirituelle F\u00fchrung bilden sollten und die mehr als jede andere Person Zugang zu der aus Gott flie\u00dfenden Kraft haben. Wenn wir nun sagen, dass ein gew\u00f6hnlicher Mensch, der kein spirituelles Bewusstsein besitzt, das Dunkel mit einem Wassertropfen n\u00e4hrt, dann n\u00e4hren die Berufenen es mit einem ganzen Ozean. <strong>Deshalb hat die Menschheit keine Chance, wenn die spirituelle F\u00fchrung der Welt nicht endlich zu ihrer Rolle erwacht und stattdessen weiterhin den kollektiven Intellekt mit der G\u00f6ttlichen Kraft n\u00e4hrt!<\/strong><\/p><p>Sie sind diejenigen, die berufen sind, das Dunkel auf Erden durch ihre Gedanken zu reinigen, und nur dann kann der Rest der Menschheit\u2014in dem der Funke des Geistes noch nicht erloschen ist\u2014gerettet werden.)<\/p><p>Das dunkle Gedankenzentrum n\u00e4hrt das Dunkel kontinuierlich und ist tats\u00e4chlich das, was heute die F\u00e4den zieht und die gesamte politische F\u00fchrung der Welt\u2014ohne dass sie sich dessen bewusst ist\u2014dazu bringt, so zu handeln, wie sie es tut.<\/p><p>Im LASST MEINEN GEIST FREI! Kurs\u2014dem Grundkurs unserer Schule zur Entwicklung des spirituellen Bewusstseins\u2014definierten wir den Intellekt als einen schlauen<strong> \u201eAnwalt&#8220;<\/strong>. Tats\u00e4chlich kann der kollektive Intellekt als<strong> \u201edas Justizministerium&#8220; <\/strong>definiert werden.<\/p><p><strong>Ein \u201eMinisterium&#8220;, das wahnsinnige Gesetze erl\u00e4sst\u2014die wir alle t\u00e4glich erleben\u2014und die Gesetze der Sch\u00f6pfung ignoriert, welche die einzigen Gesetze sind, die wir je haben sollten.<\/strong><\/p><p>Aber da das Dunkel mit Luzifers Fesselung von seiner Energiequelle abgeschnitten wurde, suchte es nun eine andere Energiequelle, und so wurde ein weiteres astrales Zentrum geschaffen: das <strong>kollektive emotionale Zentrum<\/strong>. Und wenn sich der Intellekt im Stirnhirn befindet und sich von dort mit dem kollektiven Intellekt verbindet, dann befinden sich die Emotionen in der <strong>Zirbeldr\u00fcse<\/strong> und verbinden sich von dort mit dem kollektiven emotionalen Zentrum.<\/p><p>W\u00e4hrenddessen ist der Ort der Verbindungsquelle des Geistes zum physischen K\u00f6rper der <strong>Solarplexus,<\/strong> von dem aus Eindr\u00fccke das Kleinhirn erreichen sollten, das kleine Gehirn, welches eigentlich das Hinterhirn ist. W\u00e4hrend die Zirbeldr\u00fcse die Br\u00fccke zum Stirnhirn sein sollte. <\/p><p><strong>Daher ist es nicht \u00fcberraschend, dass alle falschen Propheten und falschen Lehrer\u2014vielleicht unbewusst\u2014die Zirbeldr\u00fcse preisen und die Menschen davon \u00fcberzeugen, dass ihre Emotionen sie zu den edelsten Gesch\u00f6pfen in der Sch\u00f6pfung machen.<\/strong><\/p><p>Und die Politiker? Auch sie erkennen, dass Emotionen der \u201eTreibstoff&#8220; f\u00fcr das kollektive emotionale Zentrum des Dunkels sind, also sorgen sie daf\u00fcr, dass die Weltb\u00fcrger in st\u00e4ndiger emotionaler Aufruhr gehalten werden: <strong>Wut, Eifersucht, Hass, Angst, Sorge usw.<\/strong> <\/p><p>Der Geist hingegen wurde zum Schweigen gebracht und eingesperrt, und nur ein wahrer Prophet und ein wahrer Lehrer werden ihn aus seinem Gef\u00e4ngnis befreien und ihn wieder mit seiner Quelle verbinden k\u00f6nnen: der geistigen Sph\u00e4re, dem Paradies.<\/p><p>Als Luzifer aus seiner Gefangenschaft sah, wie die Menschheit weiterhin das Licht verr\u00e4t, sogar ohne ihn, konnte er nicht verstehen, warum<strong> das Licht den Menschen immer noch hilft, da sie zweifelsfrei bewiesen haben, dass seine Behauptung richtig war\u2014sie sind der Hilfe nicht w\u00fcrdig!<\/strong><\/p><p>Und tats\u00e4chlich, wenn wir die Menschheit betrachten, sehen wir, dass Luzifer recht hatte. Die Menschheit ist wahrhaftig der Hilfe nicht w\u00fcrdig, aber das Licht ist so barmherzig und gn\u00e4dig, dass es uns weiterhin Hilfe sendet, solange es auch nur wenige Individuen gibt, die das Licht suchen und sich danach sehnen. Luzifer brennt vor Hass in seinem Gef\u00e4ngnis, und obwohl in einem Vortrag f\u00fcr die Allgemeinheit wie diesem nicht erkl\u00e4rt werden kann, was das bedeutet, stellt Luzifer tats\u00e4chlich keine Bedrohung mehr f\u00fcr die Menschheit dar!  <\/p><p><strong>Die Bedrohung der Menschheit ist die Menschheit selbst, die das Dunkel geschaffen hat und weiterhin n\u00e4hrt und sich\u2014mit luziferischer Sturheit\u2014allen Boten widersetzt, die kommen, um ihr zu helfen.<\/strong><\/p><p><strong>Daher ist die Besiegung des Dunkels eigentlich sehr einfach:<\/strong><\/p><p><strong>Wir m\u00fcssen aufh\u00f6ren, es mit dem Intellekt und den Emotionen zu n\u00e4hren, das hei\u00dft mit dem Ego!<\/strong><\/p><p><strong>Und dann wird Frieden und Segen auf Erden sein.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1096\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1096\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kapitel Sechs: Die Endzeit und das Neue Zeitalter <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1096\" class=\"elementor-element elementor-element-167eb04 e-con-full e-flex e-con e-child\" data-id=\"167eb04\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f952797 elementor-widget elementor-widget-text-editor\" data-id=\"f952797\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Es ist wichtig, sich an die Definition des Dunkels zu erinnern, da diese der Schl\u00fcssel f\u00fcr das spirituelle Erwachen ist:<\/p><p class=\"p1\"><b>Alles, was den Geist nicht zum Licht hinf\u00fchrt, ist dunkel aber nicht unbedingt B\u00f6se, aber das B\u00f6se wird im Dunkel erschaffen!<\/b><\/p><p class=\"p1\">Daher ist die wahre Hilfe, die uns vom Licht <b>w\u00e4hrend der Tage des J\u00fcngsten Gerichts <\/b>zuteil wird, dazu bestimmt, die Befreiung des Geistes aus dem Dunkel zu bewirken (jedoch nicht das, was unserem Ego, also unserem Verstand und unseren Gef\u00fchlen, angenehm ist).<\/p><p class=\"p1\">Wir m\u00fcssen verstehen, dass wir an einer Krankheit leiden. Die Tatsache ist, dass die Menschheit krank ist, weil der Geist in ihr stirbt. <\/p><p class=\"p1\">Da das Dunkel die Menschheit als seine Kraftquelle braucht, will es diese Tatsache verzweifelt verbergen und bietet uns stattdessen Schmerzmittel an, um die Symptome zu bet\u00e4uben und h\u00e4lt uns in der illusorischen Matrixwelt des Einkaufens, Reisens, der Drogen und endlosen Ablenkungen gefangen.<\/p><p class=\"p1\"><b>Um die Menschheit jedoch im Dunkeln zu halten, ist seine st\u00e4rkste Strategie, die Bedeutung aller Konzepte zu verzerren, die vom Licht kamen, und dadurch alle zu verwirren.<\/b><\/p><p class=\"p1\">Nehmen wir den Ausdruck <b>&#8222;New Age&#8220; <\/b>als Beispiel.<\/p><p class=\"p1\">Der Begriff stammt urspr\u00fcnglich von der Idee einer &#8222;neuen \u00c4ra&#8220;, die einen Wandel im menschlichen Bewusstsein hin zu Spiritualit\u00e4t, Harmonie und Frieden einl\u00e4uten w\u00fcrde.<\/p><p class=\"p1\">Aber in Wirklichkeit hat das Dunkel das Konzept der<b> \u201eTage des J\u00fcngsten Gerichts&#8220; <\/b>und der<b> \u201eEndzeit&#8220; <\/b>der <b>Neuen \u00c4ra<\/b> gekapert\u2014welches dem Geist zugutekommen sollte\u2014und es dazu benutzt, die esoterische Kuppel aufzubauen und immer mehr Suchende dorthin zu locken. All dies geschieht, um haupts\u00e4chlich Harmonie und Frieden f\u00fcr die Emotionen zu versprechen (mit denen uns falsche Lehrer immer zu \u201eberuhigen&#8220; versuchen&#8230;). <\/p><p class=\"p1\">Tats\u00e4chlich hat das Dunkel sogar das Konzept der<b> \u201eSpiritualit\u00e4t&#8220; <\/b>gekapert und es mit drogengetr\u00e4nkten Partys in der Natur in Verbindung gebracht!<\/p><p class=\"p1\">Ein weiteres Beispiel: Hitler nahm das Konzept des <b>\u201eTausendj\u00e4hrigen Reiches&#8220;,<\/b> in dem das Licht auf der Erde herrschen wird, und verzerrte es zum<b> \u201etausendj\u00e4hrigen Reich&#8220;,<\/b> wo nach der Nazi-Vision Deutschland Europa und die Welt f\u00fcr tausend Jahre beherrschen w\u00fcrde.<\/p><p class=\"p1\">Er verzerrte auch die urspr\u00fcngliche und positive Bedeutung des Hakenkreuzes, \u00e4hnlich wie die Kirche das Kreuz der Wahrheit (das gleichlange Arme hat) in das Kreuz des Leidens verzerrte, an dem Jesus gekreuzigt wurde.<\/p><p class=\"p1\">Aber die gef\u00e4hrlichste Strategie des Dunkels ist die <b>Vermischung von Wahrheit mit L\u00fcgen.<\/b><b><\/b><\/p><p class=\"p1\">Der Geist erkennt die Wahrheit und beginnt dem Lehrer zu folgen, der eine L\u00f6sung anbietet, die dann tats\u00e4chlich eine L\u00fcge ist. Aber die Person bemerkt dies nicht und folgt diesem Lehrer weiterhin mit seinem Verstand und seinen Emotionen. <\/p><p class=\"p1\">Betrachten wir drei Beispiele, um diesen Punkt <b>aus verschiedenen Blickwinkeln zu veranschaulichen: das New Age-Paradigma, Religionen und den Humanismus.<\/b><\/p><ol class=\"ol1\"><li class=\"li1\"><b>New Age:<\/b><b> Osho<\/b> (der ber\u00fchmte indische Lehrer) spricht dar\u00fcber, wie die Institution der Ehe obsolet geworden ist\u2014was wahr ist. Aber das Heilmittel, das er anbietet\u2014<b>die offene Ehe<\/b>\u2014ist eine L\u00fcge und wird die Menschen von der Wahrheit wegf\u00fchren. <\/li><\/ol><p class=\"p1\">In dem Vortrag <b>\u201eDie Wahrheit \u00fcber freudvolle Monogamie&#8220;<\/b> erkl\u00e4re ich, was die steigenden Scheidungsraten verursacht und was die wahre L\u00f6sung f\u00fcr eine gl\u00fcckliche Ehe ist.<\/p><ol class=\"ol1\"><li class=\"li1\"><b>Religionen<\/b> liefern ein weiteres Beispiel. Das Dunkel hat gelernt, die Gesetze der Sch\u00f6pfung zu nutzen, daher missbrauchen religi\u00f6se F\u00fchrer aller Glaubensrichtungen das Gesetz von Ursache und Wirkung auf \u00e4hnliche Weise. Sie geben der Hingabe die Schuld am Leiden\u2014sei es mangelnde regelm\u00e4\u00dfige Teilnahme an Gottesdiensten, unzureichende finanzielle Unterst\u00fctzung oder Opfergaben, das Vers\u00e4umnis, religi\u00f6se Speisevorschriften zu befolgen, oder unsachgem\u00e4\u00dfe religi\u00f6se Ritualbeachtung oder -befolgung\u2014und verschreiben strengere Einhaltung ihrer menschengemachten Regeln als L\u00f6sung.  <\/li><\/ol><p class=\"p1\">Wenn wir jedoch dieses Argument am Beispiel j\u00fcdischer Rabbiner untersuchen, die das Leiden darauf zur\u00fcckf\u00fchren, dass die Koscher-Regeln nicht eingehalten werden, wie bringen sie ihr Argument mit der Tatsache in Einklang, dass w\u00e4hrend der Zerst\u00f6rung des Ersten und Zweiten Tempels, der Kreuzz\u00fcge und sogar des Holocaust die meisten Juden sehr fromm waren, ihre religi\u00f6sen Praktiken gewissenhaft befolgten, es aber ihr Leiden nicht verhinderte?<\/p><p class=\"p1\">Daher muss man die wahren Gesetze der Sch\u00f6pfung erkennen im Gegensatz zu <b>den L\u00fcgen, die in den menschengemachten Regeln der Religionen zu finden sind. <\/b>Letztendlich, wenn eine Person nicht in ihrem Geist den Unterschied zwischen den universellen und objektiven Gesetzen der Sch\u00f6pfung und den subjektiven Regeln der religi\u00f6sen Doktrin erkennt, ist es unm\u00f6glich, ihr zu helfen, den wahren Pfad zum Licht zu finden. <\/p><p class=\"p1\"><b>F\u00fcr jemanden, dessen Geistesfunke erloschen ist, kann nichts erkl\u00e4rt werden, weil der Intellekt immer ein neues logisches Argument finden wird.<\/b><b><\/b><\/p><ol class=\"ol1\"><li class=\"li1\">Eine weitere Falle ist der<b> Humanismus<\/b>, der die wahre angeborene Tendenz des Geistes zum Idealismus kapert und sie in eine radikale Tendenz f\u00fcr falsche, rein irdische Ideale verdreht, wie zum Beispiel: Feminismus, Demonstrationen f\u00fcr Immigrantenrechte, Freiheit zur Geschlechtsdefinition, Demokratie, und tats\u00e4chlich der Kampf zur Bewahrung aller Verzerrungen der alten Welt unter dem Banner, &#8222;gute Menschen&#8220; zu sein.<\/li><\/ol><p class=\"p1\">Daher muss unser Geist sehr wachsam sein, um zwischen L\u00fcgen und Wahrheit, zwischen Dunkel und Licht zu unterscheiden.<\/p><p class=\"p1\">Was sicher ist, ist, dass das Licht und die Wahrheit <b>ein Erwachen vorantreiben, um den Geist zu retten, auch wenn unser Ego das nicht mag. L\u00fcgen und das Dunkel hingegen tun genau das Gegenteil. <\/b><\/p><p class=\"p1\"><b>Aber da die Menschheit tief im Dunkel und in L\u00fcgen steckt, wird es ohne extremes Leiden unm\u00f6glich sein, den Geist zu befreien.<\/b><\/p><p class=\"p1\"><b>Das liegt daran, dass wir, solange unser Leben reibungslos verl\u00e4uft, weiterhin denken werden, dass wir wunderbare Leben voller Licht f\u00fchren, und nicht erkennen werden, dass wir tats\u00e4chlich mit jedem Tag, der vergeht, immer tiefer sinken, dank des Dunkels!<\/b><\/p><p class=\"p1\"><b>Denken Sie daran: Alles, was den Geist nicht zum Licht vorantreibt und voranbringt, ist Dunkel, und dort wird das B\u00f6se erschaffen!<\/b><\/p><p class=\"p1\">Das liegt daran, dass der gesamte Zweck unserer Existenz darin besteht, sich von einem unbewussten Geist zu einem bewussten Geist zu entwickeln und nach Hause ins Paradies zur\u00fcckzukehren\u2014 und nicht darin, die materielle Welt als unseren Lebenszweck zu sehen. <b>Denn das ist nicht der Zweck\u2014es ist nur ein Mittel!<\/b><\/p><p class=\"p1\">Daher lautet die Frage: Wer ist es, der f\u00fcr uns wichtiger zu retten ist\u2014unser Geist oder unser Ego?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1097\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1097\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kapitel Sieben: Ein weiterer Ruf an die Berufenen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1097\" class=\"elementor-element elementor-element-dae316d e-con-full e-flex e-con e-child\" data-id=\"dae316d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9279922 elementor-widget elementor-widget-text-editor\" data-id=\"9279922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In jedem Vortrag, den ich halte, rufe ich zu den M\u00e4nnern und Frauen, deren starke Geister sich nach Freiheit und dem Licht sehnen, denn ihr seid die spirituelle F\u00fchrung der neuen Welt, und nur ihr habt die Macht, <strong>das Dunkel auszutrocknen!<\/strong><\/p><p>Euer Geist hat euer ganzes Leben lang nach der Wahrheit gesucht, also gebt ihm Kraft und bek\u00e4mpft euer Ego, das versucht, Zweifel in euch zu s\u00e4en und euch daran zu hindern, das zu erf\u00fcllen, was ihr vor Tausenden von Jahren versprochen habt\u2014lange bevor ihr in euer jetziges Leben inkarniert seid!<\/p><p>Euer Geist kennt die Wahrheit, auch wenn euer Intellekt sie nicht versteht.<\/p><p>Daher ist es offensichtlich, warum gerade in euch von allen Menschen Konflikt entsteht, wenn ihr die Wahrheit h\u00f6rt.<\/p><p>Das ist der Konflikt zwischen eurem Geist und eurem Ego!<\/p><p>Das ist der wahre und einzige Krieg, der nicht mit der Niederlage des Geistes und dem Sieg des Intellekts und der Emotionen enden darf!<\/p><p>Seid daher nicht stur! Besteht nicht darauf, an allem festzuhalten, was ihr in der esoterischen Kuppel gelernt habt\u2014mit der alle Religionen, Kulte und New-Age-Methoden verbunden sind\u2014und stimmt zu, alles neu zu beginnen, denn das ist der Geist der Zeit, in der wir leben: <\/p><p>Alles <strong>muss<\/strong> neu gemacht werden!<\/p><p>Ihr wisst bereits, wer die Quelle des<strong> \u201eEigenwillens, es besser zu wissen&#8220; und der Sturheit<\/strong> ist, also besteht nicht darauf, in seinen Fu\u00dfstapfen zu wandeln und ihm zu dienen.<\/p><p>Das Ego besteht immer darauf, recht zu haben!<\/p><p>Im Gegensatz dazu<strong> ist der Geist niemals stur.<\/strong> Er ist immer flexibel und bereit, neue Dinge zu lernen und Fehler zuzugeben.<\/p><p><strong>Daher ist derjenige, der heute\u2014in diesen Zeiten, in denen wir alle leben\u2014w\u00e4hlt, diese letzte Gelegenheit zu ergreifen, um den Weg der Entwicklung seines spirituellen Bewusstseins zu beschreiten, wie eine Person, die das letzte Boot besteigt, das das Dock verl\u00e4sst.<\/strong><\/p><p><strong>Doch selbst wenn die Reise lang ist und das Schiff langsam sein Ziel erreicht, kann er dennoch ein Gef\u00fchl der Sicherheit und Freude genie\u00dfen\u2014wissend, dass er bereits die Segel in Richtung seiner Erl\u00f6sung gesetzt hat.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28b6656 e-con-full e-flex e-con e-parent\" data-id=\"28b6656\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-59091a4 e-con-full FORM e-grid e-con e-child\" data-id=\"59091a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4ab6b4f e-con-full e-flex e-con e-child\" data-id=\"4ab6b4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e460c1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1e460c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Um Erinnerungen f\u00fcr bevorstehende Veranstaltungen zu erhalten oder Hagit eine Frage zu diesem Inhalt zu stellen, geben Sie bitte Ihre Daten an:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e585c46 e-con-full e-flex e-con e-child\" data-id=\"e585c46\" data-element_type=\"container\" data-e-type=\"container\" style=\"\">\n\t\t<div class=\"elementor-element elementor-element-0c97180 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"0c97180\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f827de5 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f827de5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c456987 e-con-full e-flex e-con e-child\" data-id=\"c456987\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2021af5 elementor-widget elementor-widget-heading\" data-id=\"2021af5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">Treten Sie unserer WhatsApp Gruppe bei<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2dd166 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f2dd166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>f\u00fcr Updates zu bevorstehenden Treffen, Vortr\u00e4gen und neuen Inhalten!<br><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\" rel=\"noopener\"><strong>Klicken Sie hier<\/strong><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6084c8 e-con-full e-flex e-con e-child\" data-id=\"e6084c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-602955a elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"602955a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;N\\u00e4chste&quot;,&quot;step_previous_label&quot;:&quot;Vorherige&quot;,&quot;button_width&quot;:&quot;60&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"PvE\" name=\"Luzifer&#039;s Agenda Fragen\" aria-label=\"Luzifer&#039;s Agenda Fragen\" novalidate=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"13679\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"602955a\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-first_name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-first_name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVorname\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[first_name]\" id=\"form-field-first_name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-last_name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-last_name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNachname\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[last_name]\" id=\"form-field-last_name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-country elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-country\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tLand\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[country]\" id=\"form-field-country\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-question elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-question\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tHaben Sie eine Frage an Hagit?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[question]\" id=\"form-field-question\" rows=\"4\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_da71f3aewfeawe elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_da71f3aewfeawe]\" id=\"form-field-field_da71f3aewfeawe\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_26606d3 elementor-col-100\">\n\t\t\t\t\tWir k\u00f6nnen die E-Mail-Adresse, die Sie im Rahmen Ihrer Registrierung\/Ihres Kaufs angeben, dazu verwenden, Ihnen von Zeit zu Zeit Marketing-Inhalte und Angebote bez\u00fcglich Produkten und Dienstleistungen zu senden, die denen \u00e4hnlich sind, die Sie gekauft oder f\u00fcr die Sie sich registriert haben, in \u00dcbereinstimmung mit Abschnitt 30A(c) des israelischen Kommunikationsgesetzes (Telekommunikation und Rundfunk), 5742-1982. Sie k\u00f6nnen uns jederzeit mitteilen, dass Sie solche Inhalte nicht erhalten m\u00f6chten, indem Sie auf die E-Mail mit \"Entfernen\/Abbestellen\" antworten oder den \"Abbestellen\"-Link verwenden, der in jeder Werbenachricht erscheint. Sofern und bis wir eine solche Ablehnungsmitteilung erhalten, gelten Sie als einverstanden mit dem Erhalt solcher Inhalte.  \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-mc_tag elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[mc_tag]\" id=\"form-field-mc_tag\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" value=\"Lucifer_SITE_FORM_ORG\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-60 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d77f80 e-con-full elementor-hidden-desktop e-flex e-con e-child\" data-id=\"7d77f80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-591263e elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"591263e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3531be e-con-full e-flex e-con e-child\" data-id=\"d3531be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1185b13 elementor-widget elementor-widget-heading\" data-id=\"1185b13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\">Treten Sie unserer WhatsApp Gruppe bei<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4a40e2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d4a40e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>f\u00fcr Updates zu bevorstehenden Treffen, Vortr\u00e4gen und neuen Inhalten!<\/p><p><a href=\"https:\/\/bit.ly\/alma-school-whatsapp\" target=\"_blank\" rel=\"noopener\"><strong>Klicken Sie hier<\/strong><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-330a761 e-flex e-con-boxed e-con e-parent\" data-id=\"330a761\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-652758d elementor-widget elementor-widget-text-editor\" data-id=\"652758d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-renderer-start-pos=\"1\">Setzen Sie Ihre Reise fort:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1df970 e-grid e-con-full e-con e-child\" data-id=\"d1df970\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-89a50e7 e-con-full e-flex e-con e-child\" data-id=\"89a50e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d387c71 elementor-widget elementor-widget-text-editor\" data-id=\"d387c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Propheten gegen Imperien<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfc2270 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dfc2270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/almaschool.org\/prophets-vs-empires\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Klicken Sie hier &gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c03a119 e-con-full e-flex e-con e-child\" data-id=\"c03a119\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2503d87 elementor-widget elementor-widget-text-editor\" data-id=\"2503d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Naturkatastrophen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-910ec8e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"910ec8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/almaschool.org\/natural-disasters-post\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Klicken Sie hier &gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea9cc6a e-flex e-con-boxed e-con e-parent\" data-id=\"ea9cc6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fba41b8 elementor-widget elementor-widget-text-editor\" data-id=\"fba41b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">\u00dcber die Sprecherin:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-686d62f elementor-position-left elementor-widget__width-initial elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"686d62f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6.png\" class=\"attachment-full size-full wp-image-18128\" alt=\"\" srcset=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6.png 1080w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-300x300.png 300w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-1024x1024.png 1024w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-150x150.png 150w, https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/6-768x768.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hagit Rabbi<\/h3><p class=\"elementor-image-box-description\">\nHagit ist Lehrerin und Gr\u00fcnderin der Alma Schule f\u00fcr wahres Menschentum. Als Absolventin des Bereichs f\u00fcr Talmud und Philosophie der Hebr\u00e4ischen Universit\u00e4t Jerusalem hat sie \u00fcber 20 Jahre damit verbracht, die tiefgr\u00fcndigen Fragen der menschlichen Existenz zu erforschen und dabei Inspiration aus h\u00f6heren Wissensquellen jenseits des intellektuellen Studiums zu sch\u00f6pfen. \n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-433a6b3 elementor-widget elementor-widget-image\" data-id=\"433a6b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"106\" src=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/10\/ASFH-\u05e6\u05d1\u05e2\u05d5\u05e0\u05d9-300x106-1.png\" class=\"attachment-large size-large wp-image-18134\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06b2e20 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"06b2e20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\">Die Schule bietet Vortr\u00e4ge, Artikel, Podcasts und digitale Kurse an, die darauf ausgerichtet sind, geistiges Bewusstsein zu entwickeln, gegr\u00fcndet auf den universellen Gesetzen der Sch\u00f6pfung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Anh\u00f6ren auf Spotify Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger &#8230; <a title=\"Luzifers Agenda\" class=\"read-more\" href=\"https:\/\/almaschool.org\/de\/luzifers-agenda\/\" aria-label=\"Mehr Informationen \u00fcber Luzifers Agenda\">Weiterlesen<\/a><\/p>\n","protected":false},"author":563,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-13679","page","type-page","status-publish"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/almaschool.org\/de\/luzifers-agenda\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Alma School for Humanity - Calling for the Human Spirit\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Luzifers Agenda # - Alma School for Humanity\" \/>\n\t\t<meta property=\"og:description\" content=\"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/almaschool.org\/de\/luzifers-agenda\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-07-21T19:18:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-03T10:22:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Luzifers Agenda # - Alma School for Humanity\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/almaschool.org\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/#listItem\",\"name\":\"Luzifers Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/#listItem\",\"position\":2,\"name\":\"Luzifers Agenda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/#organization\",\"name\":\"Alma School for Humanity\",\"description\":\"Calling for the Human Spirit\",\"url\":\"https:\\\/\\\/almaschool.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/almaschool.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/ASFH-\\u05e6\\u05d1\\u05e2\\u05d5\\u05e0\\u05d9.png\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/#organizationLogo\",\"width\":5345,\"height\":1891},\"image\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/#webpage\",\"url\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/\",\"name\":\"Luzifers Agenda # - Alma School for Humanity\",\"description\":\"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \\u00fcber die Menschheit enth\\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\\u00fcck ins Paradies ist Da die globale Realit\\u00e4t zunehmend schwieriger wird\\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/luzifers-agenda\\\/#breadcrumblist\"},\"datePublished\":\"2025-07-21T22:18:55+03:00\",\"dateModified\":\"2026-06-03T13:22:11+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/almaschool.org\\\/de\\\/\",\"name\":\"Alma School for Humanity\",\"description\":\"Calling for the Human Spirit\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/almaschool.org\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Luzifers Agenda # - Alma School for Humanity","description":"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen","canonical_url":"https:\/\/almaschool.org\/de\/luzifers-agenda\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/almaschool.org\/de\/luzifers-agenda\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/almaschool.org\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/almaschool.org\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/de\/luzifers-agenda\/#listItem","name":"Luzifers Agenda"}},{"@type":"ListItem","@id":"https:\/\/almaschool.org\/de\/luzifers-agenda\/#listItem","position":2,"name":"Luzifers Agenda","previousItem":{"@type":"ListItem","@id":"https:\/\/almaschool.org\/de\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/almaschool.org\/de\/#organization","name":"Alma School for Humanity","description":"Calling for the Human Spirit","url":"https:\/\/almaschool.org\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/almaschool.org\/wp-content\/uploads\/2023\/04\/ASFH-\u05e6\u05d1\u05e2\u05d5\u05e0\u05d9.png","@id":"https:\/\/almaschool.org\/de\/luzifers-agenda\/#organizationLogo","width":5345,"height":1891},"image":{"@id":"https:\/\/almaschool.org\/de\/luzifers-agenda\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/almaschool.org\/de\/luzifers-agenda\/#webpage","url":"https:\/\/almaschool.org\/de\/luzifers-agenda\/","name":"Luzifers Agenda # - Alma School for Humanity","description":"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/almaschool.org\/de\/#website"},"breadcrumb":{"@id":"https:\/\/almaschool.org\/de\/luzifers-agenda\/#breadcrumblist"},"datePublished":"2025-07-21T22:18:55+03:00","dateModified":"2026-06-03T13:22:11+03:00"},{"@type":"WebSite","@id":"https:\/\/almaschool.org\/de\/#website","url":"https:\/\/almaschool.org\/de\/","name":"Alma School for Humanity","description":"Calling for the Human Spirit","inLanguage":"de-DE","publisher":{"@id":"https:\/\/almaschool.org\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Alma School for Humanity - Calling for the Human Spirit","og:type":"article","og:title":"Luzifers Agenda # - Alma School for Humanity","og:description":"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen","og:url":"https:\/\/almaschool.org\/de\/luzifers-agenda\/","og:image":"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg","og:image:secure_url":"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg","og:image:width":1080,"og:image:height":1080,"article:published_time":"2025-07-21T19:18:55+00:00","article:modified_time":"2026-06-03T10:22:11+00:00","twitter:card":"summary_large_image","twitter:title":"Luzifers Agenda # - Alma School for Humanity","twitter:description":"Luzifers AgendaVon Hagit Rabbi Die Methoden der Versuchungund Kontrolle \u00fcber die Menschheit enth\u00fcllen Den Vortrag ansehen: *Klicken Sie auf das Zahnrad-Symbol, um Untertitel in Ihrer bevorzugten Sprache zu aktivieren. Den Artikel anh\u00f6ren: Einleitung: Warum die Entwicklung unseres geistigen Bewusstseins unser einziger Weg zur\u00fcck ins Paradies ist Da die globale Realit\u00e4t zunehmend schwieriger wird\u2014Kriege, Naturkatastrophen, Wirtschaftskrisen","twitter:image":"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg"},"aioseo_meta_data":{"post_id":"13679","title":"#post_title # #separator_sa #site_title","description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"custom_image","og_image_url":"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg","og_image_width":"0","og_image_height":"0","og_image_custom_url":"https:\/\/almaschool.org\/wp-content\/uploads\/2025\/08\/1080X1080-\u05dc\u05d5\u05e6\u05d9\u05e4\u05e8-\u05dc\u05dc\u05d0-\u05d8\u05e7\u05e1\u05d8.jpg","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-08-30 15:10:42","updated":"2026-06-03 10:23:06","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/almaschool.org\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLuzifers Agenda\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/almaschool.org\/de\/"},{"label":"Luzifers Agenda","link":"https:\/\/almaschool.org\/de\/luzifers-agenda\/"}],"_links":{"self":[{"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/pages\/13679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/users\/563"}],"replies":[{"embeddable":true,"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/comments?post=13679"}],"version-history":[{"count":17,"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/pages\/13679\/revisions"}],"predecessor-version":[{"id":36201,"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/pages\/13679\/revisions\/36201"}],"wp:attachment":[{"href":"https:\/\/almaschool.org\/de\/wp-json\/wp\/v2\/media?parent=13679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}